{"id":1034,"date":"2014-01-13T10:16:03","date_gmt":"2014-01-13T10:16:03","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/13\/frank-martin-werke-mit-gitarre\/"},"modified":"2014-01-13T10:16:03","modified_gmt":"2014-01-13T10:16:03","slug":"frank-martin-werke-mit-gitarre","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/13\/frank-martin-werke-mit-gitarre\/","title":{"rendered":"Frank Martin: Werke mit Gitarre"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2009\/090625martin.jpg\" border=\"0\" align=\"left\" \/>26.06.2009 &#8212; Sex, Drugs and Rock &#8217;n&#8216; Roll sind gemeinhin die Welten, die mit der elektrischen Gitarre verbunden werden, besonders in den Jahren nach 1969, nach dem epochalen Woodstock-Festival. Zwischen 1969 und 1971 kombinierte der Welschschweizer Komponist Frank Martin aber ausgerechnet die unter Strom stehenden Zupfinstrumente mit traditionellen M\u00e4nnerstimmen \u2013 einem Tenor, einem Bass und einem Bariton \u2013 um daraus h\u00f6chst poetische Kleinode zu verfertigen. Die zugrundeliegenden Texte allerdings entsprechen durchaus dem zweifelhaften Ruf der E-Gitarren und -B\u00e4sse, handelt es sich doch um drei Gedichte des mittelalterlichen Poeten Fan\u00e7ois Villon, der in seiner Zeit als Outlaw und Landstreicher selber so etwas wie ein Rockerleben gef\u00fchrt hat. Die Texte handeln von Todessehnsucht, die drei M\u00e4nnerstimmen verk\u00f6rpern drei Gehenkte, die in einem der Lieder, der \u00abBallade des Pendus\u00bb sich zerknirscht aus dem Jenseits melden.<\/p>\n<p> So ungew\u00f6hnlich die Besetzung, so gut ist die Musik, die Martin daf\u00fcr geschrieben hat, und es ist nicht das einzige Mal, dass er die Gitarre f\u00fcr originelle musikalische Preziosen genutzt hat. Weitere sind ein klanglich-rhythmisch \u00fcberraschendes Wiegenlied (\u00abQuant n&#8217;ont assez fait dodo\u00bb) f\u00fcr Gitarre, Klavier zu vier H\u00e4nden und Tenor aus dem Jahr 1947 sowie ein Zyklus von drei Minneliedern f\u00fcr Sopran, Fl\u00f6te und Gitarre (1960), der ein filigranes Wechselspiel der Melodien und Klangfarben von teils ber\u00fcckender Sch\u00f6nheit entfaltet. <\/p>\n<p> Musiques Suisse h\u00e4lt f\u00fcr diese Repertoire-Entdeckungen beste F\u00fcrsprache \u2013 nicht nur die Interpreten sind erstklassig, auch aufnahmetechnisch \u00fcberzeugt die Silberscheibe, die 2006 und 2007 in der Kirche Waldkirch in Waldshut und in der Kantonsschule Baden eingespielt worden ist. So verf\u00fcgt sie unter anderem gerade \u00fcber den richtigen Teil an Raumklang um die intimen Kl\u00e4nge mit sensiblem Leben und W\u00e4rme zu f\u00fcllen, ohne die Transparenz des von franz\u00f6sischer Eleganz und Klarheit bestimmten Tonsatzes zu tr\u00fcben. <\/p>\n<p> Gelungen sind ebenso die rein instrumentalen Beitr\u00e4ge, eine Wiedergabe der \u00abQuatre pi\u00e8ces br\u00e8ves\u00bb f\u00fcr Gitarre solo, die auch editorisch interessant ist. Sie macht Oktavierungen r\u00fcckg\u00e4ngig, die sich in der von Karl Scheit f\u00fcr die Universal Edition erstellten Fassung des Zyklus aus Gr\u00fcnden der einfacheren Spielbarkeit finden, und erg\u00e4nzt Ostinato-Figuren im letzten Satz (einer Gigue), die in der Scheit-Ausgabe ebenfalls bloss ausged\u00fcnnt erscheinen.<\/p>\n<p> Auch die Transkription von zwei S\u00e4tzen aus den \u00abEtudes\u00bb f\u00fcr Streichorchester aus den f\u00fcnfziger Jahren f\u00fcr zwei Gitarren vermag zu \u00fcberzeugen. Sowohl das Solowerk als auch die Orchesters\u00e4tze sind vom in Waldshut wohnhaften Gitarristen Harald Stampa bearbeitet worden. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Frank Martin: Werke mit Gitarre. Mitwirkende: Tino Br\u00fctsch (Tenor), Samuel Z\u00fcnd (Bariton), Ren\u00e9 Koch (Bass), Harald Stampa (Gitarre), Benjamin Scheck (Gitarre), Richard Pechota (E-Bass), Barbara Vigfusson (Sopran), Miriam Terragni (Querfl\u00f6te), Antje Maria Traub (Klavier), Gregor Loepfe (Klavier). Musiques Suisses CD MGB 6264 Bezugsnachweis: <a href=\"http:\/\/www.musiques-suisses.ch\" target=\"blank\" rel=\"noopener noreferrer\">www.musiques-suisses.ch<\/a> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>26.06.2009 &#8212; Sex, Drugs and Rock &#8217;n&#8216; Roll sind gemeinhin die Welten, die mit der elektrischen Gitarre verbunden werden, besonders&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1034","post","type-post","status-publish","format-standard","hentry","category-tontraeger-besprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1034"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1034\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}