{"id":1047,"date":"2014-01-13T10:22:27","date_gmt":"2014-01-13T10:22:27","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/13\/rautavaara-12-concertos\/"},"modified":"2014-01-13T10:22:27","modified_gmt":"2014-01-13T10:22:27","slug":"rautavaara-12-concertos","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/13\/rautavaara-12-concertos\/","title":{"rendered":"Rautavaara: 12 Concertos"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2010\/rauta6110.jpg\" border=\"0\" align=\"left\" \/>18.01.2010 &#8212; Einer der profiliertesten finnischen Komponisten des 20. Jahrhunderts spielt ausserhalb seines Heimatlands eine marginale Rolle: Einojuhani Rautavaara, geboren 1928 in Helsinki. Der Sohn eines Operns\u00e4ngers wurde fr\u00fch Waise, lernte Klavier, Musikwissenschaft und Komposition. Sibelius unterst\u00fctzte ihn 1955 mit einem Stipendium, das ihm selbst zugesprochen worden war. Dank dieser F\u00f6rderung konnte Rautavaara sich an der Juilliard School in New York bei Vincent Persichetti und am Tanglewood Music Center bei Roger Sessions und Aaron Copland weiterbilden. 1957 studierte er bei Wladimir Vogel die Zw\u00f6lftontechnik. <\/p>\n<p> Nach T\u00e4tigkeiten als Lehrer an der Sibelius-Akademie, als Bibliothekar und Archivist beim Philharmonischen Orchester Helsinki und als Rektor am K\u00e4pyl\u00e4 Music Institute in Helsinki wirkte er von 1976 bis 1990 als Professor f\u00fcr Komposition an der Sibelius-Akademie. <\/p>\n<p> Rautavaaras reiches \u0152uvre, das s\u00e4mtliche Gattungen umfasst, darunter Opern (zusammen mit seinem j\u00fcngeren Landsmann Aulis Sallinen gilt er als Grossmeister des Musiktheaters), acht Sinfonien und ein Dutzend Instrumentalkonzerte, reflektiert einen grossen Teil des kompositorischen Spektrums seines Jahrhunderts und die Einfl\u00fcsse, die er im Lauf seiner Ausbildung assimilierte. <\/p>\n<p> In seinen zw\u00f6lf zwischen 1968 und 2001 geschriebenen Instrumentalkonzerten, die das finnische Label Ondine auf vier CDs in einer Box gesammelt vorlegt (die Einspielungen stammen aus den Jahren zwischen 1989 und 2005), widerspiegelt sich zudem die k\u00fcnstlerische Entwicklung Rautavaaras in verschiedenen Schaffensphasen: Sein Kennzeichen ist die Pluralit\u00e4t des Stils, das Cham\u00e4leonhafte. <\/p>\n<p> Alle Konzerte \u2013 drei f\u00fcr Klavier, zwei f\u00fcr Harfe, je eines f\u00fcr Violine, Cello, Kontrabass, Fl\u00f6te, Klarinette und Orgel, zudem eines f\u00fcr V\u00f6gel und Orchester (mit Ges\u00e4ngen arktischer V\u00f6gel ab Tonband) \u2013 folgen dem gleichen Schema: Einzelner gegen Gesellschaft. Ein Konzert, so hat Rautavaara ge\u00e4ussert, sei f\u00fcr ihn immer ein Drama, ein Konflikt zwischen Individuum und Kollektiv. Und alle sind sie expressiv, diese Concerti, effektvoll und virtuos, souver\u00e4n und wirkungssicher instrumentiert, und sie stellen die klanglichen Qualit\u00e4ten und technischen M\u00f6glichkeiten des jeweiligen Instruments in helles Licht. <\/p>\n<p> Die stilistische Spannweite reicht von Neoklassizismus \u00fcber Sp\u00e4tromantik und Neoromantik zur Postmoderne mit seriellen Elementen. Seit 1960 verzichtet er auf die Zw\u00f6lftontechnik, bedient sich eines tonal verankerten, aber sehr autonom gehandhabten Stils. Rautavaara sch\u00f6pft auch aus mystischen \u00dcberzeugungen, etwa im immer wieder aufgegriffenen Thema des Engels (das Kontrabass-Konzert tr\u00e4gt den Titel \u00abAngel of Dusk\u00bb) oder im Vogel-Konzert \u00abCantus Arcticus\u00bb.<\/p>\n<p> Mal ist der Klang opulent und eruptiv, mal schwebend, fragil und ausged\u00fcnnt, nicht immer frei von geschm\u00e4cklerischer S\u00fcsse, die Textur mal kompakt, mal pointillistisch. Stets nimmt die Musik ein durch markante Thematik, grosse Geste, kr\u00e4ftige Kontraste auf engem Raum, Farbenreichtum, durch kantige rhythmische Pr\u00e4gnanz und Ausdruckskraft. <\/p>\n<p> Die Sammlung der zw\u00f6lf Konzerte eignet sich dank hervorragender Interpreten und werkdienlicher Umsetzung der Partituren ausgezeichnet f\u00fcr eine vertiefte Besch\u00e4ftigung mit der schillernden Welt Einojuhani Rautavaaras. <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Einojuhani Rautavaara: 12 Concertos. Elmar Oliveira, Violine; Marko Yl\u00f6nen, Cello; Esko Laine, Kontrabass; Reija Bister und Marielle Nordmann, Harfe; Patrick Gallois, Fl\u00f6te; Richard Stoltzman, Klarinette; Kari Jussila, Orgel; Ralf Goth\u00f3ni und Vladimir Ashkenazy, Klavier. \u2013 Helsinki Philharmonic Orchestra unter Leif Segerstam, Max Pommer und Vladimir Ashkenazy. Tapiola Sinfonietta unter Jean-Jacques Kantorow. Ostrobothnian Chamber Orchestra unter Juha Kanga. Rundfunk-Sinfonie-Orchester Leipzig unter Max Pommer. Symphonieorchester des Bayerischen Rundfunks unter Jukka-Pekka Saraste. (Ondine ODE 1156-2Q; 4 CDs; 4h28\u2019) <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>18.01.2010 &#8212; Einer der profiliertesten finnischen Komponisten des 20. Jahrhunderts spielt ausserhalb seines Heimatlands eine marginale Rolle: Einojuhani Rautavaara, geboren&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1047","post","type-post","status-publish","format-standard","hentry","category-tontraeger-besprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1047"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1047\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}