{"id":1052,"date":"2014-01-13T10:55:04","date_gmt":"2014-01-13T10:55:04","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/13\/claire-marie-le-guay-portraetiert-gubaidulina\/"},"modified":"2014-01-13T10:55:04","modified_gmt":"2014-01-13T10:55:04","slug":"claire-marie-le-guay-portraetiert-gubaidulina","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/13\/claire-marie-le-guay-portraetiert-gubaidulina\/","title":{"rendered":"Claire-Marie Le Guay portr\u00e4tiert Gubaidulina"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2010\/100426gubaidulina.jpg\" border=\"0\" align=\"left\" \/>28.04.2010 &#8212; Die russische Komponistin Sofia Gubaidulina hat 1969 eine Reihe von kurzen St\u00fccken f\u00fcr Kinder geschrieben, die auf Spielsachen Bezug nehmen und deren Charakter oder Klang auf teils launische Weise abbilden. Erstmals aufgef\u00fchrt worden sind die Kleinode allerdings erst ein Vierteljahrhundert sp\u00e4ter, vom Schweizer Pianisten Andreas Haefliger, der das komplette Klavierwerk der tatarischen Komponistin eingespielt hat. In dem CD-Portr\u00e4t, das die franz\u00f6sische Pianistin Claire-Marie Le Guay Gubaidulina widmet, nimmt der p\u00e4dagogische Zyklus eine zentrale Stellung ein.<\/p>\n<p> Le Guay, die Gelegenheit hatte, die Werke im Dialog mit der Komponistin zu erarbeiten, bezeichnet sie in einem Interview mit einer franz\u00f6sischen Fachzeitschrift als \u00abkleine Aquarelle\u00bb. Sie illustrieren eine hierzulande wenig bekannte Seite der Tonsch\u00f6pferin, die vor allem dank ihrer schwerbl\u00fctigen grossen Orchester- und Chorwerke bekannt ist. <\/p>\n<p> Im gleichen Interview betont Le Guay den narrativen Charakter der Pi\u00e8cen, die vor allem auch einen subtilen klanglichen Kosmos entfalten. Tats\u00e4chlich wirken sie teils wie kleine Improvisationen, ab und an meint man aber auch, die Klangwelten von Gubaidulinas Mentor Schostakowitsch durchschimmern zu h\u00f6ren. <\/p>\n<p> Das zweite gr\u00f6ssere Werk auf der CD ist das Kammerkonzert Introitus f\u00fcr Klavier, Streicher und einige wenige Holzbl\u00e4ser. Es baut in weitgehend statischer Art Atmosph\u00e4ren auf, die schon fast in Minimal-Music-Manier Motive umspielen oder gar bloss einzelne T\u00f6ne aufbrechen. <\/p>\n<p> Aufgrund ihrer Erziehung, schreibt ihr Verlag (Sikorski Deutschland), sei Sofia Gubaidulina dem russischen Kulturkreis zuzurechnen, gleichwohl seien in ihrer tatarischen Abstammung begr\u00fcndete asiatische Einfl\u00fcsse in ihrem Schaffen un\u00fcberh\u00f6rbar. <\/p>\n<p> Auf das Kammerkonzert trifft die Charakterisierung zweifelssohne zu, und so ist auch die Vermutung nicht abwegig, dass an dem teils erdenschweren, teils impulsiven Werk Gefallen finden wird, wer sich auch von den Kompositionen von Gubaidulinas jungem t\u00fcrkischen Kollegen Fazil Say faszinieren l\u00e4sst, auch wenn diese m\u00f6glicherweise etwas weniger hermetisch daherkommen als die Musik der Tatarin. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Sofia Gubaidulina Portrait. Claire-Marie Le Guay (Klavier), Orchestre de Chambre de Lausanne, Jean-Jacques Kantorow (Leitung). Invention f\u00fcr Klavier (1974), Chaconne f\u00fcr Klavier (1963), Musical Toys (1969), Introitus (1978). Accord\/Universal 4080 3153<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>28.04.2010 &#8212; Die russische Komponistin Sofia Gubaidulina hat 1969 eine Reihe von kurzen St\u00fccken f\u00fcr Kinder geschrieben, die auf Spielsachen&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1052","post","type-post","status-publish","format-standard","hentry","category-tontraeger-besprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1052"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1052\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}