{"id":1153,"date":"2014-01-20T09:33:46","date_gmt":"2014-01-20T09:33:46","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/20\/tod-des-italienischen-dirigenten-claudio-abbado\/"},"modified":"2014-01-20T09:33:46","modified_gmt":"2014-01-20T09:33:46","slug":"tod-des-italienischen-dirigenten-claudio-abbado","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/20\/tod-des-italienischen-dirigenten-claudio-abbado\/","title":{"rendered":"Tod des italienischen Dirigenten Claudio Abbado"},"content":{"rendered":"<p>20.01.2014 &#8212; Der italienische\u00a0 Dirigent Claudio Abbado ist laut italienischen Pressemeldungen heute in Bologna im Alter von 80 Jahren verstorben.<\/p>\n<p>\u00a0<\/p>\n<p><strong>20.01.2014 &#8212; Der italienische\u00a0 Dirigent Claudio Abbado ist laut italienischen Pressemeldungen heute in Bologna im Alter von 80 Jahren verstorben.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Der mit dem Lucerne Festival eng verbuindene Dirigent war seit l\u00e4ngerem krank und musste seine letzten Engagements absagen. (cf)\u00a0 <strong><br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>20.01.2014 &#8212; Der italienische\u00a0 Dirigent Claudio Abbado ist laut italienischen Pressemeldungen heute in Bologna im Alter von 80 Jahren verstorben.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1153","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1153"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1153\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}