{"id":1277,"date":"2014-03-10T06:56:34","date_gmt":"2014-03-10T06:56:34","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/03\/10\/nicht-alle-menschen-beruehrt-musik\/"},"modified":"2014-03-10T06:56:34","modified_gmt":"2014-03-10T06:56:34","slug":"nicht-alle-menschen-beruehrt-musik","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/03\/10\/nicht-alle-menschen-beruehrt-musik\/","title":{"rendered":"Nicht alle Menschen ber\u00fchrt Musik"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">10.03.2014 &#8212; Musik-Anhedonie nennen Forscher von der Universit\u00e4t Barcelona die Unf\u00e4higkeit, sich von Musik emotional ber\u00fchren zu lassen. Mit einem Onlinefragebogen m\u00f6chten sie mehr \u00fcber das Ph\u00e4nomen erfahren.<\/span><\/p>\n<p><strong><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">10.03.2014 &#8212; Musik-Anhedonie nennen spanische Forscher von der Universit\u00e4t Barcelona die Unf\u00e4higkeit, sich von Musik emotional ber\u00fchren zu lassen. Mit einem Onlinefragebogen m\u00f6chten sie mehr \u00fcber das Ph\u00e4nomen erfahren.<\/span><\/strong><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Ein Team um die Neuromusikologen Ernest Mas-Herrero und\u00a0Robert\u00a0J. Zatorre ist der Frage empirisch\u00a0 nachgegangen, ob tats\u00e4chlich alle Menschen sich von Musik emotional ber\u00fchren lassen. Dabei sind sie auf eine Gruppe von Menschen gestossen, die die klingende Kunst kalt l\u00e4sst, ohne dass sie sonst psychische Auff\u00e4lligkeiten zeigen w\u00fcrden und auch Musik kognitiv ansonsten v\u00f6llig normal verarbeiten.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Auch das\u00a0 Belohnungszentrurm von\u00a0 <span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Musik-Anhedonisten funktioniert normal, reagieren diese Menschen doch auf andere Belohnungen wie Geld wie jeder andere auch. Mit einem Onlinefragebogen, der von jedermann ausgef\u00fcllt werden kann, m\u00f6chten die Forscher die Erkentnisse auf eine breitere empirische Basis stellen. <em>(cf)<\/em>\u00a0 <br \/><\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>Originalartikel:<\/strong><br \/><\/span><\/span><\/p>\n<p>Ernest Mas-Herrero, Robert J. Zatorre et al.: <a href=\"http:\/\/www.cell.com\/current-biology\/retrieve\/pii\/S096098221400133X\" target=\"_blank\" rel=\"noopener noreferrer\">Dissociation between Musical and Monetary Reward Responses in Specific Musical Anhedonia<\/a>, Current Biology, 06 March 2014, 10.1016\/j.cub.2014.01.068<\/p>\n<p>Onlinefragebogen (Englisch): <a href=\"http:\/\/www.brainvitge.org\/bmrq.php\" target=\"_blank\" rel=\"noopener noreferrer\">www.brainvitge.org\/bmrq.php<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">10.03.2014 &#8212; Musik-Anhedonie nennen Forscher von der Universit\u00e4t Barcelona die Unf\u00e4higkeit, sich von Musik emotional ber\u00fchren zu lassen. Mit einem Onlinefragebogen m\u00f6chten sie mehr \u00fcber das Ph\u00e4nomen erfahren.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1277","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1277"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1277\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}