{"id":1334,"date":"2014-04-04T05:36:17","date_gmt":"2014-04-04T05:36:17","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/04\/04\/kaufmann-kommt-nicht-zur-platzeinweihung\/"},"modified":"2014-04-04T05:36:17","modified_gmt":"2014-04-04T05:36:17","slug":"kaufmann-kommt-nicht-zur-platzeinweihung","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/04\/04\/kaufmann-kommt-nicht-zur-platzeinweihung\/","title":{"rendered":"Kaufmann kommt nicht zur Platzeinweihung"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">04.04.2014 &#8212; W\u00e4re sch\u00f6n gewesen, gibt&#8217;s aber nicht: Jonas Kaufmann hat einen gemeinsamen Auftritt mit Bryn Terfel vor dem Z\u00fcrcher Opernhaus anl\u00e4sslich der Einweihung des neu gestalteten Sechsel\u00e4utenplatzes abgesagt.<\/span><\/p>\n<p><strong><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">04.04.2014 &#8212; W\u00e4re sch\u00f6n gewesen, gibt&#8217;s aber nicht: Jonas Kaufmann hat einen gemeinsamen Auftritt mit Bryn Terfel vor dem Z\u00fcrcher Opernhaus anl\u00e4sslich der Einweihung des neu gestalteten Sechsel\u00e4utenplatzes abgesagt.<\/span><\/strong><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Kaufmann hat eine urspr\u00fcngliche Zusage zum Er\u00f6ffnungskonzert des Sechsel\u00e4utenplatzes am 26. April 2014 aus pers\u00f6nlichen Gr\u00fcnden wieder zur\u00fcckgezogen. An der Seite von Bryn Terfel pr\u00e4sentieren nun Julie Fuchs, Anna Goryachova und Benjamin Bernheim aus dem Ensemble des Opernhauses die sch\u00f6nsten Arien und Duette unter anderem von Wolfgang Amadeus Mozart, Giuseppe Verdi und Georges Bizet. Es spielt die Philharmonia Z\u00fcrich unter der Leitung von Alain Altinoglu. <em>(cf)<\/em><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">04.04.2014 &#8212; W\u00e4re sch\u00f6n gewesen, gibt&#8217;s aber nicht: Jonas Kaufmann hat einen gemeinsamen Auftritt mit Bryn Terfel vor dem Z\u00fcrcher Opernhaus anl\u00e4sslich der Einweihung des neu gestalteten Sechsel\u00e4utenplatzes abgesagt.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1334","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1334"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1334\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}