{"id":1417,"date":"2014-05-13T06:08:09","date_gmt":"2014-05-13T06:08:09","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/05\/13\/takacs-quartet-erhaelt-wigmore-hall-medal\/"},"modified":"2014-05-13T06:08:09","modified_gmt":"2014-05-13T06:08:09","slug":"takacs-quartet-erhaelt-wigmore-hall-medal","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/05\/13\/takacs-quartet-erhaelt-wigmore-hall-medal\/","title":{"rendered":"Tak\u00e1cs Quartet erh\u00e4lt Wigmore Hall Medal"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">13.05.2014 &#8212; Die Wigmore Hall in London ist m\u00f6glicherweise der bedeutendste Saal f\u00fcr Kammermusik weltweit. Er vergibt seit 2007 mit der Wigmore Hall Medal eine Auszeichnung f\u00fcr K\u00fcnstler, die mit ihm eng verbunden sind. Heuer wird so das Tak\u00e1cs Quartet geehrt.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>13.05.2014 &#8212; Die Wigmore Hall in London ist m\u00f6glicherweise der bedeutendste Saal f\u00fcr Kammermusik weltweit. Er vergibt seit 2007 mit der Wigmore Hall Medal eine Auszeichnung f\u00fcr K\u00fcnstler, die mit ihm eng verbunden sind. Heuer wird so das Tak\u00e1cs Quartet geehrt.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Das Tak\u00e1cs Quartet deb\u00fctierte 1979 in dem geschichtstr\u00e4chtigen Saal in der britischen Metropole, als Gewinner der damaligen Portsmouth International String Quartet Competition. 2012 wurde es zum ersten Associate Artist der Wigmore Hall.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Fr\u00fchere Tr\u00e4ger der Wigmore Hall Medal sind Andr\u00e1s Schiff, Thomas Quasthoff, Menahem Pressler und Dame Felicity Lott. Das Tak\u00e1cs Quartet ist das erste Streichquartett, das mit der Medaille geehrt wird. <em>(cf)<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">13.05.2014 &#8212; Die Wigmore Hall in London ist m\u00f6glicherweise der bedeutendste Saal f\u00fcr Kammermusik weltweit. Er vergibt seit 2007 mit der Wigmore Hall Medal eine Auszeichnung f\u00fcr K\u00fcnstler, die mit ihm eng verbunden sind. Heuer wird so das Tak\u00e1cs Quartet geehrt.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1417","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1417"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1417\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}