{"id":1486,"date":"2014-06-11T06:38:59","date_gmt":"2014-06-11T06:38:59","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/06\/11\/nuernberger-meistersinger-kirche-ausgebrannt\/"},"modified":"2014-06-11T06:38:59","modified_gmt":"2014-06-11T06:38:59","slug":"nuernberger-meistersinger-kirche-ausgebrannt","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/06\/11\/nuernberger-meistersinger-kirche-ausgebrannt\/","title":{"rendered":"N\u00fcrnberger Meistersinger-Kirche ausgebrannt"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">11.06.2014 &#8212; Die N\u00fcrnberger St.Martha-Kirche ist ausgebrannt. Der Dachstuhl ist v\u00f6llig zerst\u00f6rt, die Orgel ist geschmolzen, die Fassade einsturzgef\u00e4hrdet. Die Kirche war im 17. Jahrhundert Treffpunkt der N\u00fcrnberger Meistersinger, denen Wagner mit seiner gleichnamigen Oper ein Denkmal gesetzt hat.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong> 11.06.2014 &#8212; Die N\u00fcrnberger St.Martha-Kirche ist ausgebrannt. Der Dachstuhl ist v\u00f6llig zerst\u00f6rt, die Orgel ist geschmolzen, die Fassade einsturzgef\u00e4hrdet. Die Kirche war historischer Treffpunkt der N\u00fcrnberger Meistersinger, denen Wagner mit seiner gleichnamigen Oper ein Denkmal gesetzt hat.<\/strong><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die Kriminalpolizei suche nach der Ursache des Brandes in der Kirche, die vor einer Sanierung stand, schreibt die Kirchenverwaltung. Nach bisherigem Stand gebe es keine Hinweise auf Brandstiftung oder fahrl\u00e4ssiges Handeln. Die Ermittlungen dauerten noch an.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die St.Martha-Kirche war zu Beginn des 17. Jahrhunderts ein bedeutender Treffpunkt der N\u00fcrnberger Meistersinger. Der erste Akt der Wagner-Oper spielt allerdings in der N\u00fcrnberger Katharinenkirche, einem andern Versammlungsort der Gilde. <em>(cf)<\/em> <\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">11.06.2014 &#8212; Die N\u00fcrnberger St.Martha-Kirche ist ausgebrannt. Der Dachstuhl ist v\u00f6llig zerst\u00f6rt, die Orgel ist geschmolzen, die Fassade einsturzgef\u00e4hrdet. Die Kirche war im 17. Jahrhundert Treffpunkt der N\u00fcrnberger Meistersinger, denen Wagner mit seiner gleichnamigen Oper ein Denkmal gesetzt hat.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1486","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1486\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}