{"id":1550,"date":"2014-07-07T06:19:24","date_gmt":"2014-07-07T06:19:24","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/07\/07\/erste-singapore-international-violin-competition\/"},"modified":"2014-07-07T06:19:24","modified_gmt":"2014-07-07T06:19:24","slug":"erste-singapore-international-violin-competition","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/07\/07\/erste-singapore-international-violin-competition\/","title":{"rendered":"Erste Singapore International Violin Competition"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">07.07.2014 &#8212; Auch der s\u00fcdasiatische Stadtstaat Singapur will im globalen Zirkus der Musikwettbewerbe mitmischen. Der <\/span>National Arts Council und die National University of Singapore loben f\u00fcr die erste triennale Singapore International Violin Competition eine erkleckliche Preissumme aus.<\/p>\n<p><strong><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">07.07.2014 &#8212; <\/span><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Auch der s\u00fcdasiatische Stadtstaat Singapur will im globalen Zirkus der Musikwettbewerbe mitmischen. Der <\/span>National Arts Council und die National University of Singapore loben f\u00fcr die erste triennale Singapore International Violin Competition eine erkleckliche Preissumme aus.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>F\u00fcr den Gewinner oder die Gewinnerin des Wettbewerbs liegen schlappe 50&#8217;000 Dollar bereit. Die Competition geht zwischen 10. und 21. Januar 2015 am Yong Siew Toh Conservatory of Music \u00fcber die B\u00fchne. Die Jury besteht unter anderem aus Qian Zhou, der Leiterin der Streicherabteilung des Konservatoriums, dem franz\u00f6sischen Geiger Pierre Amoyal und Shmuel Ashkenasi, dem Gr\u00fcnder des Vermeer Quartet. <em>(cf)<\/em><\/p>\n<p>\u00a0<\/p>\n<p><strong>Mehr Infos<\/strong>: <a href=\"http:\/\/singaporeviolincompetition.com\" target=\"_blank\" rel=\"noopener noreferrer\">singaporeviolincompetition.com <\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">07.07.2014 &#8212; Auch der s\u00fcdasiatische Stadtstaat Singapur will im globalen Zirkus der Musikwettbewerbe mitmischen. Der <\/span>National Arts Council und die National University of Singapore loben f\u00fcr die erste triennale Singapore International Violin Competition eine erkleckliche Preissumme aus.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1550","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1550"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1550\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}