{"id":1727,"date":"2014-09-18T05:57:52","date_gmt":"2014-09-18T05:57:52","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/09\/18\/lucerne-festival-ark-nova-gastiert-in-sendai\/"},"modified":"2014-09-18T05:57:52","modified_gmt":"2014-09-18T05:57:52","slug":"lucerne-festival-ark-nova-gastiert-in-sendai","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/09\/18\/lucerne-festival-ark-nova-gastiert-in-sendai\/","title":{"rendered":"Lucerne Festival Ark Nova gastiert in Sendai"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">18.09.2014 &#8212; Lucerne Festival Ark Nova, der mobile Konzertsaal des Lucerne Festival und von Kajimoto, wird diesen Herbst im japanischen Sendai aufgebaut, nachdem er 2013 in Matsushima gastierte. Konzertieren werden unter anderem das Lucerne Festival Orchestra und die Kenichi Tsunoda Big Band.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>18.09.2014 &#8212; Lucerne Festival Ark Nova, der mobile Konzertsaal des Lucerne Festival und von Kajimoto, wird diesen Herbst im japanischen Sendai aufgebaut, nachdem er 2013 in Matsushima gastierte. Konzertieren werden unter anderem das Lucerne Festival Orchestra und die Kenichi Tsunoda Big Band.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die vom britischen Designer Anish Kapoor zusammen mit dem japanischen Architekten Arata Isozaki entwickelte aufblasbare und mobile Konzerthalle dient vom 1. bis 9. November 2014 zum zweiten Mal als Spiel- und Begegnungsort f\u00fcr K\u00fcnstler und Bev\u00f6lkerung, in diesem Jahr mitten im Stadtzentrum Sendais.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Neben Konzerten der Solisten des Lucerne Festival Orchestra und der Kenichi Tsunoda Big Band gibt es unter anderem Rezitals mit dem Shakuhachi-Virtuosen Kaoru Kakizakai, dem Pianisten Till Fellner, der Pianistin Yulianna Avdeeva und dem japanischen Akkordeonisten coba. Begleitend wird ein Bildungs- und Musikvermittlungsprogramm angeboten: Es gibt \u00f6ffentliche Proben eines Kinderorchesters und -chores und einen Meisterkurs mit Mitgliedern der Kenichi Tsunoda Big Band sowie ein Mitsingkonzert f\u00fcr Grundschulkinder und deren Eltern.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der versetzbare Konzertsaal bietet mit flexibler Bestuhlung Platz f\u00fcr bis zu 500 Personen und wurde vom 27. September bis zum 13. Oktober 2013 erstmals bespielt. F\u00fcr die kommenden Jahre ist in Planung, die Konzerthalle nach New York sowie in die Schweiz zu bringen.\u00a0<em> (cf)<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">18.09.2014 &#8212; Lucerne Festival Ark Nova, der mobile Konzertsaal des Lucerne Festival und von Kajimoto, wird diesen Herbst im japanischen Sendai aufgebaut, nachdem er 2013 in Matsushima gastierte. Konzertieren werden unter anderem das Lucerne Festival Orchestra und die Kenichi Tsunoda Big Band.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1727","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1727"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1727\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}