{"id":1732,"date":"2014-09-18T19:06:24","date_gmt":"2014-09-18T19:06:24","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/09\/18\/schweizerischer-musikverband-offeriert-gratis-jubilaeumskonzert\/"},"modified":"2014-09-18T19:06:24","modified_gmt":"2014-09-18T19:06:24","slug":"schweizerischer-musikverband-offeriert-gratis-jubilaeumskonzert","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/09\/18\/schweizerischer-musikverband-offeriert-gratis-jubilaeumskonzert\/","title":{"rendered":"Schweizerischer Musikverband offeriert Gratis-Jubil\u00e4umskonzert"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">19.09.2014 &#8212; Zu seinem 100-Jahr-Jubil\u00e4um l\u00e4dt der Schweizerische Musikverband am 6. Oktober zu einem grossen Festkonzert im Opernhaus Z\u00fcrich ein. Der Verband m\u00f6chte sein Jubil\u00e4um mit der ganzen Bev\u00f6lkerung feiern und vergibt die Karten kostenlos an alle Musikliebhaber.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>19.09.2014 &#8212; Zu seinem 100-Jahr-Jubil\u00e4um l\u00e4dt der Schweizerische Musikverband am 6. Oktober zu einem grossen Festkonzert im Opernhaus Z\u00fcrich ein. Der Verband m\u00f6chte sein Jubil\u00e4um mit der ganzen Bev\u00f6lkerung feiern und vergibt die Karten kostenlos an alle Musikliebhaber.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Das Festkonzert, dessen Patronat Bundesrat Alain Berset \u00fcbernommen hat, wird mit der Urauff\u00fchrung einer eigens f\u00fcr diesen Anlass komponierten Fanfare von Jean-Fran\u00e7ois Michel er\u00f6ffnet. Des Weiteren wird der Einzug der S\u00e4nger auf die Wartburg aus dem zweiten Akt von Wagners Tannh\u00e4user erklingen, und es werden Werke von Othmar Schoeck, Maurice Ravel und Richard Strauss zu h\u00f6ren sein.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Es spielt das Jubil\u00e4umsorchester des Schweizerischen Musikverbands mit Musikerinnen und Musikern aus allen Berufsorchestern der Schweiz sowie mit freischaffenden Musikern. Unter der musikalischen Leitung von Mario Venzago, dem Chefdirigenten des Berner Sinfonieorchesters, wirken ebenfalls die Ch\u00f6re des Opernhauses Z\u00fcrich und des Konzert Theaters Bern mit.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die Ticketvergabe startet am kommenden Samstag, den 20. September im Rahmen des grossen Er\u00f6ffnungsfests des Opernhauses Z\u00fcrich. Ab 11 Uhr k\u00f6nnen die Tickets ausschliesslich pers\u00f6nlich an der Billettkasse des Opernhauses bezogen werden (max. 4 Tickets pro Person).<em> (cf)<\/em><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">19.09.2014 &#8212; Zu seinem 100-Jahr-Jubil\u00e4um l\u00e4dt der Schweizerische Musikverband am 6. Oktober zu einem grossen Festkonzert im Opernhaus Z\u00fcrich ein. Der Verband m\u00f6chte sein Jubil\u00e4um mit der ganzen Bev\u00f6lkerung feiern und vergibt die Karten kostenlos an alle Musikliebhaber.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1732","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1732"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1732\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}