{"id":1776,"date":"2014-10-06T06:57:39","date_gmt":"2014-10-06T06:57:39","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/10\/06\/eklat-beim-klavierwettbewerb-rina-sala-gallo\/"},"modified":"2014-10-06T06:57:39","modified_gmt":"2014-10-06T06:57:39","slug":"eklat-beim-klavierwettbewerb-rina-sala-gallo","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/10\/06\/eklat-beim-klavierwettbewerb-rina-sala-gallo\/","title":{"rendered":"Eklat beim Klavierwettbewerb Rina Sala Gallo"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">06.10.2014 &#8211;Der franz\u00f6sische Pianist\u00a0 Pascal Rog\u00e9 hat die Jury des Internationalen Klavierwettbewerbs Rina Sala Gallo im italienischen Monza aus Protest verlassen. Die Begr\u00fcndung entspricht g\u00e4ngigen Vermutungen \u00fcber die Entscheidprozesse an solchen Konkurrenzen. Rog\u00e9 st\u00fcnden zudem drei Magnumflaschen Chianti zu. <\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>06.10.2014 &#8211;Der franz\u00f6sische Pianist Pascal Rog\u00e9 hat die Jury des Internationalen Klavierwettbewerbs Rina Sala Gallo im italienischen Monza aus Protest verlassen. Die Begr\u00fcndung entspricht g\u00e4ngigen Vermutungen \u00fcber die Entscheidprozesse an solchen Konkurrenzen.<span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"> Rog\u00e9 st\u00fcnden zudem drei Magnumflaschen Chianti zu.<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Rog\u00e9 protestiert mit dem Schritt gegen die Wahl der Finalisten und die Art, wie diese bestimmt worden sind. Zur Auswahl gestanden seien sechs Kandidaten, eine Japanerin, ein Japaner, drei Italiener und eine Koreanerin. Seit Beginn des Wettbewerbs, schreibt Rog\u00e9 auf seiner Facebook-Seite, h\u00e4tten die Koreanerin Yejin Noh und der Japaner Yuta Yano am besten abgeschnitten.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Ins Finale gehoben worden seien aber die beiden Italiener und die Japanerin, die zuletzt deutlich abgefallen sei. Der Entscheid sei der stark italienisch gepr\u00e4gten Jury zuzuschreiben, deren Strukturen an das Wort \u00abMafia\u00bb erinnerten.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Zwei Magnum-Flaschen Chianti, die Rog\u00e9 gewettet h\u00e4tte, dass die Preistr\u00e4ger in dieser Reihenfolge Fiorenzo Pascalucci (1.), Federica Bortoluzzi (2.) und Atsuko Kinoshita (3.) heissen w\u00fcrden, h\u00e4tte er im \u00fcbrigen gewonnen.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em>\u00a0<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Auf die Vorw\u00fcrfe Rog\u00e9s antwortet das italienische Jurymitglied Roberto Prosseda, das sie zur\u00fcckweist und Rog\u00e9 selber seltsames Juryverhalten vorwirft, auf dieser Seite:<\/span><\/span><br \/><a href=\"http:\/\/slippedisc.com\/2014\/10\/monza-a-maligned-juror-responds\/\">http:\/\/slippedisc.com\/2014\/10\/monza-a-maligned-juror-responds <\/a><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em>(cf)<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">06.10.2014 &#8211;Der franz\u00f6sische Pianist\u00a0 Pascal Rog\u00e9 hat die Jury des Internationalen Klavierwettbewerbs Rina Sala Gallo im italienischen Monza aus Protest verlassen. Die Begr\u00fcndung entspricht g\u00e4ngigen Vermutungen \u00fcber die Entscheidprozesse an solchen Konkurrenzen. Rog\u00e9 st\u00fcnden zudem drei Magnumflaschen Chianti zu. <\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1776","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1776"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1776\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}