{"id":1783,"date":"2014-10-08T05:55:17","date_gmt":"2014-10-08T05:55:17","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/10\/08\/der-jazz-im-europa-des-wirtschaftswunders\/"},"modified":"2014-10-08T05:55:17","modified_gmt":"2014-10-08T05:55:17","slug":"der-jazz-im-europa-des-wirtschaftswunders","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/10\/08\/der-jazz-im-europa-des-wirtschaftswunders\/","title":{"rendered":"Der Jazz im Europa des Wirtschaftswunders"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">08.10.2014 &#8212; Mehrere Schweizer Musikhochschulen veranstalten unter dem Titel \u00abGrowing Up: Jazz in Europa 1960 \u20131980\u00bb gemeinsam eine Tagung. Sie reflektiert die Entwicklungen im europ\u00e4ischen Jazz w\u00e4hrend zwei seiner ereignisreichsten Jahrzehnte.<\/span><\/p>\n<p><span style=\"font-family: arial black,avant garde; font-size: small;\">08.10.2014 &#8212; Mehrere Schweizer Musikhochschulen veranstalten unter dem Titel \u00abGrowing Up: Jazz in Europa 1960 \u20131980\u00bb gemeinsam eine Tagung. Sie reflektiert die Entwicklungen im europ\u00e4ischen Jazz w\u00e4hrend zwei seiner ereignisreichsten Jahrzehnte.<\/span><\/p>\n<p>\u00a0<\/p>\n<div class=\"text-section\">\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Zentrale Themen sind die Emanzipation des Jazz von den amerikanischen Vorbildern, der Pluralismus von Szenen und Stilen, die Instrumentalisierung w\u00e4hrend des Kalten Krieges im Westen und im Osten, Genderfragen, die Professionalisierung der Ausbildung, aber auch die Suche nach dem \u00abSchweizerischen\u00bb im Schweizer Jazz.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Erg\u00e4nzend zu den Referaten finden Concert Lectures, Workshopkonzerte von Studierenden und Konzerte u.a. mit der DKSJ-All-Star-Band (einem Ensemble mit Studierenden aller Schweizer Jazzdepartemente) sowie mit Ir\u00e8ne Schweizer und Pierre Favre statt.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die Konferenz wird in Zusammenarbeit der Hochschule der K\u00fcnste Bern (HKB), der Hochschule Luzern (HSLU) und der Haute Ecole de Musique Lausanne (HEMU) organisiert.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\"><strong>Info:<\/strong> 6.\u20138. November 2014, 6.\u20138. November 2014, Saal der Maskenliebhaber-Gesellschaft, S\u00fcesswinkel 7, 6004 Luzern.<\/span> <a href=\"http:\/\/www.hkb.bfh.ch\/growing-up\">www.hkb.bfh.ch\/growing-up<\/a><\/span><\/p>\n<\/p><\/div>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">08.10.2014 &#8212; Mehrere Schweizer Musikhochschulen veranstalten unter dem Titel \u00abGrowing Up: Jazz in Europa 1960 \u20131980\u00bb gemeinsam eine Tagung. Sie reflektiert die Entwicklungen im europ\u00e4ischen Jazz w\u00e4hrend zwei seiner ereignisreichsten Jahrzehnte.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1783","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1783"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1783\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}