{"id":189,"date":"2014-01-10T06:49:59","date_gmt":"2014-01-10T06:49:59","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/10\/bilanz-2013-des-haendel-hauses-in-halle\/"},"modified":"2014-01-10T06:49:59","modified_gmt":"2014-01-10T06:49:59","slug":"bilanz-2013-des-haendel-hauses-in-halle","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/10\/bilanz-2013-des-haendel-hauses-in-halle\/","title":{"rendered":"Bilanz 2013 des H\u00e4ndel-Hauses in Halle"},"content":{"rendered":"<p><em>10.01.2014 &#8212;<\/em> Im Jahr 2013 verzeichneten das H\u00e4ndel-Haus und das Wilhelm-Friedemann-Bach-Haus in Halle rund 34&#8217;000 Eintritte. Trotz Ausfall der H\u00e4ndel-Festspiele war demnach kaum ein Besucherr\u00fcckgang festzustellen.<\/p>\n<p><strong><em>10.01.2014 &#8212;<\/em> Im Jahr 2013 verzeichneten das H\u00e4ndel-Haus und das Wilhelm-Friedemann-Bach-Haus in Halle rund 34&#8217;000 Eintritte. Trotz Ausfall der H\u00e4ndel-Festspiele war demnach kaum ein Besucherr\u00fcckgang festzustellen.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Nach 2010 mit 34&#8217;000 und 2011 und 2012 mit jeweils 35&#8217;000 Eintritten verharrte die Zahl der Eintritte laut dem H\u00e4ndel-Haus auf etwa gleichem Niveau &#8211; trotz der wetterbedingten Absage der H\u00e4ndel-Festspiele. Vor allem im Monat Juni war die Zahl der Eintritte (3200) deutlich niedriger ausgefallen als in den beiden Vorjahren (5200).<\/p>\n<p>\u00a0<\/p>\n<p>Das seit Juni 2012 er\u00f6ffnete Wilhelm-Friedemann-Bach-Haus hat bei zwei \u00d6ffnungstagen in der Woche (Freitag und Samstag) einen Anteil von circa 1200 Eintritten f\u00fcr das Jahr 2013. 2013 realisierte die Stiftung H\u00e4ndel-Haus rund 170 Veranstaltungen &#8211; Konzerte, Vortr\u00e4ge und p\u00e4dagogische Veranstaltungen. Die Jahresausstellung 2013 (\u00abH\u00e4ndel als Staatskomponist?\u00bb) wird noch bis zum 26. Januar 2014 gezeigt.<em> (cf)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><em>10.01.2014 &#8212;<\/em> Im Jahr 2013 verzeichneten das H\u00e4ndel-Haus und das Wilhelm-Friedemann-Bach-Haus in Halle rund 34&#8217;000 Eintritte. Trotz Ausfall der H\u00e4ndel-Festspiele war demnach kaum ein Besucherr\u00fcckgang festzustellen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-189","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=189"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/189\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}