{"id":1938,"date":"2014-12-04T06:41:46","date_gmt":"2014-12-04T06:41:46","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/12\/04\/bestaende-des-schott-archivs-in-neuen-haenden\/"},"modified":"2014-12-04T06:41:46","modified_gmt":"2014-12-04T06:41:46","slug":"bestaende-des-schott-archivs-in-neuen-haenden","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/12\/04\/bestaende-des-schott-archivs-in-neuen-haenden\/","title":{"rendered":"Best\u00e4nde des Schott-Archivs in neuen H\u00e4nden"},"content":{"rendered":"<p><span style=\"font-size: small; line-height: 16px; font-family: arial,helvetica,sans-serif;\">04.12.2014 &#8212; Die Strecker-Stiftung Mainz hat das historische Archiv des Schott-Verlages an die Bayerische Staatsbibliothek und die Staatsbibliothek zu Berlin sowie sechs auf einzelne Komponisten spezialisierte Institutionen (darunter die Carl-Orff-Stiftung und die Fondation Hindemith) verkauft. <br \/><\/span><\/p>\n<p><span style=\"font-size: small; line-height: 16px; font-family: arial,helvetica,sans-serif;\"><strong>04.12.2014 &#8212; Die Strecker-Stiftung Mainz hat das historische Archiv des Schott-Verlages an die Bayerische Staatsbibliothek und die Staatsbibliothek zu Berlin sowie sechs auf einzelne Komponisten spezialisierte Institutionen (darunter die Carl-Orff-Stiftung und die Fondation Hindemith) verkauft.<\/strong> <\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Das Konvolut umfasst die rund 85&#8217;000 Archivalien des historischen Verlagsarchivs, die bis einschliesslich 1950 bei Schott Mainz eingingen oder entstanden. Dazu geh\u00f6ren das historische Herstellungs-, Musikautographen- und Erstausgabenarchiv ebenso wie die unz\u00e4hligen Einzelst\u00fccke der Gesch\u00e4ftsakten von 1787 bis 1945 sowie Briefe bis 1950. Allein das Briefarchiv umfasst rund 40&#8217;000 Positionen, darunter 265 Briefe aus der Feder von Richard Wagner und 690 von Paul Hindemith. <\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Unter den wertvollen Musikmanuskripten ist Richard Wagners erster handschriftlicher Entwurf zum Text der Oper <em>Die Meistersinger von N\u00fcrnberg<\/em>. Ausserdem umfasst das historische Archiv die Partitur-Autographe bedeutender Werke des 20. Jahrhunderts wie <em>Carmina Burana<\/em> (Chorpartitur) von Carl Orff, die sechste Symphonie von Karl Amadeus Hartmann und <em>Il canto sospeso<\/em> von Luigi Nono. <em>(cf)<\/em><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: small; line-height: 16px; font-family: arial,helvetica,sans-serif;\">04.12.2014 &#8212; Die Strecker-Stiftung Mainz hat das historische Archiv des Schott-Verlages an die Bayerische Staatsbibliothek und die Staatsbibliothek zu Berlin sowie sechs auf einzelne Komponisten spezialisierte Institutionen (darunter die Carl-Orff-Stiftung und die Fondation Hindemith) verkauft. <br \/><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1938","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1938"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1938\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}