{"id":1947,"date":"2014-12-08T06:59:53","date_gmt":"2014-12-08T06:59:53","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/12\/08\/kulturstiftung-dortmund\/"},"modified":"2014-12-08T06:59:53","modified_gmt":"2014-12-08T06:59:53","slug":"kulturstiftung-dortmund","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/12\/08\/kulturstiftung-dortmund\/","title":{"rendered":"Kulturstiftung Dortmund ehrt Edita Gruberova"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">08.12.2014 &#8212; Die Kulturstiftung Dortmund hat mit ihrem mit 25&#8217;000 Euro dotierten Kulturpreis die Sopranistin Edita Gruberova f\u00fcr ihr Lebenswerk ausgezeichnet.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>08.12.2014 &#8212; Die Kulturstiftung Dortmund hat mit ihrem mit 25&#8217;000 Euro dotierten Kulturpreis die Sopranistin Edita Gruberova f\u00fcr ihr Lebenswerk ausgezeichnet.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Mit dem Preis w\u00fcrdige man \u00abeine der bedeutendsten S\u00e4ngerinnen unserer Zeit und eine beeindruckende Pers\u00f6nlichkeit\u00bb, erkl\u00e4rt dazu Hans-Dieter Michalski, der Vorsitzende der Kulturstiftung Dortmund, bei der \u00dcbergabe des Preises. Er betont dabei zugleich auch das soziale Engagement der Preistr\u00e4gerin &#8211; insbesondere zugunsten von Kindern in Not.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der Preis der Kulturstiftung Dortmund, eine Initiative der Dortmunder Wirtschaft f\u00fcr Kunst und Kultur, wird seit 1998 im Zweijahresrhythmus vergeben. Die Preistr\u00e4ger, abwechselnd aus den Bereichen Musik und Bildende Kunst, werden f\u00fcr ihr Lebenswerk geehrt. Die Preisvergabe an Edita Gruberova ist auf Vorschlag einer Jury erfolgt, der mit J\u00fcrgen Kesting, Andreas M\u00f6lich-Zebhauser und Franz Willnauer Fachleute sowie als Vertreter der Stiftung Harald Heinze und Hans-Dieter Michalski angeh\u00f6ren.<em> (cf)<\/em><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">08.12.2014 &#8212; Die Kulturstiftung Dortmund hat mit ihrem mit 25&#8217;000 Euro dotierten Kulturpreis die Sopranistin Edita Gruberova f\u00fcr ihr Lebenswerk ausgezeichnet.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1947","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1947"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1947\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}