{"id":1948,"date":"2014-12-08T07:13:00","date_gmt":"2014-12-08T07:13:00","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/12\/08\/zuercher-opernorchester-mit-eigenen-label\/"},"modified":"2014-12-08T07:13:00","modified_gmt":"2014-12-08T07:13:00","slug":"zuercher-opernorchester-mit-eigenen-label","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/12\/08\/zuercher-opernorchester-mit-eigenen-label\/","title":{"rendered":"Z\u00fcrcher Opernorchester mit eigenen Label"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">08.12.2014 &#8212; Philharmonia Z\u00fcrich, das Orchester des Z\u00fcrcher Opernhauses, hat mit Philharmonia Records ein eigenes Label gegr\u00fcndet. Erste Releases sind ein Livemitschnitt von Hector Berlioz\u2019 <em>Symphonie fantastique, <\/em>eine Studioaufnahme mit ausgew\u00e4hlten Ouvert\u00fcren und Zwischenspielen aus Opern von Wagner sowie Verdis <em>Rigoletto<\/em> in der Inszenierung von Tatjana G\u00fcrbaca auf DVD.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>08.12.2014 &#8212; Philharmonia Z\u00fcrich, das Orchester des Z\u00fcrcher Opernhauses, hat mit Philharmonia Records ein eigenes Label gegr\u00fcndet. Erste Releases sind ein Livemitschnitt von Hector Berlioz\u2019 <em>Symphonie fantastique, <\/em>eine Studioaufnahme mit ausgew\u00e4hlten Ouvert\u00fcren und Zwischenspielen aus Opern von Wagner sowie Verdis <em>Rigoletto<\/em> in der Inszenierung von Tatjana G\u00fcrbaca auf DVD.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Im Oktober 2015 wird \u00fcberdies eine CD-Box mit allen Rachmaninow-Klavierkonzerten ver\u00f6ffentlicht, mit Lise de la Salle\u00a0\u2013 seit 2013 Artist in Residence bei der Philharmonia Z\u00fcrich <span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u2013 <\/span> als Solistin. Ab 2016 sollen j\u00e4hrlich zwei bis drei weitere Ver\u00f6ffentlichungen mit Fabio Luisi und der Philharmonia Z\u00fcrich bei Philharmonia Records erscheinen und weltweit im Handel und \u00fcber Online-Vertriebskan\u00e4le erh\u00e4ltlich sein. Generalmusikdirektor Fabio Luisi und die Philharmonia Z\u00fcrich wollen damit den eingeschlagenen Weg, das Orchester auch im sinfonischen Bereich st\u00e4rker zu positionieren, weiter beschreiten. <\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">1985 aus der Trennung des traditionsreichen Tonhalle- und Theaterorchesters hervorgegangen, ist das Orchester der Oper Z\u00fcrich mit Beginn der Intendanz von Andreas Homoki und dem Amtsantritt des neuen Generalmusikdirektors Fabio Luisi 2012 zur Philharmonia Z\u00fcrich umfirmiert worden. <em>(cf)<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">08.12.2014 &#8212; Philharmonia Z\u00fcrich, das Orchester des Z\u00fcrcher Opernhauses, hat mit Philharmonia Records ein eigenes Label gegr\u00fcndet. Erste Releases sind ein Livemitschnitt von Hector Berlioz\u2019 <em>Symphonie fantastique, <\/em>eine Studioaufnahme mit ausgew\u00e4hlten Ouvert\u00fcren und Zwischenspielen aus Opern von Wagner sowie Verdis <em>Rigoletto<\/em> in der Inszenierung von Tatjana G\u00fcrbaca auf DVD.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1948","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1948"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1948\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}