{"id":1951,"date":"2014-12-09T07:12:09","date_gmt":"2014-12-09T07:12:09","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/12\/09\/anna-netrebko-unterstuetzt-donetsker-oper\/"},"modified":"2014-12-09T07:12:09","modified_gmt":"2014-12-09T07:12:09","slug":"anna-netrebko-unterstuetzt-donetsker-oper","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/12\/09\/anna-netrebko-unterstuetzt-donetsker-oper\/","title":{"rendered":"Anna Netrebko unterst\u00fctzt Donetsker Oper"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">09.12.2014 &#8212; Laut einer Notiz des luxemburgischen Fachmagazins <em>Pizzicato<\/em> hat die Sopranistin Anna Netrebko das Opern- und Balletttheater in der ost-ukrainischen Sadt Donetsk mit einer Million Rubel (15&#8217;000 Euro) unterst\u00fctzt und sich zusammen mit dem prorussischen Separatistenf\u00fchrer der Ostukraine hinter der Separatistenfahne ablichten lassen.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>09.12.2014 &#8212; Laut einer Notiz des luxemburgischen Fachmagazins <em>Pizzicato<\/em> hat die Sopranistin Anna Netrebko das Opern- und Balletttheater in der ost-ukrainischen Sadt Donetsk mit einer Million Rubel (15&#8217;000 Euro) unterst\u00fctzt und sich zusammen mit dem prorussischen Separatistenf\u00fchrer der Ostukraine hinter der Separatistenfahne ablichten lassen.<\/strong><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Laut Pizzicato betont Netrebko, dass sie keine Politikerin sei, sondern nur helfen wolle. Sie habe Kollegen in Donetsk, die erz\u00e4hlten, wie es sei, unter den Bomben zu leben, und dennoch zu den Proben zu gehen.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die via Twitter verbreitete Foto zeigt die S\u00e4ngerin allerdings mit Oleg Zarjow, der auf der schwarzen Sanktionsliste der EU steht. <em>(cf)<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em><br \/><\/em><strong>Originalartikel:<\/strong> <\/span><a href=\"http:\/\/www.pizzicato.lu\/netrebko-spielt-ein-gefahrliches-spiel\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">www.pizzicato.lu\/netrebko-spielt-ein-gefahrliches-spiel\/<\/span><em><br \/><\/em><\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">09.12.2014 &#8212; Laut einer Notiz des luxemburgischen Fachmagazins <em>Pizzicato<\/em> hat die Sopranistin Anna Netrebko das Opern- und Balletttheater in der ost-ukrainischen Sadt Donetsk mit einer Million Rubel (15&#8217;000 Euro) unterst\u00fctzt und sich zusammen mit dem prorussischen Separatistenf\u00fchrer der Ostukraine hinter der Separatistenfahne ablichten lassen.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1951","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1951"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1951\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}