{"id":1980,"date":"2014-12-17T12:56:34","date_gmt":"2014-12-17T12:56:34","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/12\/17\/aufenthaltsbewilligungen-fuer-musiker-aus-drittstaaten\/"},"modified":"2014-12-17T12:56:34","modified_gmt":"2014-12-17T12:56:34","slug":"aufenthaltsbewilligungen-fuer-musiker-aus-drittstaaten","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/12\/17\/aufenthaltsbewilligungen-fuer-musiker-aus-drittstaaten\/","title":{"rendered":"Musiker aus Drittstaaten in der Schweiz"},"content":{"rendered":"<p style=\"text-align: center;\"><em>von Wolfgang B\u00f6hler<\/em><\/p>\n<p>\u00a0<\/p>\n<p><img decoding=\"async\" src=\"images\/kolumnewb.jpg\" border=\"0\" alt=\"Portr\u00e4t Wolfgang B\u00f6hler\" style=\"float: left; margin: 4px;\" \/>12.12.2014 &#8212; Daniel Stolz, freisinnig-liberaler Nationalrat der Stadt Basel, hat vor einigen Tagen in seinem Rat eine Interpellation eingereicht. Er will wissen, wie viele Kunstschaffende aus Drittstaaten in den letzten Jahren eine Aufenthaltsbewilligung in der Schweiz erhalten haben, welchen Einfluss die vom Bundesrat k\u00fcrzlich beschlossene K\u00fcrzung der Drittstaatenkontingente hat und ob Absolventinnen und Absolventen Schweizer Hochschulen mit einer erfolgreichen Karriere und regelm\u00e4ssigen Kunstprojekten in der Schweiz Wohnsitz in der Schweiz nehmen k\u00f6nnen. Stolz fragt sich, ob in diesem Bereich allenfalls eine Regelungsl\u00fccke besteht.\u00a0 Motiviert ist die Interpellation von den j\u00fcngsten Entwicklungen in \u00a0Basel, wo formal allzu salopp Aufenthaltsbewilligungen f\u00fcr Musiker aus Drittstaaten erteilt worden sind und einige nun damit rechnen m\u00fcssen, diese zu verlieren.<\/p>\n<p style=\"text-align: center;\"><em>von Wolfgang B\u00f6hler<\/em><\/p>\n<p>\u00a0<\/p>\n<p><img decoding=\"async\" src=\"images\/kolumnewb.jpg\" border=\"0\" alt=\"Portr\u00e4t Wolfgang B\u00f6hler\" style=\"float: left; margin: 4px;\" \/>12.12.2014 &#8212; Daniel Stolz, freisinnig-liberaler Nationalrat der Stadt Basel, hat vor einigen Tagen in seinem Rat eine Interpellation eingereicht. Er will wissen, wie viele Kunstschaffende aus Drittstaaten in den letzten Jahren eine Aufenthaltsbewilligung in der Schweiz erhalten haben, welchen Einfluss die vom Bundesrat k\u00fcrzlich beschlossene K\u00fcrzung der Drittstaatenkontingente hat und ob Absolventinnen und Absolventen Schweizer Hochschulen mit einer erfolgreichen Karriere und regelm\u00e4ssigen Kunstprojekten in der Schweiz Wohnsitz in der Schweiz nehmen k\u00f6nnen. Stolz fragt sich, ob in diesem Bereich allenfalls eine Regelungsl\u00fccke besteht.\u00a0 Motiviert ist die Interpellation von den j\u00fcngsten Entwicklungen in \u00a0Basel, wo formal allzu salopp Aufenthaltsbewilligungen f\u00fcr Musiker aus Drittstaaten erteilt worden sind und einige nun damit rechnen m\u00fcssen, diese zu verlieren.<\/p>\n<p>\u00a0<\/p>\n<p>In vielen Zentren der Schweiz, nicht zuletzt in Basel werde, so Stolz, \u00abin die Entwicklung der Hochschule f\u00fcr Musik Basel mit ihrer Spezialisierung auf Neue Musik sowie die Schola Cantorum Basiliensis, weltweit ber\u00fchmt als spezialisierte Hochschule f\u00fcr Alte Musik, investiert\u00bb. \u00a0Er w\u00fcnscht sich, dass der Aufenthalt von professionellen Musikern erm\u00f6glicht wird, die \u00abAbsolventinnen und Absolventen von Schweizer Kunsthochschulen sind, die als selbst\u00e4ndig Erwerbst\u00e4tige in regelm\u00e4ssigen Abst\u00e4nden in Kunstprojekten in der Schweiz, deren Arbeitspensum in Kombination verschiedener Erwerbst\u00e4tigkeiten einem Besch\u00e4ftigungsgrad von 75 Prozent gleich kommt und deren Engagement aufgrund ihrer bisherigen Karriere (Biographie) f\u00fcr Hauptrollen auf B\u00fchnen bzw. tragende Funktionen im Orchester oder als Mitglied eines bestehenden, in der Schweiz basierten Ensembles basiert\u00bb.<\/p>\n<p>\u00a0<\/p>\n<p>Tats\u00e4chlich ist der professionelle Musikmarkt (in beinahe allen Stilen) heute eines der am st\u00e4rksten globalisierten Gebiete menschlicher T\u00e4tigkeiten, und nationale Abgrenzungsstrategien machen da noch weniger Sinn als auf manchem anderen Arbeitsmarkt. Die Schweiz ist, auch wenn die Schweizer dies selber nicht immer realisieren, eines der weltweiten Gravitationszentren der Ausbildung und des Festival- und Konzertlebens, zumindest in der klassischen Musik. Ein m\u00f6glichst freier Austausch ist deshalb mehr als w\u00fcnschenswert.<\/p>\n<p>\u00a0<\/p>\n<p>Das Anliegen ist aber auch heikel. Es gibt unz\u00e4hlige exzellent ausgebildete Musikerinnen und Musiker, die sich liebend gerne in der Schweiz niederlassen w\u00fcrden, und die Regelungen dazu sollten nicht allzu locker formuliert sein. Sonst k\u00f6nnten ausl\u00e4ndische Musiker in der Schweiz dem Verdacht ausgesetzt werden, ihre T\u00e4tigkeit bloss f\u00fcr eine Niederlassung hierzulande zu benutzen. Auf der andern Seite d\u00fcrften allzu strikte Regeln B\u00fcrokratie und Kontrollwahn bef\u00f6rdern und die Kulturinstitutionen mit schikan\u00f6sem administrativem Aufwand belasten. Zudem m\u00fcsste wirklich gut begr\u00fcndet werden k\u00f6nnen, dass gerade auf dem Gebiet der Musik eine grossz\u00fcgigere Vergabepraxis legitimiert werden sollte, als in andern Branchen, die m\u00f6glicherweise mit einer vergleichbaren Internationalisierung argumentieren k\u00f6nnen.<\/p>\n<p>\u00a0<\/p>\n<p>Eine L\u00f6sung f\u00fcr die institutionell protegierten Musiker k\u00f6nnte m\u00f6glicherweise ungerecht sein, weil sie \u00a0Autodidakten oder Kreative mit ungew\u00f6hnlichen Werdeg\u00e4ngen diskriminiert, die k\u00fcnstlerisch m\u00f6glicherweise genauso bedeutende (oder gar bedeutendere?) Beitr\u00e4ge zur Lebendigkeit des aktuellen Musiklebens beitragen. Bedingungen f\u00fcr Aufenthaltsbewilligungen an etablierte Strukturen zu kn\u00fcpfen, k\u00f6nnte da sogar strukturerhaltend und innovationshemmend sein.<\/p>\n<p>\u00a0<\/p>\n<p>Man sieht: ein sehr schwieriges Thema. Man sollte sich aber nicht scheuen, sich seiner tats\u00e4chlich anzunehmen und eine m\u00f6glichst solide L\u00f6sung daf\u00fcr zu finden. \u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><em>von Wolfgang B\u00f6hler<\/em><\/p>\n<p>\u00a0<\/p>\n<p><img decoding=\"async\" src=\"images\/kolumnewb.jpg\" border=\"0\" alt=\"Portr\u00e4t Wolfgang B\u00f6hler\" style=\"float: left; margin: 4px;\" \/>12.12.2014 &#8212; Daniel Stolz, freisinnig-liberaler Nationalrat der Stadt Basel, hat vor einigen Tagen in seinem Rat eine Interpellation eingereicht. Er will wissen, wie viele Kunstschaffende aus Drittstaaten in den letzten Jahren eine Aufenthaltsbewilligung in der Schweiz erhalten haben, welchen Einfluss die vom Bundesrat k\u00fcrzlich beschlossene K\u00fcrzung der Drittstaatenkontingente hat und ob Absolventinnen und Absolventen Schweizer Hochschulen mit einer erfolgreichen Karriere und regelm\u00e4ssigen Kunstprojekten in der Schweiz Wohnsitz in der Schweiz nehmen k\u00f6nnen. Stolz fragt sich, ob in diesem Bereich allenfalls eine Regelungsl\u00fccke besteht.\u00a0 Motiviert ist die Interpellation von den j\u00fcngsten Entwicklungen in \u00a0Basel, wo formal allzu salopp Aufenthaltsbewilligungen f\u00fcr Musiker aus Drittstaaten erteilt worden sind und einige nun damit rechnen m\u00fcssen, diese zu verlieren.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1980","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1980"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/1980\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}