{"id":2153,"date":"2015-03-10T07:52:16","date_gmt":"2015-03-10T07:52:16","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2015\/03\/10\/wollasch-wird-geschaeftsfuehrer-der-bdbv\/"},"modified":"2015-03-10T07:52:16","modified_gmt":"2015-03-10T07:52:16","slug":"wollasch-wird-geschaeftsfuehrer-der-bdbv","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2015\/03\/10\/wollasch-wird-geschaeftsfuehrer-der-bdbv\/","title":{"rendered":"Wollasch wird Gesch\u00e4ftsf\u00fchrer der BDBV"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">10.03.2015 &#8212; Die Bundesvereinigung Deutscher Musikverb\u00e4nde (BDBV) hat mit dem 29-j\u00e4hrigen Johannes Wollasch aus Bad Cannstatt einen neuen Gesch\u00e4ftsf\u00fchrer.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>10.03.2015 &#8212; Die Bundesvereinigung Deutscher Musikverb\u00e4nde (BDBV) hat mit dem 29-j\u00e4hrigen Johannes Wollasch aus Bad Cannstatt einen neuen Gesch\u00e4ftsf\u00fchrer.<\/strong><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Wollasch studierte er an der Hochschule f\u00fcr Wirtschaft, Technik und Gestaltung in Pforzheim Betriebswirtschaft mit der Vertiefung Personalmanagement. Es folge ein weiteres Studium f\u00fcr Kultur, Wissenschaft und Kulturmanagement am Institut f\u00fcr Kulturmanagement in Ludwigsburg. Danach war er an mehreren Projekten als Wirtschaftsberater bei einer Versicherung, am Deutschen Theater in G\u00f6ttingen und an der Musikhochschule in Trossingen beteiligt.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der Bundesvereinigung Deutscher Musikverb\u00e4nde e.V. (BDMV) geh\u00f6ren \u00fcber 1,3 Millionen Mitglieder an. Vorwiegend ehrenamtlich gef\u00fchrte Orchester sind in Deutschlands gr\u00f6sstem Musikverband organisiert. Sie ist der Dachverband von mehr als 18&#8217;000 Ensembles in rund 11&#8217;000 Mitgliedsvereinen und k\u00fcmmert sich um die Interessenvertretung gegen\u00fcber Politik und Medien und um die musikalisch-fachliche Grundlagenarbeit. <em>(cf)<\/em><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">10.03.2015 &#8212; Die Bundesvereinigung Deutscher Musikverb\u00e4nde (BDBV) hat mit dem 29-j\u00e4hrigen Johannes Wollasch aus Bad Cannstatt einen neuen Gesch\u00e4ftsf\u00fchrer.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2153","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=2153"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2153\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=2153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=2153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=2153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}