{"id":2179,"date":"2015-03-20T07:07:22","date_gmt":"2015-03-20T07:07:22","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2015\/03\/20\/online-musikservice-qobuz-kommt-in-die-schweiz\/"},"modified":"2015-03-20T07:07:22","modified_gmt":"2015-03-20T07:07:22","slug":"online-musikservice-qobuz-kommt-in-die-schweiz","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2015\/03\/20\/online-musikservice-qobuz-kommt-in-die-schweiz\/","title":{"rendered":"Online-Musikservice Qobuz kommt in die Schweiz"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">20.03.2015 &#8212; Der franz\u00f6sische Online-Musikservice Qobuz weitet sein Angebot auf Deutschland, \u00d6sterreich und die\u00a0 Schweiz aus. Er macht gem\u00e4ss Selbstdeklaration als \u00abweltweit einziger Online-Musikanbieter seinen umfassenden Musikkatalog sowohl im HiFi Streaming in CD-Qualit\u00e4t als auch als Hi-Res Downloads in 24 Bit verf\u00fcgbar\u00bb.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>20.03.2015 &#8212; Der franz\u00f6sische Online-Musikservice Qobuz weitet sein Angebot auf Deutschland, \u00d6sterreich und die\u00a0 Schweiz aus. Er macht gem\u00e4ss Selbstdeklaration als \u00abweltweit einziger Online-Musikanbieter seinen umfassenden Musikkatalog sowohl im HiFi Streaming in CD-Qualit\u00e4t als auch als Hi-Res Downloads in 24 Bit verf\u00fcgbar\u00bb.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Auf der deutschsprachigen Version des Onlineportals offeriert Qobuz Einspielungen s\u00e4mtlicher Independent und Major Labels und aller Genres von Klassik \u00fcber Jazz bis hin zu Rock, Pop und Elektro.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Qobuz wurde 2008 in Frankreich aus der Taufe gehoben. Im vergangenen Jahr hat der Dienst zun\u00e4chst sein Streaming-Angebot auf acht weitere europ\u00e4ische L\u00e4nder ausgedehnt, darunter Deutschland, Grossbritannien und die Niederlande. F\u00fcr das Jahr 2015 ist die Ausdehnung des Musikservices auf weitere europ\u00e4ische L\u00e4nder geplant. Bis Ende des Jahres will Qobuz in 25 L\u00e4ndern aktiv sein.\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>Mehr Infos:<\/strong> <a href=\"http:\/\/www.qobuz.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.qobuz.com<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">20.03.2015 &#8212; Der franz\u00f6sische Online-Musikservice Qobuz weitet sein Angebot auf Deutschland, \u00d6sterreich und die\u00a0 Schweiz aus. Er macht gem\u00e4ss Selbstdeklaration als \u00abweltweit einziger Online-Musikanbieter seinen umfassenden Musikkatalog sowohl im HiFi Streaming in CD-Qualit\u00e4t als auch als Hi-Res Downloads in 24 Bit verf\u00fcgbar\u00bb.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2179","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=2179"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2179\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=2179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=2179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=2179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}