{"id":2303,"date":"2015-05-15T05:57:08","date_gmt":"2015-05-15T05:57:08","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2015\/05\/15\/botero-erhaelt-den-theodore-gouvy-preis-2015\/"},"modified":"2015-05-15T05:57:08","modified_gmt":"2015-05-15T05:57:08","slug":"botero-erhaelt-den-theodore-gouvy-preis-2015","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2015\/05\/15\/botero-erhaelt-den-theodore-gouvy-preis-2015\/","title":{"rendered":"Botero erh\u00e4lt den Th\u00e9odore-Gouvy-Preis 2015"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">15.05.2015 &#8212; Der vom Eurodistrict SaarMoselle ausgelobte Th\u00e9odore-Gouvy-Preis 2015 geht an den 1987 geborenen kolumbianischen Komponisten Mart\u00edn Rinc\u00f3n Botero f\u00fcr sein Orchesterwerk <em>Planos y fondos<\/em>. Das Werk ist von Elementen s\u00fcdamerikanischer Rhythmen gepr\u00e4gt.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>15.05.2015 &#8212; Der vom Eurodistrict SaarMoselle ausgelobte Th\u00e9odore-Gouvy-Preis 2015 geht an den 1987 geborenen kolumbianischen Komponisten Mart\u00edn Rinc\u00f3n Botero f\u00fcr sein Orchesterwerk <em>Planos y fondos<\/em>. Das Werk ist von Elementen s\u00fcdamerikanischer Rhythmen gepr\u00e4gt.<\/strong><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der Preis beinhaltet einen Auftrag f\u00fcr ein Orchesterwerk, das im Mai 2016 von der Deutschen Radio Philharmonie uraufgef\u00fchrt wird und mit 5000 Euro dotiert ist.\u00a0 <\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der Singer-Songwriter, Gitarrist, Schlagzeuger und Keyboarder Botero studierte in Bogot\u00e1 Komposition. Nach privaten Studien bei dem amerikanischen Komponisten Don Freund, ist er seit 2013 Masterstudent im Fach Komposition bei Dieter Mack in L\u00fcbeck. Seit Oktober 2013 wirkt er auch als Dirigent des Sinfonischen Blasorchesters Wind &amp; Brass Hamburg. <\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Als Hommage an den im 19. Jahrhundert im saarl\u00e4ndisch-lothringischen Grenzraum lebenden deutsch-franz\u00f6sischen Komponisten Th\u00e9odore Gouvy, wurde der nach ihm benannte Kompositionspreis nun zum zweiten Mal vom Eurodistrict SaarMoselle ausgelobt. Die Musiker der Deutschen Radio Philharmonie w\u00e4hlten im Anschluss an das Abschlusskonzert der Saarbr\u00fccker Komponistenwerkstatt 2015 unter den f\u00fcnf teilnehmenden Jungkomponisten den Preistr\u00e4ger.<em> (cf)<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">15.05.2015 &#8212; Der vom Eurodistrict SaarMoselle ausgelobte Th\u00e9odore-Gouvy-Preis 2015 geht an den 1987 geborenen kolumbianischen Komponisten Mart\u00edn Rinc\u00f3n Botero f\u00fcr sein Orchesterwerk <em>Planos y fondos<\/em>. Das Werk ist von Elementen s\u00fcdamerikanischer Rhythmen gepr\u00e4gt.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2303","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=2303"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2303\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=2303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=2303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=2303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}