{"id":2334,"date":"2015-06-01T06:10:19","date_gmt":"2015-06-01T06:10:19","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2015\/06\/01\/mohn-stiftung-sucht-musische-projektideen\/"},"modified":"2015-06-01T06:10:19","modified_gmt":"2015-06-01T06:10:19","slug":"mohn-stiftung-sucht-musische-projektideen","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2015\/06\/01\/mohn-stiftung-sucht-musische-projektideen\/","title":{"rendered":"Mohn-Stiftung sucht musische Projektideen"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">01.06.2015 &#8212; Die Liz Mohn Kultur- und Musikstiftung sucht musische Projektideen, die das Miteinander von Kindern und Jugendlichen verschiedener kultureller Herkunft f\u00f6rdern. Sie stellt dazu F\u00f6rdermittel in H\u00f6he von 50&#8217;000 Euro bereit.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>01.06.2015 &#8212; Die Liz Mohn Kultur- und Musikstiftung sucht musische Projektideen, die das Miteinander von Kindern und Jugendlichen verschiedener kultureller Herkunft f\u00f6rdern. Sie stellt dazu F\u00f6rdermittel in H\u00f6he von 50&#8217;000 Euro bereit.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Bis zum 15. September 2015 k\u00f6nnen sich Kinderg\u00e4rten, Schulen, Vereine, Verb\u00e4nde, Stiftungen, aber auch einzelne Initiativen und Akteure mit gemeinn\u00fctziger Zielsetzung bewerben, die in musischen Projekten zeigen, wie Vielfalt gelebt werden kann. Gesucht werden neue Ideen, bei denen Kinder und Jugendliche in allen Phasen aktiv beteiligt sind. <\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Bereits gestartete oder in Deutschland schon existierende Projekte werden nicht gef\u00f6rdert. Die Laufzeit sollte drei Monate nicht \u00fcberschreiten. Maximal 15 Antr\u00e4ge wird die <em>Ideeninitiative\u201a Kulturelle Vielfalt mit Musik<\/em> der Stiftung mit jeweils bis zu 5000 Euro unterst\u00fctzen. Das Bewerbungsformular ist auf der Website <a href=\"http:\/\/www.kultur-und-musikstiftung.de%20\" target=\"_blank\" rel=\"noopener noreferrer\">www.kultur-und-musikstiftung.de <\/a>erh\u00e4ltlich. <em>(cf)<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">01.06.2015 &#8212; Die Liz Mohn Kultur- und Musikstiftung sucht musische Projektideen, die das Miteinander von Kindern und Jugendlichen verschiedener kultureller Herkunft f\u00f6rdern. Sie stellt dazu F\u00f6rdermittel in H\u00f6he von 50&#8217;000 Euro bereit.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2334","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}