{"id":2339,"date":"2015-06-02T09:38:56","date_gmt":"2015-06-02T09:38:56","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2015\/06\/02\/streaming-und-downloads-auf-dem-vormarsch\/"},"modified":"2015-06-02T09:38:56","modified_gmt":"2015-06-02T09:38:56","slug":"streaming-und-downloads-auf-dem-vormarsch","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2015\/06\/02\/streaming-und-downloads-auf-dem-vormarsch\/","title":{"rendered":"Streaming und Downloads auf dem Vormarsch"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em>von Wolfgang B\u00f6hler<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em>\u00a0<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><img decoding=\"async\" src=\"images\/kolumnewb.jpg\" border=\"0\" alt=\"Portr\u00e4t Wolfgang B\u00f6hler\" style=\"float: left; margin: 8px;\" \/>29.05.2015 &#8212; In Sachen physische Tontr\u00e4ger mutet die Situation mittlerweile absurd an: Sie haben ihren Ereignischarakter praktisch vollst\u00e4ndig verloren, und Geld l\u00e4sst sich damit keines mehr verdienen. Gl\u00fccklich ist, wer sie einspielen kann, ohne dabei allzu grosse Verluste einzufahren. Dennoch ist die Produktion eines Tontr\u00e4gers f\u00fcr Musiker nach wie vor unverzichtbar, ja wichtiger denn je. Erwartet werden CD von Agenturen und Veranstaltern. K\u00fcnstler und Gruppen, die keine Tontr\u00e4ger und idealerweise Rezensionen dazu vorlegen k\u00f6nnen, werden weniger gebucht. Das Renommee der CD erinnert damit ein wenig an die Grinsekatze in <em>Alice in Wonderland<\/em>: Sie verschwindet k\u00f6rperlich nach und nach, bis bloss noch ihr Grinsen \u00fcbrigbleibt. Auch die Tontr\u00e4ger sind k\u00f6rperlich verschwunden. Bloss noch ihre (Phantom-)Funktion als Relevanzzeuge ist geblieben.<\/span><\/p>\n<p style=\"text-align: center;\">\u00a0<span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em>von Wolfgang B\u00f6hler <br \/><\/em><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><img decoding=\"async\" src=\"images\/kolumnewb.jpg\" border=\"0\" alt=\"Portr\u00e4t Wolfgang B\u00f6hler\" style=\"float: left; margin: 8px;\" \/>29.05.2015 &#8212; In Sachen physische Tontr\u00e4ger mutet die Situation mittlerweile absurd an: Sie haben ihren Ereignischarakter praktisch vollst\u00e4ndig verloren, und Geld l\u00e4sst sich damit keines mehr verdienen. Gl\u00fccklich ist, wer sie einspielen kann, ohne dabei allzu grosse Verluste einzufahren. Dennoch ist die Produktion eines Tontr\u00e4gers f\u00fcr Musiker nach wie vor unverzichtbar, ja wichtiger denn je. Erwartet werden CD von Agenturen und Veranstaltern. K\u00fcnstler und Gruppen, die keine Tontr\u00e4ger und idealerweise Rezensionen dazu vorlegen k\u00f6nnen, werden weniger gebucht. Das Renommee der CD erinnert damit ein wenig an die Grinsekatze in <em>Alice in Wonderland<\/em>: Sie verschwindet k\u00f6rperlich nach und nach, bis bloss noch ihr Grinsen \u00fcbrigbleibt. Auch die Tontr\u00e4ger sind k\u00f6rperlich verschwunden. Bloss noch ihre (Phantom-)Funktion als Relevanzzeuge ist geblieben. <br \/><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Kulturelle Freizeitgestaltung findet vermehrt in den eigenen vier W\u00e4nden statt. Junge gehen nicht mehr ins Kino oder ins Konzert, sondern laden sich Filme (und Serien, welche die Funktion eines Leitmediums \u00fcbernehmen) auf ihren Flachbildschirm-TV oder ihren Tablet-PC, sie formen ihren Musikgeschmack immer weniger aktiv mit St\u00f6bern im Plattenladen um die Ecke und dem Besuch von Konzerten, sondern lassen sich vage definiert \u00fcber Stilpr\u00e4ferenzen von Streams berieseln.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die j\u00fcngsten Zahlen der Urheberrechtsgesellschaft Suisa best\u00e4tigen den Trend: 2014 wuchsen die Urheberrechtseinnahmen aus Downloads und Streaming um 32 Prozent. Zum Anstieg beigetragen haben laut der offiziellen Medienmitteilung der Genossenschaft Mehreinnahmen aus dem Tarif f\u00fcr die Verg\u00fctungen auf Smartphones, steigende Einnahmen aus dem Onlinebereich und die starke Verbreitung von digitalem und zeitversetztem Fernsehen (Die Zunahme im Online-Bereich ist allerdings vor allem auf die Zunahme der Lizenzierungsgebiete zur\u00fcckzuf\u00fchren).<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der Megatrend, der hinter diesen Entwicklungen auszumachen ist, heisst Fragmentierung. Die Zersplitterung des Musikmarktes l\u00e4sst sich in zwei Etappen unterteilen. Die erste, die weitgehend abgeschlossen ist, hat dank der Globalisierung zu einer enormen Zunahme der Stil- und Kulturenvielfalt gef\u00fchrt. Gab\u2019s fr\u00fcher hierzulande Klassik, Jazz, Schlager, Volks- und Tanzmusik, sind die Szenen in un\u00fcbersehbare Gruppen und Gr\u00fcppchen zerfallen \u2012 von der Shakuhachi-Musik \u00fcber Gangster-Rap und Tango-Revival bis zu Neuer Musik, Pop aus Island, Ukulele-Orchestern und so weiter und so fort. Hinzu kommt nun noch die Fragmentierung der Vertriebswege und Marketingstrategien.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Was bedeutet das f\u00fcr das Selbstbild der Musikerinnen und Musiker? Im nach wie sp\u00e4tromantisch beeinflussten Europa des 20. Jahrhundert bedeutete der Beruf eine Sonderstellung von gesellschaftlicher Prominenz und spiritueller Autorit\u00e4t. Darauf, dass diese Zeiten vorbei sein d\u00fcrften, werden sich die meisten, die beruflich mt Musik zu tun haben, einstellen m\u00fcssen. Es ist diese soziale Zur\u00fcckstufung die zu schaffen macht, weniger das gef\u00fchlt abnehmende Einkommen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em>von Wolfgang B\u00f6hler<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><em>\u00a0<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><img decoding=\"async\" src=\"images\/kolumnewb.jpg\" border=\"0\" alt=\"Portr\u00e4t Wolfgang B\u00f6hler\" style=\"float: left; margin: 8px;\" \/>29.05.2015 &#8212; In Sachen physische Tontr\u00e4ger mutet die Situation mittlerweile absurd an: Sie haben ihren Ereignischarakter praktisch vollst\u00e4ndig verloren, und Geld l\u00e4sst sich damit keines mehr verdienen. Gl\u00fccklich ist, wer sie einspielen kann, ohne dabei allzu grosse Verluste einzufahren. Dennoch ist die Produktion eines Tontr\u00e4gers f\u00fcr Musiker nach wie vor unverzichtbar, ja wichtiger denn je. Erwartet werden CD von Agenturen und Veranstaltern. K\u00fcnstler und Gruppen, die keine Tontr\u00e4ger und idealerweise Rezensionen dazu vorlegen k\u00f6nnen, werden weniger gebucht. Das Renommee der CD erinnert damit ein wenig an die Grinsekatze in <em>Alice in Wonderland<\/em>: Sie verschwindet k\u00f6rperlich nach und nach, bis bloss noch ihr Grinsen \u00fcbrigbleibt. Auch die Tontr\u00e4ger sind k\u00f6rperlich verschwunden. Bloss noch ihre (Phantom-)Funktion als Relevanzzeuge ist geblieben.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2339","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=2339"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2339\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=2339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=2339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=2339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}