{"id":2434,"date":"2015-07-13T09:24:48","date_gmt":"2015-07-13T09:24:48","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2015\/07\/13\/was-macht-die-musik-in-der-musiktherapie\/"},"modified":"2015-07-13T09:24:48","modified_gmt":"2015-07-13T09:24:48","slug":"was-macht-die-musik-in-der-musiktherapie","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2015\/07\/13\/was-macht-die-musik-in-der-musiktherapie\/","title":{"rendered":"Was macht die Musik in der Musiktherapie?"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong><img loading=\"lazy\" decoding=\"async\" src=\"images\/bilder2015\/150713bellikon.jpg\" border=\"0\" alt=\"\" width=\"520\" height=\"374\" \/><\/strong><\/span><\/p>\n<p style=\"text-align: center;\">\u00a0<span style=\"font-size: x-small;\">Doris M\u00e4der-G\u00fcntner und der Aphasiechor der <span style=\"font-family: arial,helvetica,sans-serif;\">Rehaclinic Baden (Bild: Codex flores)<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>Einmal mehr hat die Rehaklinik Bellikon zu ihrer j\u00e4hrlichen Musiktherapie-Tagung eingeladen. Unter dem Motto \u00abWas macht die Musik in der Musiktherapie?\u00bb reichte die Palette der Beitr\u00e4ge von Aspekten der musikalischen Improvisation \u00fcber Grundsatzfragen der Musikwirkungsforschung bis zu einem \u00fcberaus ber\u00fchrenden Beispiel gelungener Arbeit mit Aphasie-Betroffenen.<\/strong><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">10.07.2015 \u2013 Der in Wien t\u00e4tige Thomas Stegemann erinnerte gleich zum Auftakt daran, dass der Druck auf die Therapeuten, die Wirkung ihre T\u00e4tigkeiten nach den \u00fcblichen Kriterien der Wirksamkeit, Zweckm\u00e4ssigkeit und Wirtschaftlichkeit zu \u00fcberpr\u00fcfen gestiegen ist und dass Hoffnungen bestehen, sich dank neurophysiologischen Methoden dabei ein klareres, empirisch fundiertes Bild von den Effekten der Therapieform zu machen. Er skizzierte die aktuellen Modelle der neuronalen Verarbeitung des Musikh\u00f6rens und \u2011machens und wies auf neuere Untersuchungen hin, die zeigen, dass w\u00e4hrend musikalischen Improvisationen auch Regionen der Sprachverarbeitung im Endhirn aktiviert werden. So glauben etwa Forscher der Johns Hopkins University School of Medicine zeigen zu k\u00f6nnen, dass gemeinsames Musizieren einem sprachlichen Dialog durchaus nicht un\u00e4hnlich ist.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Geht es um die Beziehungen zwischen Musik und Emotion, so steigt zur Zeit die Einsicht, dass es sich dabei um ein komplexes System zahlreicher Komponenten handelt. Sie m\u00f6chte laut Stegemann das Modell einer schwedischen Forschergruppe um Patrik Juslin und Daniel V\u00e4stfj\u00e4ll in den Griff bekommen. Da spielen die Aspekte Hirnstammreflex, Konditionierung, Emotionale Ansteckung, Episodisches Ged\u00e4chtnis, Visuelle Imagination, Musikalische Erwartung und Kognitive Bewertungen eine Rolle. Schliesslich wies Stegemann auch auf j\u00fcngere Einsichten in die Bedeutung der Neuroplastizit\u00e4t hin, die in Therapieprozessen dank Interaktionen und Intersubjektivit\u00e4t \u00fcber rein kognitive oder emotionale Lernvorg\u00e4nge hinausf\u00fchren k\u00f6nnen.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der Schweizer Philosoph und Musiker Wolfgang B\u00f6hler (der Verfasser dieses Berichts), warf einen Blick auf die grossen Wandlungsprozesse, die in der globalen Gemeinschaft der Musiktherapetinnen und \u2011therapeuten zu Zeit zu beobachten sind. Nach einer Periode des zuversichtlichen Aufbruchs \u2012 unter anderem dank der neueren Methoden der Hirnforschung und dem Aufbau wissenschaftlicher Strukturen \u2012 scheint im Moment ein skeptischer Zwischenhalt angesagt zu sein. Dabei beeinflussen auch die zur Zeit laufenden, teils hitzig gef\u00fchrten Grundsatzdiskussionen um den Zustand der wissenschaftlichen Forschung in Psychologie und Sozialwissenschaften die Debatte. Zwar sind in den letzten Jahrzehnten eine F\u00fclle an Daten erhoben worden, allerdings w\u00e4chst die Einsicht, dass diese wenig aussagen, wenn ihre Strukturen nicht vereinheitlicht und mit soliden Rahmentheorien zur Musikwirkung in einen gr\u00f6sseren Zusammenhang gebracht werden k\u00f6nnen. Dass es im Verst\u00e4ndnis der Wirkungen von Musik noch nicht zu echten Durchbr\u00fcchen gekommen ist, ist auch darauf zur\u00fcckzuf\u00fchren, dass erst heute richtig realisiert wird, wie komplex die Zusammenh\u00e4nge sind, aber auch auf noch fehlende Resultate in zudienenden Disziplinen wie Musiktheorie, Neurowissenschaften, Sozialpsychologie und so weiter. Sie erst k\u00f6nnten ein aussagekr\u00e4ftiges Gesamtbild erm\u00f6glichen.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der Pianist und Dozent f\u00fcr Improvisation Christoph Baumann charakterisierte in seinem Referat die Improvisation, die seiner \u00dcberzeugung nach keineswegs ausschliesslich ein spezifisches Kennzeichen des Muszierens ist. Vielmehr durchziehe Improvisation als Prinzip die unterschiedlichsten Lebenswelten. So improvisierten wir im t\u00e4glichen Leben, genauso wie Kinder sich die Welt mit improvisierendem Lernen und Ausprobieren die Welt aneignen, so Baumann. In der westlichen Welt haben zum einen die Verschriftlichung der Musik in der Neuzeit und die damit entstandene Schriftgl\u00e4ubigkeit sowie zum andern die Allgegenw\u00e4rtigkeit von Tonaufnahmen, die aus dem Moment Entstehendes fixieren, dazu gef\u00fchrt, dass der ungezwungene Zugang zum Improvisieren verloren gegangen ist.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">In der Musik verwende man Improvisation einerseits als Mittel zum Zweck, erkl\u00e4rte Baumann weiter, andererseits auch als Kunstform. Als Mittel zum Zeck nutzten wir sie, wenn wir ein komponiertes Musikwerk improvisierend erarbeiten und uns einzelne Stellen und Aspekte so aneignen. Als Kunstform wiederum bilde jedes Improvisationssystem einen eigenen Kanon an (Vermeidungs-)Regeln aus.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">F\u00fcr die Musiktherapie am Interessantesten d\u00fcrfte die freie Improviation sein, der Baumann als Musiker am n\u00e4chsten steht. Es handelt sich dabei um eine in den 1960er-Jahren entstandene, eigenst\u00e4ndige Ausdrucksform, in der sich im Gegensatz zu Komposition die Zeit der Kreation mit der Zeit der Darbietung deckt. Frei Improvisierende k\u00f6nnen nichts zur\u00fccknehmen, sie sind gezwungen, aus allem einmal h\u00f6rbar gewordenen Material etwas zu machen. Kreative \u00abFehler\u00bb k\u00f6nnen dabei ein spannungsausl\u00f6sendes Moment bilden. Baumann sieht Chancen, solcherart Entstehendes als Ausdruck des Unbewussten, als \u00abm\u00f6gliches Dialogsritual\u00bb mit heilender Wirkung\u00a0 zu nutzen. Allerdings, so der Referent, k\u00f6nne die Bewertung so entstehender Klangresultate auch irref\u00fchrend sein, da sie an \u00e4sthetische Maximen gekoppelt sei.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Grunds\u00e4tzliches zur Musiktherapie und ihren historischen Gebundeheiten legte die in Wien und Berlin t\u00e4tige Karin Schumacher dar. Die Deutsche Gesellschaft f\u00fcr Musiktherapie definierte 1973 die Musiktherapie als \u00abAnwendung der Kunst Musik, um therapeutische Ziele zu erreichen\u00bb. Der Musiktherapeut setze dabei Musik und sich selbst ein, um Verhaltens\u00e4nderungen herbeizuf\u00fchren. Schumacher erinnerte an Pioniere wie Schwabe, Schm\u00f6lz, Alvin, Orff, Wilms, Priestley, Benenzon, Nordoff und Robbins sowie Loos und den Schweizer Fritz Hegi. Durch ihre Konzeptionen ziehe sich immer wieder das Motiv der emotionalen Aktivierung oder Regulierung. So zielte etwa in Mary Priestleys Vorstellungen Musik nicht darauf ab, angenehme Erlebnisse zu vermitteln, sondern vielmehr darauf, \u00abBlockierungen zu beseitigen, die einer weiteren Entwicklung entgegenstehen\u00bb, und Katja Loos sah Musik als M\u00f6glichkeit, die \u00ab\u00fcberstrapazierte Rationalit\u00e4t\u00bb zu entlasten und damit die Wahrnehmung von Gef\u00fchlen und eine Ver\u00e4nderung der Erlebnisverarbeitung zu bewirken.<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Die in Baden und Zurzach t\u00e4tige klinische Musiktherapeutin Doris M\u00e4der-G\u00fcntner hatte f\u00fcr ihr Referat gleich einen ganzen Chor mitgebracht, den Aphasiechor der Rehaclinic Baden. M\u00e4der<span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">-G\u00fcntner<\/span> bekr\u00e4ftigte die Einsicht, dass die Verarbeitung von Musik in engem Kontakt zu dem emotionalen Zentrum einer Person steht, das von der modernen Neurologie schwergewichtig im limbischen System lokalisiert wird. Je mehr Aphasie-Betroffene emotional mit einem Lied verbinden, desto besser k\u00f6nnten sie Lieder denn auch lernen. Sprachkompetenzen seien in der linken Hemisph\u00e4re situiert. Diese sei es, die bei Aphasikern gesch\u00e4digt sei. Melodische Strukturen, so M\u00e4der<span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">-G\u00fcntner<\/span>, werden jedoch von der rechten Gehirnh\u00e4lfte verarbeitet. \u00a0Beim Singen von Liedern verb\u00e4nden sich Melodien mit dem dazu geh\u00f6rigen Text. So entstehe \u2012 im Sinne einer netzwerkartigen Aktivierung \u2012 eine Br\u00fccke zwischen Melodien und W\u00f6rtern. Es erstaune immer wieder, wie Aphasiker und Aphasikerinnen deshalb schon fr\u00fch einzelne Vokale, Silben, W\u00f6rter, Refrains oder gar die erste Strophe eines Liedes singen k\u00f6nnten, in der Spontansprache jedoch anst\u00fcnden. F\u00fcr sie bedeute Musik ein K\u00f6nigsweg zum Wiederentdecken ihrer Sprache.<em> (wb)<\/em><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>Info:<\/strong>\u00a0 Villa Boveri, Baden, 12. Juni 2015. <em>Musiktherapie und neurologische Rehabilitation, Was macht die Musik in der Musiktherapie?<\/em> Tagung der Rehaklinik Belikon. \u00a0\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Doris M\u00e4der-G\u00fcntner und der Aphasiechor der Rehaclinic Baden (Bild: Codex flores) \u00a0 Einmal mehr hat die Rehaklinik Bellikon zu ihrer&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2434","post","type-post","status-publish","format-standard","hentry","category-musiktherapie","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=2434"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2434\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=2434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=2434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=2434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}