{"id":2445,"date":"2015-07-20T05:48:07","date_gmt":"2015-07-20T05:48:07","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2015\/07\/20\/tod-des-bassbaritons-franz-ferdinand-nentwig\/"},"modified":"2015-07-20T05:48:07","modified_gmt":"2015-07-20T05:48:07","slug":"tod-des-bassbaritons-franz-ferdinand-nentwig","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2015\/07\/20\/tod-des-bassbaritons-franz-ferdinand-nentwig\/","title":{"rendered":"Tod des Bassbaritons Franz-Ferdinand Nentwig"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">20.07.2015 &#8212; Wie die Staatsoper Hannover schreibt, ist wenige Wochen vor seinem 86. Geburtstag der Bassbariton Franz-Ferdinand Nentwig in seiner Wahlheimat Portugal verstorben. Nentwig geh\u00f6rte vor\u00fcbergehend dem Ensemble der Staatsoper Hannover an.<\/span><\/p>\n<p><strong>20.07.2015 &#8212;<\/strong> <span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"><strong>Wie die Staatsoper Hannover schreibt, ist wenige Wochen vor seinem 86. Geburtstag der Bassbariton Franz-Ferdinand Nentwig in seiner Wahlheimat Portugal verstorben. Nentwig geh\u00f6rte vor\u00fcbergehend dem Ensemble der Staatsoper Hannover an.<\/strong><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">Der 1929 in Duisburg geborene Nentwig liess sich nach Zwischenstationen als Bildhauer und Regieassistent an den Musikhochschulen in Detmold, Hamburg und Essen zum S\u00e4nger ausbilden. 1962 deb\u00fctierte er am Stadttheater Bielefeld, 1963 wechselte er nach Freiburg, 1969 nach Ulm. Verheiratet war er mit der ebenfalls in Hannover engagierten S\u00e4ngerin Elena Dumitrescu-Nentwig.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\"> An der Staatsoper Hannover war er von 1973 bis 1976 fest engagiert, blieb dem Haus aber bis 1983 als Gast verbunden. Er war insbesondere im dramatischen und im Wagner-Fach erfolgreich. Vor allem an der Wiener Staatsoper trat er h\u00e4ufig auf. <em>(cf)<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: small;\">20.07.2015 &#8212; Wie die Staatsoper Hannover schreibt, ist wenige Wochen vor seinem 86. Geburtstag der Bassbariton Franz-Ferdinand Nentwig in seiner Wahlheimat Portugal verstorben. Nentwig geh\u00f6rte vor\u00fcbergehend dem Ensemble der Staatsoper Hannover an.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2445","post","type-post","status-publish","format-standard","hentry","category-nachrichten","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=2445"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/2445\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=2445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=2445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=2445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}