{"id":289,"date":"2014-01-10T21:54:51","date_gmt":"2014-01-10T21:54:51","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/10\/der-nachwuchs-im-opernhaus\/"},"modified":"2014-01-10T21:54:51","modified_gmt":"2014-01-10T21:54:51","slug":"der-nachwuchs-im-opernhaus","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/10\/der-nachwuchs-im-opernhaus\/","title":{"rendered":"Der Nachwuchs im Opernhaus"},"content":{"rendered":"<p>28.11.2005 &#8212; <span class=\"txt-m-black\">Das Publikum von Opern- und Konzerth\u00e4usern wird immer \u00e4lter. Mit gezielten p\u00e4dagogischen Programmen wird deshalb versucht, eine Verj\u00fcngung der Stammkundschaft zu erreichen. Auch das Opernhaus Z\u00fcrich hat mehrere F\u00f6rderprogramme f\u00fcr den Nachwuchs aufgegleist. Im Vordergrund stehen dabei aber nicht Bem\u00fchungen um die Verj\u00fcngung der Zuschauer.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><strong>28.11.2005 &#8212; <span class=\"txt-m-black\">Das Publikum von Opern- und Konzerth\u00e4usern wird immer \u00e4lter. Mit gezielten p\u00e4dagogischen Programmen wird deshalb versucht, eine Verj\u00fcngung der Stammkundschaft zu erreichen. Auch das Opernhaus Z\u00fcrich hat mehrere F\u00f6rderprogramme f\u00fcr den Nachwuchs aufgegleist. Im Vordergrund stehen dabei aber nicht Bem\u00fchungen um die Verj\u00fcngung der Zuschauer.<\/span><\/strong><\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\"><span class=\"txt-m-black\">Mit \u00abOpera viva\u00bb hat das Opernhaus Z\u00fcrich letztes Jahr ein Programm f\u00fcr Kinder ins Leben gerufen. Die Kleinen k\u00f6nnen dabei unter Anleitung erfahrener Opernp\u00e4dagogen die Werke auf einer Studiob\u00fchne selber nachspielen, die im grossen Haus auf dem Spielplan stehen. Ein Schulprojekt wiederum macht Gymnasiasten und Berufssch\u00fcler von Stadt und Kanton mit dem Alltag im Haus und seinen vielf\u00e4ltigen Facetten vertraut und l\u00e4sst sie das Entstehen von Produktionen hautnah miterleben. Last but not least unterh\u00e4lt das Opernhaus seit 1997 eine Orchester-Akademie, die jungen Musikerinnen und Musikern aus der Schweiz und dem Ausland die M\u00f6glichkeit gibt, erste Erfahrungen in einem professionellen Opernorchester zu sammeln. Zu diesen Aktivit\u00e4ten hat sich Codex flores mit dem Dramaturgen Stefan Rissi unterhalten.<\/p>\n<p> <strong>Codex flores:<\/strong> <em>Wie findet der durchschnittliche Besucher eines Opernhauses seinen Weg in eine Vorstellung?<\/em><br \/> <strong>Stefan Rissi:<\/strong> Dies kann auf ganz unterschiedliche Art geschehen. Wer nicht in einer Familie aufw\u00e4chst, in der die Oper bereits eine Rolle spielt, findet in der Regel dank der Schule zu Kontaktm\u00f6glichkeiten, m\u00f6glicherweise zun\u00e4chst nicht einmal freiwillig. Beim einen oder andern springt da der Funke sofort, bei andern ist damit zu rechnen, dass sie nach Besuchen mit einer Schulklasse nicht mehr kommen.<\/p>\n<p><\/span><\/span><\/span><\/p>\n<p> <center>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/><strong>Die Weblinks<\/strong><br \/> Opernhaus Z\u00fcrich:<br \/> <a href=\"http:\/\/www.opernhaus.ch\" target=\"blank\" rel=\"noopener noreferrer\">www.opernhaus.ch<\/a><br \/> Opera Viva:<br \/> <a href=\"http:\/\/www.opernhaus.ch\/d\/spielplan\/operfuerkinder.php\" target=\"blank\" rel=\"noopener noreferrer\">www.opernhaus.ch\/d\/spielplan\/operfuerkinder.php<\/a><br \/> Orchester-Akademie des Opernhauses Z\u00fcrich:<br \/> <a href=\"http:\/\/www.opernhaus.ch\/d\/akademie\/orchesterakademie.php\" target=\"blank\" rel=\"noopener noreferrer\">www.opernhaus.ch\/d\/akademie\/orchesterakademie.php<\/a> <br \/> &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\"><span class=\"txt-m-black\"><br \/> Es kann auch sein, dass die Erfahrung lange Zeit im Unterbewussten schwelt und ein Interesse pl\u00f6tzlich wieder ausbricht. Um einen ersten Kontakt zu schaffen, aus dem die Sch\u00fcler dann selber machen k\u00f6nnen, was sie wollen, nehmen wir gerne einiges auf uns. In die Schulprojekte sind deshalb auch viele Mitarbeitende aus allen Abteilungen einbezogen.<\/p>\n<p> <em>Werden die Sch\u00fcler auch animiert, Vorstellungen von sich aus zu besuchen?<\/em><br \/> Wir haben Sch\u00fcler- und Studententarife und stehen damit im internationalen Vergleich recht gut da. Ein Student kann sich teils schon im Vorverkauf eindecken oder eineinhalb Stunden vor Vorstellungsbeginn mit dem Studentenausweis an die Abendkasse kommen und findet fast immer Einlass \u2013 ausser nat\u00fcrlich an Sonderveranstaltungen oder Auftritten wie demjenigen von Superstars wie Placido Domingo.<\/p>\n<p><\/span><\/span><\/span><\/p>\n<p> <center> <\/p>\n<table>\n<tbody>\n<tr>\n<td><span class=\"txt-s-black\"> <img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/261105oper04.jpg\" border=\"0\" \/> <\/span><\/td>\n<\/tr>\n<tr>\n<td><center><span class=\"txt-s-black\"><strong>Stefan Rissi, Dramaturg.<\/strong><\/span><center><\/center><\/center><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\"><span class=\"txt-m-black\"><\/p>\n<p> Das heisst, man kommt als Student oder Sch\u00fcler mit wenig Geld mit grosser Sicherheit in die Vorstellungen. Man kann sich dazu im Internet informieren. Das Haus ist relativ klein, und man hat auch mit normalen Preisen auf den hinteren R\u00e4ngen eine hervorragende Akustik und eine sehr gute Sicht auf die B\u00fchne.<\/p>\n<p> <em>Dennoch verl\u00e4sst man sich nicht darauf, dass die Jungen die Oper von selber entdecken.<\/em><br \/> Man muss da schon etwas mehr tun, das ist richtig. Unser Intendant Alexander Pereira war der Meinung, dass es nicht gen\u00fcgt, wenn man Gymnasiasten einfach einmal zum Besuch einer Vorstellung einl\u00e4dt. Als \u00f6ffentliche Institution hat das Haus nach der \u00dcberzeugung Pereiras weitergehende Verpflichtungen.<\/p>\n<p> <em>Welche denn?<\/em><br \/> Als Institution, die weitgehend von der \u00f6ffentlichen Hand getragen wird, m\u00fcssen wir auch Bildungs- und Erziehungsaufgaben \u00fcbernehmen, die in Schule und Familie leider immer weniger Raum erhalten. Es geht da in erster Linie darum, \u00fcberhaupt einmal zu zeigen, was Oper ist und was es braucht, um eine solche zu realisieren. Nat\u00fcrlich hoffen wir auch, dass der eine oder die andere zum Schluss kommt, dass da etwas ist, was ihnen etwas zu sagen hat und nicht einfach abgehoben vom Leben ist.<\/p>\n<p> <em>Was bedeutet das konkret?<\/em><br \/> Wir wollen den Jugendlichen zeigen, wie der Alltag einer Opernproduktion aussieht. Wir \u00f6ffnen die Werkst\u00e4tten um zu zeigen, welche Vielfalt an Aufgaben diese erf\u00fcllen. Berufssch\u00fcler erfahren so etwas \u00fcber Berufe, die nur noch in einem Haus wie dem unsrigen gepflegt werden. F\u00fcr die Sch\u00fcler, die zunehmend unter Druck sind, um Lehrstellen zu finden, k\u00f6nnen sich da Optionen ergeben; \u00fcberdies sind wir uns bewusst, dass wir in ein, zwei Jahren da und dort Leute f\u00fcr Spezialberufe suchen werden, die nicht einfach zu finden sind. F\u00fcr die Oper ein neues Publikum zu gewinnen, ist eigentlich ein Nebenaspekt, zumindest in diesen Schulprojekten.<\/p>\n<p> <em>Spontan w\u00fcrde man die Berufssch\u00fcler eher im Hallenstadion vermuten.<\/em><br \/> Das ist ein Vorurteil. Wir wollten die Berufssch\u00fcler einbeziehen ohne eine klare Trennung im Angebot zu machen, obwohl wir den Lehrgang auf die Bed\u00fcrfnisse der einzelnen Schulen abstimmen. Die Sch\u00fcler, gleich welcher Herkunft, erhalten Einf\u00fchrungen ins Werk und besuchen Proben und Vorstellungen.<\/p>\n<p><\/span><\/span><\/span><\/p>\n<table cellpadding=\"4\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/261105oper06.jpg\" border=\"0\" \/><\/td>\n<td align=\"left\" valign=\"bottom\"><span class=\"txt-s-black\"><strong>Die Sch\u00fcler, die den Alltag mit Jazz, Rock und Techno verbringen, verstehen Zusammenh\u00e4nge zwischen Text und Musik in der modernen Oper schnell und intuitiv.<\/strong><br \/><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\"><span class=\"txt-m-black\"><br \/> <em>Wie sind die praktischen Erfahrungen mit dieser Arbeit? Generell gilt ja die Meinung, dass die Jungen heute kaum mehr \u00fcber genug Ausdauer verf\u00fcgen, um so etwas Komplexes wie eine Oper auszusitzen.<\/em><br \/> Auch das ist ein Vorurteil. Unsere Erfahrungen sind im Gegenteil ausgesprochen erfreulich. Die Sch\u00fcler sind offener als viele aus dem \u00e4lteren Stammpublikum. Mit diesem diskutierten wir vor kurzem, was es im Opernhaus sehen und h\u00f6ren m\u00f6chte.<\/p>\n<p> <em>Und welche W\u00fcnsche hat dieses?<\/em><br \/> Es verweigert sich teilweise modernen St\u00fccken wie \u00abDer Herr Nordwind\u00bb des \u00f6sterreichischen Komponisten HK Gruber, das bei uns in der letzten Saison zur Urauff\u00fchrung gekommen ist. Es verlangt nach der melodi\u00f6sen Musik, die es gewohnt ist.<\/p>\n<p> <em>Der Nachwuchs ist da offener?<\/em><br \/> Die Sch\u00fcler, die den Alltag in andern Klangwelten verbringen, im Jazz, Rock, Techno und so weiter, verstehen gewisse Zusammenh\u00e4nge zwischen Text und Musik schneller und intuitiver. Wenn etwa jemand in einer zeitgen\u00f6ssischen Oper am Handy spricht und dazu ganz hohe und schrille T\u00f6ne erklingen, dann verstehen die sofort, was da abl\u00e4uft. Die Musik dient ja dazu, zus\u00e4tzliche Informationen zu transportieren; die Sch\u00fcler sind da sehr wach und vorurteilsfrei.<\/p>\n<p> <em>Sie konfrontieren diese bewusst mit neuen Klangwelten?<\/em><br \/> Aber sicher. Grischa Asagaroff, unser k\u00fcnstlerischer Betriebsdirektor, der auch als Regisseur t\u00e4tig ist, hat dieses Jahr die Oper \u00abHarley\u00bb des britischen Komponisten Edward Rushton zur Urauff\u00fchrung gebracht. Die Arbeiten dazu hat er f\u00fcr die p\u00e4dagogischen Projekte mit den Sch\u00fclern spontan ge\u00f6ffnet. Das macht nicht jeder Regisseur gerne, aber Asagaroff hat sich da sofort reingekniet. Dass das sehr gut ging, war f\u00fcr uns eine freudige \u00dcberraschung.<\/p>\n<p> <em>Was k\u00f6nnten die Gr\u00fcnde daf\u00fcr sein?<\/em><br \/> Zum einen sind die Klassen, die zu uns kommen, von den Lehrern bereits ausgew\u00e4hlt worden. Sie kommen aber immer vollst\u00e4ndig. Es hat sicher in jeder Klasse ein paar Sch\u00fcler, die lieber nicht mitgekommen w\u00e4ren. Sie st\u00f6ren den Betrieb aber nicht. Zum andern bereiten wird die Sch\u00fcler seri\u00f6s vor.<\/p>\n<p> <em>Wie sieht eine solche Vorbereitung konkret aus?<\/em><br \/> Mit \u00abHarley\u00bb haben wir bewusst ein St\u00fcck gew\u00e4hlt, das die Sch\u00fcler unserer \u00dcberzeugung nach ansprechen d\u00fcrfte. Auch oder gerade weil es kein Schulst\u00fcck und auch keine Kinderoper, ja nicht einmal eine Oper f\u00fcr Jugendliche ist. Vor dem ersten Probenbesuch haben wir den Sch\u00fclern eine Einf\u00fchrung gegeben. Da kamen sie in drei Gruppen von vierzig bis neunzig Nasen. Wir haben ihnen erkl\u00e4rt, was Oper ist und ihnen unser Haus vorgestellt.<\/p>\n<p> Obwohl die Arbeit parallel zur \u00abHarley\u00bb-Urauff\u00fchrung sehr kurzfristig angesetzt worden war, haben einige Lehrer mit den Sch\u00fclern ebenfalls gearbeitet; sie haben mit ihnen zum Beispiel das Libretto durchgearbeitet. So hatten wir Klassen, die sehr gut vorbereitet waren.<\/p>\n<p> Gerade f\u00fcr die Vor- und Nachbearbeitung sind wir nat\u00fcrlich auf die Hilfe der Lehrpersonen angewiesen. Und die sind, nach anf\u00e4nglicher Skepsis, begeistert vom Projekt.<\/p>\n<p><\/span><\/span><\/span><\/p>\n<table>\n<tbody>\n<tr>\n<td align=\"right\" valign=\"bottom\" width=\"200\"><span class=\"txt-s-black\"><strong>Man kann generell feststellen, dass die jungen Studierenden heute viel weniger ideologisch ausgerichtet sind.<\/strong><br \/><\/span><\/td>\n<td><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/261105oper05.jpg\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\"><span class=\"txt-m-black\"><br \/> <em>Arbeiten andere Vertreter des Hauses da aktiv mit?<\/em><br \/> Wir sorgten daf\u00fcr, dass neben dem Regisseur auch die Librettistin und der Komponist da waren, um Auskunft zu geben. Da kamen Fragen wie, ob es Vorgaben gebe oder gar eine Zensur oder ob man v\u00f6llig frei sei, wenn man ein Auftragswerk komponiere. Daran hat man gemerkt, dass die Jungendlichen recht gut vorbereitet waren. Auch nach den Proben kamen kritische Bemerkungen, die teils sogar in der Regie ber\u00fccksichtigt wurden. Das war f\u00fcr mich eigentlich das Sch\u00f6nste: die Leute beginnen selbst\u00e4ndig zu denken. Das verstehe ich unter P\u00e4dagogik.<\/p>\n<p> <em>Das ganze Drum und Dran in einem Opernhaus ist f\u00fcr Junge zweifelsohne sehr attraktiv \u2013 solange niemand zu singen beginnt. Wie schafft man es, auch die vielleicht etwas ungewohnte Art mit der Stimme umzugehen, den Sch\u00fclern n\u00e4herzubringen?<\/em><br \/> Wir hatten da auch unsere Bef\u00fcrchtungen. In der Einf\u00fchrung zu \u00abHarley\u00bb haben wir das bewusst thematisiert und mit ablehnenden Reaktionen gerechnet \u2013 mit Befremden und Lachen und so. Es war dann aber sehr erfreulich zu sehen, wie gebannt und neugierig die Sch\u00fcler zuh\u00f6rten, als wir Ihnen zun\u00e4chst einmal Ausschnitte aus einem fr\u00fcheren Werk von Edward Rushton vorspielten.<\/p>\n<p> <em>Die ideologische Entkrampfung, die in den letzten Jahren zu beobachten war, hilft sicher.<\/em><br \/> Man kann generell feststellen, dass die jungen Studierenden heute viel weniger ideologisch ausgerichtet sind. Die Vorstellung, dass Oper etwas f\u00fcr die Elite ist, viel Geld kostet und mit engen Kleidervorschriften verbunden ist, ist aber auch ein Vorurteil. <\/p>\n<p> <em>Pr\u00e4gt dies das Bild der Jugendlichen?<\/em><br \/> Bei den ersten Besuchen der Sch\u00fcler hat man sicherlich eine gewisse Befangenheit feststellen k\u00f6nnen, so als ob sie ein Museum betreten w\u00fcrden. Da geht es sicher lockerer zu und her, wenn man mit der Schulklasse in den Zoo geht. Man kann den Sch\u00fclern aber zeigen, dass wenn man regelm\u00e4ssig in die Oper geht, etwa die vermeintlichen Kleidercodes ihre Bedeutung verlieren.<\/p>\n<p> <em>Repr\u00e4sentationsfunktionen hat das Opernhaus aber sicher noch immer. Gerade im zwinglianischen Z\u00fcrich d\u00fcrfte der gesellschaftliche Druck auf das Opernhaus, eine Rolle f\u00fcr eine Polit- und Wirtschaftselite zu \u00fcbernehmen, m\u00f6glicherweise etwas h\u00f6her sein als an andern Orten.<\/em><br \/> Es gibt sicher eine sehr wichtige Gruppe von Besuchern, die auch zu den Sponsoren geh\u00f6rt und daran interessiert ist, dass gewisse Konventionen nicht allzusehr in Frage gestellt werden. Dieses Anliegen ist auch absolut legitim. Man muss aber auch sagen, dass es von Seiten der Geldgeber keinerlei Bestrebungen gibt, da einen exklusiven Zirkel zu bilden und das Opernleben m\u00f6glichst nicht weiterzuentwickeln. Im Gegenteil: Das sind Leute, die sich f\u00fcr das Prinzip Oper in jeder Hinsicht engagieren.<\/p>\n<p> <em>Sie versuchen also, den verschiedensten Vorstellungen gerecht zu werden?<\/em><br \/> Ein Haus wie das unsere kann es sich nicht leisten, bloss f\u00fcr einen Teil der Gesellschaft da zu sein. Es geh\u00f6rt deshalb erkl\u00e4rtermassen zu unserer Politik, die Grenzen zu \u00f6ffnen \u2013 sowohl altersm\u00e4ssig wie auch gesellschaftlich. <\/p>\n<p><\/span><\/span><\/span><\/p>\n<p> <center> <\/p>\n<table style=\"width: 250px;\">\n<tbody>\n<tr>\n<td><span class=\"txt-s-black\"> <img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/261105oper03.jpg\" border=\"0\" \/> <\/span><\/td>\n<\/tr>\n<tr>\n<td><center><span class=\"txt-s-black\"><strong>Unter Anleitung der Theaterp\u00e4dagogen finden die Kinder mit Leichtigkeit den richtigen Rhythmus.<\/strong><br \/><\/span><\/center><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\"><span class=\"txt-m-black\"><\/p>\n<p> <em>Auch f\u00fcr Familien? Man kann daran zweifeln, dass Kinder von einer \u00abParsifal\u00bb-Vorstellung von Anfang bis Ende gefesselt werden k\u00f6nnten.<\/em><br \/> F\u00fcr die Kleinen haben wir mit der \u00abOpera Viva\u00bb-Reihe seit letztem Jahr ein eigenes Angebot. Die Vorstellungen, in denen die Kinder eine Oper mit Kost\u00fcmen und allem Drum und Dran selber durchspielen, sind bewusst parallel zu den Hauptvorstellungen gelegt, so dass die Eltern die M\u00f6glichkeit haben, die Vorstellung im Grossen Haus zu besuchen, w\u00e4hrend die Kinder auf der Studiob\u00fchne gut aufgehoben sind. Mit \u00abOpera Viva\u00bb wird f\u00fcr wenig Geld \u2013 35 Franken \u2013 sehr viel geboten. Die Kinder erhalten Verpflegung, und mehrere Betreuerinnen und Betreuer stehen ihnen zur Verf\u00fcgung.<\/p>\n<p> <em>Wie ist das Verh\u00e4ltnis zwischen \u00abOpera Viva\u00bb und der Arbeit mit den Sch\u00fcler und Studenten?<\/em><br \/> Es sind verschiedene S\u00e4ulen der Jugenarbeit, die durchaus auch ausbauf\u00e4hig sind. Dazu kommt auch noch die \u00abZauberfl\u00f6te f\u00fcr Kinder\u00bb, die in den letzten 18 Monaten nicht weniger als 35&#8217;000 Kinder gesehen haben. Auch das Repertoire an Kinderfassungen kann noch erweitert werden. <\/p>\n<p> <em>Schl\u00e4gt sich der Erfolg der Kinder- und Jugendarbeit auch in der Struktur des \u00abnormalen\u00bb Publikums nieder?<\/em><br \/> Inzwischen sind 22 Prozent der Besucher im Opernhaus unter 25 Jahre alt. Vor acht Jahren waren das noch 12 Prozent. Es gibt aber sicher ein grosses Potential, das noch nicht ausgesch\u00f6pft ist. Wir hoffen deshalb, dass wir die Jugendarbeit noch deutlich erweitern k\u00f6nnen. Ich pers\u00f6nlich bin auch dabei, die Zusammenarbeit mit der Universit\u00e4t zu intensivieren; hier liegen Potenziale brach.<\/p>\n<p> <em>Kann die scheinbar mangelnde Attraktivit\u00e4t der Oper f\u00fcr Junge auch damit zusammenh\u00e4ngen, dass diese sich an eine Massenmedien-kompatible \u00c4sthetik gew\u00f6hnt haben und die Eigenheiten der Oper deshalb gar nicht mehr wahrzunehmen in der Lage sind?<\/em><br \/> Ein Opernbesuch hat sicher eine besondere Qualit\u00e4t, die sich in den Massenmedien nur sehr unvollkommen erschliesst. Ich sage das im vollen Wissen darum, dass das Z\u00fcrcher Opernhaus auch eine Pionierrolle in Sachen DVD-Produktionen innehat. Die Komplettheit des Mediums, aus T\u00f6nen, Farben, Licht und Bewegung ist etwas ganz Wichtiges.<\/p>\n<p><\/span><\/span><\/span><\/p>\n<table cellpadding=\"4\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/261105oper02.jpg\" border=\"0\" \/><\/td>\n<td align=\"left\" valign=\"bottom\"><span class=\"txt-s-black\"><strong>Die lange, komplizierte und tragische Geschichte rund um einen Inkaprinzen in \u00abLa Forza del Destino\u00bb spielen die Kinder unter kundiger Anleitung aufmerksam nach.<\/strong><br \/><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\"><br \/> Dazu kommen die verschiedenen Formen von Sprachlichkeit, die wir auch mit den \u00dcbertiteln st\u00e4rker r\u00fcberbringen m\u00f6chten. Solche Aspekte entziehen sich der Technisierung. Auch die Fragilit\u00e4t des Momentes spielt eine wichtige Rolle. Das Wissen darum, dass immer etwas schief gehen kann, erzeugt eine ganz eigene Spannung.<\/p>\n<p> <em>Wie sieht die Zukunft der Jugendf\u00f6rderung aus?<\/em><br \/> Im Moment ist die Arbeit im Aufbau, wir wollen sie aber institutionalisieren. Es gibt auch vieles, das man besser machen kann, wir m\u00f6chten vermehrt in die Schulen gehen, mit den Betroffenen sprechen und sie fragen, was ihnen gef\u00e4llt und was nicht. Auch neue, andersgelagerte Projekte sind denkbar. Die Jugendarbeit wird zunehmend wichtig. Da wird einiges an Ressourcen hineinfliessen.<\/p>\n<p> <em>Schaffen Sie auch Partizipationsm\u00f6glichkeiten?<\/em><br \/> Zu Assistenzen und Hospitanzen gibt es immer wieder M\u00f6glichkeiten, das war auch schon immer so. Wir sind f\u00fcr alles offen. Man kann nicht alles machen, aber die Offenheit ist schon da. Ein grosses Anliegen ist uns, dass die Hinf\u00fchrung zur Oper f\u00fcr niemanden an finanziellen Barrieren scheitern soll.<\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>28.11.2005 &#8212; <span class=\"txt-m-black\">Das Publikum von Opern- und Konzerth\u00e4usern wird immer \u00e4lter. Mit gezielten p\u00e4dagogischen Programmen wird deshalb versucht, eine Verj\u00fcngung der Stammkundschaft zu erreichen. Auch das Opernhaus Z\u00fcrich hat mehrere F\u00f6rderprogramme f\u00fcr den Nachwuchs aufgegleist. Im Vordergrund stehen dabei aber nicht Bem\u00fchungen um die Verj\u00fcngung der Zuschauer.<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-289","post","type-post","status-publish","format-standard","hentry","category-musikvermittlung","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=289"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/289\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}