{"id":323,"date":"2014-01-11T08:01:07","date_gmt":"2014-01-11T08:01:07","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/irrige-forschung-falsche-kritiken\/"},"modified":"2014-01-11T08:01:07","modified_gmt":"2014-01-11T08:01:07","slug":"irrige-forschung-falsche-kritiken","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/irrige-forschung-falsche-kritiken\/","title":{"rendered":"Irrige Forschung, falsche Kritiken"},"content":{"rendered":"<p><center><em>Von Wolfgang B\u00f6hler<\/em><\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\">\u00a0<\/span><\/span><\/p>\n<table align=\"left\">\n<tbody>\n<tr>\n<td width=\"70\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/kolumnewb.jpg\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\">10.10.2005 &#8212; Vor einigen Tagen machte eine Meldung die Runde, die sich \u00fcberaus spektakul\u00e4r, ja skandal\u00f6s anh\u00f6rte. Eigentlich d\u00fcrfte sie aber bloss diejenigen erstaunt haben, die mit den Gesetzen des modernen Wissenschaftsbetriebes wenig vertraut sind. Um was geht es? Der Epidemiologe John Ioannidis behauptet in einem Artikel in der \u00abPublic Library of Science\u00bb, dass die statistische Wahrscheinlichkeit f\u00fcr die Richtigkeit einer beliebigen einzelnen wissenschaftlichen Arbeit unter f\u00fcnfzig Prozent liegt. Schuld daran seien zu kleine Samples, ein schlechtes Studiendesign, selektive Auswertungen und so weiter und so fort. Man muss daraus schliessen, dass sogar beinharte Empiriker nicht selten und v\u00f6llig unbewusst das zurechtbiegen, was nicht sein darf, um etwas zu erhalten, was ihren Erwartungen entspricht. Wissenschaftler sind ja schliesslich auch nur Menschen.<\/p>\n<p> Die Behauptung ergibt \u2013 nebenbei bemerkt \u2013 eine h\u00fcbsche Variante des L\u00fcgner-Paradox\u2019. Denn auch die Arbeit von Ioannidis ist ja bloss ein einzelner Beitrag zum Thema. Wenn sie also richtig ist, behauptet sie auch von sich selber, dass sie wohl eher falsch ist \u2013 ein krasser logischer Widerspruch. <\/p>\n<p> Sei\u2019s drum. Wir wollen eigentlich auf etwas anderes hinaus: Jeder seri\u00f6se Wissenschaftler weiss, dass bloss eine F\u00fclle an Belegen sowie von unabh\u00e4ngigen Dritten tats\u00e4chlich reproduzierte Wiederholungen von experimentellen Befunden Anlass bieten k\u00f6nnen, entsprechende Resultate als glaubw\u00fcrdig zu akzeptieren. <\/p>\n<p> Der Befund l\u00e4sst sich auch auf die Kulturberichterstattung im Allgemeinen und Rezensionen in den Feuilletons im Besonderen \u00fcbertragen. Eine einzelne Kritik ist an und f\u00fcr sich wertlos. Erst eine F\u00fclle an Besprechungen \u2013 am besten aus den verschiedensten \u00e4sthetischen und politischen Ecken \u2013 l\u00e4sst ein sprechendes Gesamtbild eines neuen Buches, Musikwerkes, Theaters oder Filmes entstehen. Diese Breite ist jedoch h\u00e4ufig nicht gegeben; sie kommt h\u00f6chstens zustande, wenn es um grosse \u00fcberregionale und glamourf\u00e4hige Events geht, etwa um Opernpremieren des Regietheaters. <\/p>\n<p> Der Kritiker, der weiss, dass er den vermutlich einzigen Text zu einem originellen und einzigartigen, aber m\u00f6glicherweise nicht mehrheitsf\u00e4higen Kulturereignis abliefert, hat da h\u00e4ufig einen frustrierenden Job. Die Erwartungshaltung der K\u00fcnstler, \u00fcber die er schreibt, treibt ihn n\u00e4mlich in der Regel auch in einen logischen Widerspruch: Auf der einen Seite soll dem Besprochenen nicht Unrecht getan werden. Das ungewollte Monopol der Berichterstattung verlangt nach gr\u00f6sstm\u00f6glicher Objektivit\u00e4t. Dennoch soll der Beckmesser \u00abaus dem Bauch heraus\u00bb schreiben, denn jeder sch\u00f6pferische Mensch m\u00f6chte ja schliesslich, dass seine Werke auch emotional etwas ausl\u00f6sen.<\/p>\n<p> Der Engl\u00e4nder nennt dies \u00abdouble bind\u00bb: Sei spontan, aber \u00fcberlege dir gef\u00e4lligst genau, was du dabei machst. Ein \u2013 wie vieles nur unvollkommener \u2013 pragmatischer Ausweg aus dem Dilemma k\u00f6nnte heissen: Sei in der Sache angriffig und streng und wahre den unbedingten Respekt auf der pers\u00f6nlichen Ebene. Leider wird aber allzu oft der umgekehrte Weg begangen: Angriffe werden auf der pers\u00f6nliche Ebene lanciert, und die sachliche Auseinandersetzung findet mit der Schutzbehauptung des \u00abRepektes vor dem Werk\u00bb nicht statt. <\/p>\n<p> Der Grund sind oft nicht eimal Arroganz und H\u00e4me. Fehlende zeitliche Ressourcen erlauben kein differenziertes Urteil \u00fcber ein Werk, und so peppt man den eigenen Text mit pers\u00f6nlichen Sticheleien auf, damit eine Kontroverse \u00fcberhaupt in Gang kommt. Im Interesse eines hochklassigen Kultur- und Wissenschaftslebens sollten solch unlautere Methoden dennoch m\u00f6glichst vermieden werden.<\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p> <center> <\/p>\n<table style=\"width: 420px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Der Wissenschaftstheoretiker und Musikpublizist Wolfgang B\u00f6hler ist Produzent von Worldmusic- und Kammerjazz-Projekten und Chefredaktor des Codex flores Onlinemagazins<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Wolfgang B\u00f6hler \u00a0 10.10.2005 &#8212; Vor einigen Tagen machte eine Meldung die Runde, die sich \u00fcberaus spektakul\u00e4r, ja skandal\u00f6s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-323","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=323"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/323\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}