{"id":369,"date":"2014-01-11T08:36:57","date_gmt":"2014-01-11T08:36:57","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/sommerspiel-iii-musikalische-tiefe\/"},"modified":"2014-01-11T08:36:57","modified_gmt":"2014-01-11T08:36:57","slug":"sommerspiel-iii-musikalische-tiefe","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/sommerspiel-iii-musikalische-tiefe\/","title":{"rendered":"Sommerspiel III: Musikalische Tiefe"},"content":{"rendered":"<p><center><em>Von Wolfgang B\u00f6hler<\/em><\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\">\u00a0<\/span><\/span><\/p>\n<table align=\"left\">\n<tbody>\n<tr>\n<td width=\"70\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/kolumnewb.jpg\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\">03.08.2007 &#8212; Wenn Musik von angeblich ganz besonderem Wert ist, so wird ihr gerne \u00abTiefe\u00bb zugesprochen. Tiefe Musik sch\u00e4tzen dann nur die Kundigen, ganz tiefe Musik bloss noch die, die guten Willens sind, und abgrundtiefe Musik zu verstehen, bleibt schliesslich das hohe Privileg weniger Geweihter. Bachs <em>Kunst der Fuge<\/em> oder Beethovens sp\u00e4te Streichquartette etwa versteht nur, wessen Seele die transzendenten Resonanzkammern eigen sind, die von den Dramen solch existentieller Bekenntniskl\u00e4nge in Schwingung gebracht werden k\u00f6nnen. Nun kann man sich unter einem tiefergelegten VW Golf etwas vorstellen, unter einem Tiefflug oder unter Meerestiefe und meinetwegen auch unter einem tiefen Preis. Musik hat aber kein Chassis, das man absenken k\u00f6nnte, sie d\u00fcst nicht r\u00f6hrend direkt \u00fcber unsere K\u00f6pfe und an ihrem Grund w\u00fchlen auch keine krabbelnden Urviecher Staub auf. Bloss billig sein kann sie auch, die Musik, aber auch das nat\u00fcrlich nur in \u2013 wenig tiefsch\u00fcrfendem \u2013 metaphorischem Sinn.<\/p>\n<p> Das Erleben von Musik als eine Art Akt der Erkenntnis zu verstehen, hat halt eben seine T\u00fccken. Ein Verst\u00e4ndnis der tieferen Wahrheit, welche in der \u00abUniversalsprache der Gef\u00fchle\u00bb zum Ausdruck kommen soll, ist schon nur deshalb nicht m\u00f6glich, weil Musik nichts zum Ausdruck bringt, schon gar nichts Universales und keine Gef\u00fchle (wessen denn auch) und auch keine Wahrheit, erst recht keine tiefere, und es ergo auch nichts zu verstehen gibt. Wohl kann Musik Emotionen wecken, aber das kann auch das erste Gebrabbel eines Kleinkindes \u2013 besonders diejenigen seiner Eltern \u2013, ohne dass es gleich Antworten auf existentielle Fragen liefern w\u00fcrde.<\/p>\n<p> Das Gef\u00fchl, im Erleben von Musik eine tiefe Erfahrung zu machen, gleicht viel eher der \u00dcberzeugung, aus den Sternen den Charakter eines Menschen lesen oder mit farbigen Steinen Energiefelder erzeugen zu k\u00f6nnen. Wer dran glaubt, schw\u00f6rt darauf, dass da tiefe emotionale Schichten angesprochen und jahrtausendealtes mystisches Wissen anger\u00fchrt wird, wer nicht, der sieht bloss Schlafwandler, die ihre Selbstbezogenheit mit Welterkenntnis verwechseln. Und selbst wenn uns Musik im Konzertsaal abgrundtief ersch\u00fcttert, finden wir uns Minuten sp\u00e4ter beim C\u00fcpli, wenn wir es nicht vorziehen, dem Gef\u00fchl wie einer Erleuchtung unter Drogen noch etwas l\u00e4nger nachzusinnen und uns erst dann ans C\u00fcplitrinken zu machen, oder meinetwegen hinters k\u00fchle Bier.<\/p>\n<p> Zu glauben, Musik vermittle <em>per se<\/em> eine Botschaft und erst recht noch eine tiefsinnige, ist gef\u00e4hrlich. Diejenigen, die zu einer solchen \u00dcberzegung neigen, nutzen Musik als eine Art Rohrschach-Klatschbild, zu deren korrekten Deutung einzig sie f\u00e4hig sind. Aufgrund ihrer felsenfesten inneren \u00dcberzeugung, zu den Auserw\u00e4hlten zu geh\u00f6ren, neigen sie zu Erhabenheitsgef\u00fchlen, weshalb es unter sogenannten Musikliebhabern leider eine Menge autorit\u00e4rer Charaktere mit Tendenz zu (in der Regel humorloser) Belehrerei gibt. Und es bleibt eines der grossen Paradoxa des gemeinsamen Musizierens, dass man sich dabei auf geheimnisvolle Weise Eins f\u00fchlt, ohne die W\u00fcnsche, Sehns\u00fcchte, \u00c4ngste und Freuden der Mitmusiker auch nur im geringsten wahrnehmen zu m\u00fcssen. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p> <center> <\/p>\n<table style=\"width: 420px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Der Musikphilosoph Wolfgang B\u00f6hler (M.A.) studierte an der Universit\u00e4t Bern Wissenschaftstheorie, Mathematik und Musikwissenschaft. Er ist Chefredaktor des Codex flores Onlinemagazins.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Wolfgang B\u00f6hler \u00a0 03.08.2007 &#8212; Wenn Musik von angeblich ganz besonderem Wert ist, so wird ihr gerne \u00abTiefe\u00bb zugesprochen.&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-369","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/369\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}