{"id":444,"date":"2014-01-11T10:24:58","date_gmt":"2014-01-11T10:24:58","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/kultur-und-medien-ii-zukunftsmotor-archiv\/"},"modified":"2014-01-11T10:24:58","modified_gmt":"2014-01-11T10:24:58","slug":"kultur-und-medien-ii-zukunftsmotor-archiv","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/kultur-und-medien-ii-zukunftsmotor-archiv\/","title":{"rendered":"Kultur und Medien II: Zukunftsmotor Archiv"},"content":{"rendered":"<p><center><em>Von Wolfgang B\u00f6hler<\/em><\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\">\u00a0<\/span><\/span><\/p>\n<table align=\"left\">\n<tbody>\n<tr>\n<td width=\"70\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/kolumnewb.jpg\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\">23.07.2010 &#8212; Pessimisten bef\u00fcrchten, dass es ernsthafte und hintergr\u00fcndige Kultur in den elektronischen Medien immer schwieriger hat und dass das Internet vor allem zu einer l\u00e4rmigen, aufgeregten und \u00fcberspannten Schwatzbude verkommt. Beides hat oberfl\u00e4chlich betrachtet etwas f\u00fcr sich, ist aber summa summarum falsch. Noch nie war das Kulturangebot in den elektronischen und digitalen Medienkan\u00e4len so breit, hochklassig und anregend.<\/p>\n<p> Wer Zugang zum Digitalfernsehen hat, w\u00e4hlt aus einer F\u00fclle wunderbarer Spartensender wie ZDF Theater, ZDF Festival, BR Alpha, Arte, 3Sat, den gut gemachten Regionalangeboten SWF, NDR und so fort; im Internet lassen sich \u00fcber die Webseiten der Sender praktisch \u00e0 discretion Dokumentationen und Mitschnitte von Kulturereignissen abrufen, \u00fcber Plattformen wie Medici TV kann an Festivals teilgenommen werden.<\/p>\n<p> Dasselbe gilt f\u00fcrs Radio; viele Formate des Schweizer Kultursenders DRS2 k\u00f6nnen zu einem frei w\u00e4hlbaren Termin aufgerufen oder als Audiodatei heruntergeladen werden. Das heisst, der Kulturkonsument wird nicht nur besser bedient, sondern es wird ihm auch wesentlich mehr Autonomie dar\u00fcber zugestanden, wann er welche Angebote nutzen will. Youtube bietet \u00fcberdies eine unglaubliche F\u00fclle an historischen und aktuellen audiovisuellen Zeugnissen. Zahlreiche weitere Webangebote kommen dazu. Kulturinteressierte leben medial gesehen in paradiesischen Zeiten.<\/p>\n<p> Etwas allerdings wird sich mit den neuen Distributionskan\u00e4len dramatisch ver\u00e4ndern (oder es hat sich schon ver\u00e4ndert): Das Zeitalter des linearen Medienkonsums d\u00fcrfte mehr oder weniger vorbei sein. Kulturbeitr\u00e4ge werden viel gezielter genutzt. Und die k\u00f6nnen \u2013 siehe Youtube \u2013 \u00fcber sehr lange Zeit in online einfach zug\u00e4nglichen Archiven gelagert werden. Dies muss auch die Inhalte selber ver\u00e4ndern. <\/p>\n<p> Heute wird erwartet, dass Kulturbeitr\u00e4ge zum Zeitpunkt ihrer Ausstrahlung ein m\u00f6glichst grosses Publikum erreichen \u2013 das Diktat der Einschaltquote gilt auch hier. Dazu m\u00fcssen die Beitr\u00e4ge oberfl\u00e4chlicher, personalisierter und unterhaltender daherkommen, als es ihr Thema m\u00f6glicherweise erfordern w\u00fcrde, weil auch die mediale Laufkundschaft ber\u00fccksichtigt werden muss. Wer hingegen Beitr\u00e4ge gestaltet, die sich \u00fcber eine lange Dauer an Nutzer richten, die zu Themen, an denen sie gerade interessiert sind, Materialien suchen, der muss die Materie fundierter, mehr in die Tiefe lotend und anspruchsvoller gestalten. <\/p>\n<p> Vermutlich m\u00fcssen deshalb k\u00fcnftig zwei Typen von Kulturbeitr\u00e4gen f\u00fcr die elektronischen Medien produziert werden: popul\u00e4re, leichtverdauliche, unterhaltende f\u00fcr die Sendezeiten, in denen das Massenpublikum adressiert wird, und hochkar\u00e4tige, fundierte und anspruchsvolle, die von Beginn weg f\u00fcrs Archiv gedacht sind. Deren Erstausstrahlung kann dann auch zu sp\u00e4ter Nacht- oder gar fr\u00fcher Morgenstunde erfolgen. <\/p>\n<p> Die elektronischen Medien werden damit etwas von ihrer Funktion als B\u00fcndler der Aufmerksamkeit verlieren. Strassenfeger, die Grosseregnisse, die ein Volk oder eine Region auf den Zeitpunkt einer einzelnen Sendung vor dem kollektiven Lagerfeuer vereinen, wird es aber vermutlich so oder so kaum mehr geben. Sie d\u00fcrften sich auf Sport-Ereignisse wie die Fussball-WM oder die Olympischen Spiele beschr\u00e4nken, die senderunabh\u00e4ngig das Masseninteresse synchronisieren. <\/p>\n<p> Was dieses Fehlen von Brennpunkten f\u00fcr die Entwicklung des Kulturlebens und der kulturellen Identit\u00e4t einer Nation bedeutet, scheint noch weitgehend offen. <\/span> <span class=\"txt-m-black\">(<em>cf<\/em>)<\/span><\/p>\n<p> <center> <\/p>\n<table style=\"width: 420px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Der Musikphilosoph Wolfgang B\u00f6hler (M.A.) studierte an der Universit\u00e4t Bern Wissenschaftstheorie, Mathematik und Musikwissenschaft. Er ist Chefredaktor des Codex flores Onlinemagazins.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Wolfgang B\u00f6hler \u00a0 23.07.2010 &#8212; Pessimisten bef\u00fcrchten, dass es ernsthafte und hintergr\u00fcndige Kultur in den elektronischen Medien immer schwieriger&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}