{"id":458,"date":"2014-01-11T11:38:56","date_gmt":"2014-01-11T11:38:56","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/der-aufhaltsame-aufstieg-der-sponsoren\/"},"modified":"2014-01-11T11:38:56","modified_gmt":"2014-01-11T11:38:56","slug":"der-aufhaltsame-aufstieg-der-sponsoren","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/der-aufhaltsame-aufstieg-der-sponsoren\/","title":{"rendered":"Der aufhaltsame Aufstieg der Sponsoren"},"content":{"rendered":"<p><center><em>Von Wolfgang B\u00f6hler<\/em><\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\">\u00a0<\/span><\/span><\/p>\n<table align=\"left\">\n<tbody>\n<tr>\n<td width=\"70\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/kolumnewb.jpg\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\">04.02.2011 &#8212; Die Kommission f\u00fcr Rechtsfragen des St\u00e4nderates hat sich mit der Volksinitiative \u00abF\u00fcr Geldspiele im Dienste des Gemeinwohls\u00bb besch\u00e4ftigt und empfiehlt dem Parlament, einem Gegenentwurf des Bundesrates zu folgen. Vorgeschlagen werden laut offizieller Mitteilung der Bundesversammlung \u00abL\u00f6sungen, um die in den letzten Jahren auf dem Gebiet der Geldspiele zwischen Bund und Kantonen aufgetretenen Kompetenzkonflikte zu regeln\u00bb. Das t\u00f6nt alles ziemlich technisch, und man kann sich fragen, was das mit Kulturf\u00f6rderung zu tun hat. Ziemlich viel. Und es gibt Gr\u00fcnde genug, dar\u00fcber beunruhigt zu sein.<\/p>\n<p> Die Lotteriefonds, um die es da geht, decken die Kulturausgaben in der Schweiz zu fast einem Drittel. Es ist zwar absurd, dass die Finanzierung von Kulturprojekten mit Zockerei von Spiels\u00fcchtigen in Casinos und Sportwetten sichergestellt wird. Aber dass die Art der Alimentierung staatlicher Ausgaben manchmal ziemlich schr\u00e4g anmutet, daran muss man sich in modernen Demokratien gew\u00f6hnen. Schliesslich berappen Nikotins\u00fcchtige ja auch einen Teil der Altersrenten. Und wir wollen jetzt nicht allzusehr graben, um noch schizophrenere Querfinanzierungen freizulegen (etwa in Strassengr\u00e4ben und Bahntrassees&#8230;)<\/p>\n<p> Das System hat allerdings Vorteile: Den Gamblern ist es herzlich egal, welchen Kunst- und Kulturprojekten sie mit jedem Kreuzchen auf dem Totto-Schein auf die Beine helfen. Sie sind in gewisser Hinsicht die im kantischen Sinn am radikalsten interesselosen Kunstm\u00e4zene. Das ist gut und schlecht zugleich: Man kann deshalb n\u00e4mlich auch nicht mit ihrer Solidarit\u00e4t rechnen. Sie werden ihre Spielleidenschaft k\u00fcnftig mehr und mehr in Onlinespielen und ausl\u00e4ndischen Casinos ausleben und damit den Geldfluss f\u00fcr die Kultur mehr und mehr versiegen lassen \u2013 Pipilotti Rist hin, Fischli\/Weiss her. <\/p>\n<p> Und wodurch werden die Ausf\u00e4lle ersetzt? Durch vermehrten R\u00fcckgriff aufs Sponsoring? Sponsoren sind allerdings nicht so interesselos wie Gl\u00fccksspieler. Sie suchen sich die Projekte, die sie unterst\u00fctzen wollen, auch aufgrund von Eigeninteressen und inhaltlicher \u00dcberlegungen aus (sie m\u00fcssen \u00abzu ihnen passen\u00bb).<\/p>\n<p> Solche zu erwartenden Verschiebungen in der Schweizer Kulturfinanzierung besch\u00e4ftigen auch das j\u00e4hrliche Klassentreffen \u00f6ffentlicher und privater Kulturf\u00f6rderer \u2013 das <em>Forum Kultur und \u00d6konomie<\/em> nimmt sich im M\u00e4rz in Neuenburg auch die Rolle der Lotterien in der Kulturf\u00f6rderung der Schweiz zur Brust. Dazu \u00e4ussert sich in einem Referat unter anderem Sabine Pegoraro. Die Basler Regierungsr\u00e4tin ist Pr\u00e4sidentin der Fachdirektorenkonferenz Lotteriemarkt und Lotteriegesetz. Aus den Niederlanden reist gar Tjeerd Veenstra an, der auf europ\u00e4ischer Ebene mit \u00e4hnlichen Aufgaben betraut ist.<\/p>\n<p> Das kommt nicht von ungef\u00e4hr: Die interesselose Kultur-Querfinanzierung durch Lottogelder und andere unkonventionelle Staatsk\u00e4sseli wird mehr und mehr ersetzt durch sogenannte Public Private Partnerships (PPP), oder um es weniger Neudeutsch auszudr\u00fccken, das politisch unkontrollierte Zusammenstrecken der K\u00f6pfe von privaten Interessegruppen und Staatsfunktion\u00e4ren zwecks Verteilung von Geldern an K\u00fcnstler und Kulturschaffende. <\/p>\n<p> Das Sponsoring bestimmt damit mehr und mehr die Agenda der Kulturf\u00f6rderung. Einen gewichtigen Anteil an den Sponsoringaktivit\u00e4ten haben Finanzinstitute und Grosskonzerne. Deren Erwartungen an gesponserte Kulturaktivit\u00e4ten decken sich allerdings nur sehr bedingt mit denjenigen der Gesponserten: Banken wollen Sicherheit, Planbarkeit und messbaren Return on Investment. Kunst will spielen, \u00fcberraschen und scheitern k\u00f6nnen. <\/p>\n<p> Ohne dass eine staatspolitische Grundsatzdiskussion die Regeln bestimmte, wird in (un)heimlicher Art die implizite Steuerung des Kulturlebens von Partikularinteressen eines Teils der Privatindustrie \u00fcbernommen \u2013 nicht zuletzt von den Banken, die als Hochburgen der als Abzocker diskreditierten globalen Finanzexperten-Kaste in Verruf geraten sind.<\/p>\n<p> Abzocker statt Zocker. Was f\u00fcr eine Alternative f\u00fcr die Kulturf\u00f6rderung. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p> <center> <\/p>\n<table style=\"width: 420px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Der Musikphilosoph Wolfgang B\u00f6hler (M.A.) studierte an der Universit\u00e4t Bern Wissenschaftstheorie, Mathematik und Musikwissenschaft. Er ist Chefredaktor des Codex flores Onlinemagazins.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Wolfgang B\u00f6hler \u00a0 04.02.2011 &#8212; Die Kommission f\u00fcr Rechtsfragen des St\u00e4nderates hat sich mit der Volksinitiative \u00abF\u00fcr Geldspiele im&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-458","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=458"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/458\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}