{"id":467,"date":"2014-01-11T11:46:32","date_gmt":"2014-01-11T11:46:32","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/wieviel-geld-braucht-die-kulturfoerderung\/"},"modified":"2014-01-11T11:46:32","modified_gmt":"2014-01-11T11:46:32","slug":"wieviel-geld-braucht-die-kulturfoerderung","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/wieviel-geld-braucht-die-kulturfoerderung\/","title":{"rendered":"Wieviel Geld braucht die Kulturf\u00f6rderung?"},"content":{"rendered":"<p><center><em>Von Wolfgang B\u00f6hler<\/em><\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\">\u00a0<\/span><\/span><\/p>\n<table align=\"left\">\n<tbody>\n<tr>\n<td width=\"70\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/kolumnewb.jpg\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\">03.06.2011 &#8212; In den letzten Jahren hat sich bei uns ein Verdacht verdichtet, um es mal etwas kalauernd auszudr\u00fccken, aber mit durchaus ernstem Hintergrund: Die Kulturf\u00f6rderung wird von der Politik am immer k\u00fcrzeren G\u00e4ngelband gef\u00fchrt, und es wird von ihr immer dringlicher verlangt, dass sie sich mit Rentabilit\u00e4t rechtfertigt: Kultur muss sich lohnen, Kunst, die edle, ach so zweckfreie, muss etwas bringen! (Was auch immer&#8230;) Demgegen\u00fcber hat sich in der Wirtschaft, in der angeblich knallhart auf Gewinne gewettet wird, die Einsicht durchgesetzt, dass Ausgaben in Forschung und Entwicklung von Produkten der eigentliche Motor einer gesunden Unternehmensentwicklung sind \u2013 und dass dabei <em>verliert, wer Milchb\u00fcchleinrechnungen macht<\/em>.<\/p>\n<p> Mit andern Worten: die Kunst der verschwenderischen F\u00fclle an Ressourcen f\u00fcr kreative Ideen und die Bereitschaft, Geld, manchmal viel Geld, mal einfach so auf Zusehen hin in die Entwicklung von Produkten zu stecken, die m\u00f6glicherweise oder sogar sehrwahrscheinlicherweise nie auf den Markt kommen, beherrschen heute die grossen Konzerne, wohingegen die Kulturf\u00f6rderung mehr und mehr von kleingeistigen Controllern, Rappenspaltern und \u00abGeiz ist geil\u00bb-Apologeten mit dem Esprit von Fausts Sch\u00fcler Wagner (Sie wissen schon: was man Schwarz auf Weiss etc&#8230;) gekn\u00fcttelt wird. <\/p>\n<p> Die eindeutig unverd\u00e4chtige Deutsche Bank liefert dazu die Zahlen: Wie gross ist der Anteil der Aufwendungen f\u00fcr Forschung und Entwicklung (F&amp;E) am Gesamtbudget in grossen Unternehmen? Bei einem Umsatz von 30,8 Milliarden Euro hatte die Pharmafirma Roche 2009 etwa ein F&amp;E-Budget von 6,4 Milliarden Euro, das sind 20 (!) Prozent. Bei Nokia waren es knapp 10 Prozent, bei Microsoft 15 Prozent, bei einem traditionellen Autobauer wie Volkswagen immerhin auch noch rund 5 Prozent. Die durchschnittliche F&amp;E-Intensit\u00e4t (F&amp;E-Ausgaben im Verh\u00e4ltnis zum Umsatz) der von der Deutschen Bank betrachteten b\u00f6rsenkotierten Unternehmen betrug 2009 3,7 Prozent. <\/p>\n<p> Man kann Kunst und Kultur als die F&amp;E-Abteilung eines Landes betrachten (der Vergleich ist zugegebenermassen etwas schief, aber nichtsdestotrotz erhellend). An das Geld, das in der Wirtschaft f\u00fcr Innovation ausgegeben wird, kommen die entsprechenden Aufwendungen nicht ann\u00e4hernd heran: Der Anteil der Kulturausgaben am Geamtbudget des Bundes bel\u00e4uft sich in der Schweiz zur Zeit auf rund 0,4 Prozent. Kantone schaffen\u2019s (mit Kulturf\u00f6rdergesetzen wie im Aargau) bis auf 1 Prozent. Mit leicht n\u00e4selnder Stimme w\u00fcrde der unvergleichliche Volksschauspieler Theo Lingen da wohl seufzen: Traurig, traurig, traurig. <\/p>\n<p> Das Benchmarking m\u00fcsste vor allem denen zu denken geben, die Staaten in einer reduzierten \u00f6konomischen Sichtweise als Unternehmen betrachten. Sie erwarten von ihnen betriebswirtschaftliches Verhalten. Ja, dann stocken wir mal das Kulturbudget auf \u2013 mindestens um das Neunfache, um nur mal den Durchschnittswert der F&amp;E-Ausgaben eines modernen Unternehmens zu erreichen. <\/p>\n<p> Die Moral von der Geschicht&#8216;? In den grossen, gnadenlos auf Gewinn getrimmten Unternehmen findet man heute mehr Offenheit, <em>Free Spirit<\/em>, Wissen um die Bedeutung grossz\u00fcgiger Alimentierung auch scheinbar verr\u00fcckter Ideen und Zukunftsoptimismus als in der staatlichen Kulturf\u00f6rderung, die per se davon ausgeht, dass sie in die Kunst investiertes Geld \u00e0 fonds perdu verteilt. Irgendetwas l\u00e4uft da schief. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p> <center> <\/p>\n<table style=\"width: 420px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Der Musikphilosoph Wolfgang B\u00f6hler (M.A.) studierte an der Universit\u00e4t Bern Wissenschaftstheorie, Mathematik und Musikwissenschaft. Er ist Chefredaktor des Codex flores Onlinemagazins.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Wolfgang B\u00f6hler \u00a0 03.06.2011 &#8212; In den letzten Jahren hat sich bei uns ein Verdacht verdichtet, um es mal&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-467","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=467"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/467\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}