{"id":504,"date":"2014-01-11T12:06:18","date_gmt":"2014-01-11T12:06:18","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/darf-information-etwas-kosten\/"},"modified":"2014-01-11T12:06:18","modified_gmt":"2014-01-11T12:06:18","slug":"darf-information-etwas-kosten","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/darf-information-etwas-kosten\/","title":{"rendered":"Darf Information etwas kosten?"},"content":{"rendered":"<p><center><em>Von Wolfgang B\u00f6hler<\/em><\/center> <\/p>\n<p><span class=\"txt-m-black\"><span class=\"txt-m-black\">\u00a0<\/span><\/span><\/p>\n<table align=\"left\">\n<tbody>\n<tr>\n<td width=\"70\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/kolumnewb.jpg\" border=\"0\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span class=\"txt-m-black\">30.11.2012 &#8212; Die traditionellen Verleger l\u00e4uten zur Zeit eine weitere Runde in der Auseinandersetzung um eine Schl\u00fcsselfrage der modernen Medien ein: Gleicht Information eher dem Wasser, das als frei verf\u00fcgbares \u00f6ffentliches Gut verstanden wird, oder eher der Elektrizit\u00e4t, f\u00fcr die wir je nach bezogener Menge etwas bezahlen m\u00fcssen? (Beim Wasser ist die Sache etwas komplexer, weil wir im Grunde genommen daf\u00fcr auch bezahlen, aber wir vernachl\u00e4ssigen das mal \u2013 um der Pointe willen). Da wird dann das \u00fcbliche Klagelied angestimmt: Journalistische Inhalte, die aufwendig und kostspielig erstellt werden m\u00fcssen, w\u00fcrden im Netz gratis zur Verf\u00fcgung gestellt, der Nutzer habe sich daran gew\u00f6hnt, und verstehe nun nicht, weshalb er daf\u00fcr bezahlen solle. <\/p>\n<p> In Tat und Wahrheit sind die Dinge etwas komplizierter, denn andere \u2013 gemeinschaftlich finanzierte \u2013 Inhaltsangebote sind heute in einfacher Weise frei verf\u00fcgbar, die schon immer frei zug\u00e4nglich waren. Der einfachere Zugriff auf diese, der ihre Nutzung radikal ver\u00e4ndert hat, tr\u00e4gt dazu bei, Informationen eher Wasser-Eigenschaften zuzuschreiben. Der Zugriff via Internet hat ihre Reichweite dramatisch vergr\u00f6ssert und den Aufwand, sie zu nutzen, nicht minder dramatisch gesenkt. Dies gilt vor allem f\u00fcr die Best\u00e4nde \u00f6ffentlicher Bibliotheken, Archive, \u00f6ffentlicher Forschungsinstitutionen und nicht gewinnorientierter Stiftungen. <\/p>\n<p> Auf was da alles zugegriffen werden kann, demonstriert die soeben als Beta-Version aufgeschaltete Deutsche Digitale Bibliothek (DDB, <a href=\"http:\/\/www.deutsche-digitale-bibliothek.de\" target=\"blank\" rel=\"noopener noreferrer\">www.deutsche-digitale-bibliothek.de <\/a>). Da sich musikalische Inhalte (Aufnahmen, Noten, kritische Berichte, und so weiter) einfach digitalisieren lassen, wird der Zugriff auf Manuskripte, historische Audiodokumente und weiteres hochgradig demokratisiert. Das ver\u00e4ndert nicht nur das musikwissenschaftliche Arbeiten.<\/p>\n<p> \u00abZiel der DDB\u00bb, erkl\u00e4rt Hermann Parzinger, Pr\u00e4sident der Stiftung Preussischer Kulturbesitz und Sprecher des Vorstands des Kompetenznetzwerks der DDB, in einer Medienmitteilung, \u00abist es, jedermann \u00fcber das Internet freien Zugang zum kulturellen und wissenschaftlichen Erbe Deutschlands zu er\u00f6ffnen, also zu Millionen von B\u00fcchern, Archivalien, Denkm\u00e4lern, Bildern, Skulpturen, Musikst\u00fccken und anderen Tondokumenten, Filmen und Noten\u00bb. <\/p>\n<p> Man muss dabei auch in noch gr\u00f6sseren Dimensionen denken, denn die DDB soll Teil des europ\u00e4ischen Kulturportals Europeana werden. Hinter der Europeana stehe die \u00dcberzeugung, dass freier, demokratischer Zugriff auf das kulturelle Erbe f\u00fcr alle gew\u00e4hrleistet sein m\u00fcsse, um die mit der Digitalisierung verbundenen Chancen f\u00fcr die gesellschaftliche Entwicklung nutzen zu k\u00f6nnen, zitiert die Mitteilung Jill Cousins, die Gesch\u00e4ftsf\u00fchrerin der entsprechenden Tr\u00e4gerstiftung. <\/p>\n<p> Hinzu kommen Initiativen wie die zahllosen Wikis, die Lexikonwissen gratis distribuieren, oder Angebote wie die Petrucci-Bibliothek, die Notenmaterial, deren Urheberschutz abgelaufen ist, frei zur Verf\u00fcgung stellen.<\/p>\n<p> Damit haben wir ein Problem: Wenn der Staat und nicht gewinnorientierte Organisationen hochwertige Information frei zur Verf\u00fcgung stellt (was gut und richtig ist), private Medienunternehmen aber nicht, dann d\u00fcrfte der B\u00fcrger, respektive Konsument dies als Ungleichgewicht empfinden. Ist Information nun eben etwas, was frei und unentgeltlich zur Verf\u00fcgung stehen soll, oder ist ihre Nutzung das Privileg der Hablichen, die daf\u00fcr (teuer) bezahlen k\u00f6nnen und wollen? <\/p>\n<p> Wir haben f\u00fcr das Dilemma auch keine L\u00f6sung, sind aber \u00fcberzeugt davon, dass sich das Problem der Gesch\u00e4ftsmodelle traditioneller Verlage nur aus einer Gesamtschau aller Informationsquellen und -anbieter l\u00f6sen l\u00e4sst. Ein \u00abAlleingang\u00bb der Anbieter journalistischer Inhalte scheint zum Scheitern verurteilt. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p> <center> <\/p>\n<table style=\"width: 420px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Der Musikphilosoph Wolfgang B\u00f6hler (M.A.) studierte an der Universit\u00e4t Bern Wissenschaftstheorie, Mathematik und Musikwissenschaft. Er ist Chefredaktor des Codex flores Onlinemagazins.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Wolfgang B\u00f6hler \u00a0 30.11.2012 &#8212; Die traditionellen Verleger l\u00e4uten zur Zeit eine weitere Runde in der Auseinandersetzung um eine&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-504","post","type-post","status-publish","format-standard","hentry","category-editorials","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=504"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/504\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}