{"id":576,"date":"2014-01-11T15:07:28","date_gmt":"2014-01-11T15:07:28","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/rough-guide-jazz\/"},"modified":"2014-01-11T15:07:28","modified_gmt":"2014-01-11T15:07:28","slug":"rough-guide-jazz","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/rough-guide-jazz\/","title":{"rendered":"Rough Guide Jazz"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/jazz290205.jpg\" border=\"0\" align=\"left\" \/>05.03.2005 &#8212; Ein Jahrhundert Jazz auf 800 Seiten: Wer nennt die Namen, z\u00e4hlt die Stile in der Entwicklung des Jazz von den einfachen harmonischen Ger\u00fcsten und klaren Strukturen der Anf\u00e4nge (New Orleans, Chicago, Dixieland) \u00fcber die formbildenden Innovationen der Zwanziger- und Dreissigerjahre, die Komplexit\u00e4t des Bebop und Post-Bop der Vierziger- und F\u00fcnfzigerjahre, die Abstraktion der Sechziger- und die Jazz-Rock-Fusion der Siebzigerjahre bis zum heutigen Pluralismus der Weltsprache Jazz? <\/p>\n<p> Drei Praktiker, Ian Carr, Gr\u00fcnder und Trompeter der Jazz-Rock-Band Nucleus und u.a. Verfasser einer vielger\u00fchmten Miles-Davis-Biographie, der Trompeter Digby Fairweather und der Pianist Brian Priestley, beide bekannte Rundfunkmitarbeiter, sowie neun weitere Autoren unternahmen es, F\u00fclle und Vielfalt des Jazz in Einzelportr\u00e4ts von Musikern zu konzentrieren; den renommierten Rough Guide Jazz haben sie nun f\u00fcr dessen 2. Auflage aktualisiert und erweitert. <\/p>\n<p> In \u00fcber 1800 alphabetisch geordneten Personenartikeln von A (Ahmed Abdul-Malik) bis Z (Axel Zwingenberger) werden die massgeblichen Erneuerer und f\u00fchrenden Musikerinnen und Musiker aus allen Kontinenten portr\u00e4tiert und in ihren Leistungen (weder undifferenziert noch unkritisch) gew\u00fcrdigt \u2013 breiter und vertiefend abgehandelt sind der Werdegang und der Einfluss legend\u00e4rer Revolution\u00e4re des Jazz. In den Personenartikeln werden auch die Teilnahme an wichtigen Einspielungen und Orchestern, Bands bzw. Gruppen genannt (die Formationen lassen sich mangels Register allerdings nicht nachschlagen). Den Beitr\u00e4gen angef\u00fcgt sind Auswahl-Diskografien mit Kurzcharakterisierungen von \u00fcber 3000 ausgew\u00e4hlten Alben (CD, fallweise aber auch LP). <\/p>\n<p> Der Hauptakzent liegt zahlenm\u00e4ssig auf Musikern und Musikerinnen aus den USA, doch f\u00e4llt die intensive Ber\u00fccksichtigung von Pers\u00f6nlichkeiten anderer L\u00e4nder auf. Hervorzuheben ist zudem, dass die Autoren, deren Beitr\u00e4ge durch Schwarz-Weiss-Abbildungen von Plattenh\u00fcllen und Portr\u00e4tfotos bereichert sind, nicht nur die Instrumentalsolisten an der Rampe, Altmeister und Jungstars, sondern auch Sidemen, Vokalistinnen und Vokalisten, Begleiter und Arrangeure w\u00fcrdigen. Ein Glossar kl\u00e4rt eine knapp gefasste Auswahl wichtiger musikalischer Fachbegriffe und Stilrichtungen des Jazz. <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Ian Carr\/Digby Fairweather\/Brian Priestley: Rough Guide Jazz. 2., erweiterte und aktualisierte Auflage. Mit 300 Schwarz-weiss-Abbildungen. Verlag J. B. Metzler, Stuttgart 2004. 805 Seiten. \u20ac 29,95. Fr. 48.-.<\/p>\n<p> <a href=\"http:\/\/www.amazon.de\/exec\/obidos\/ASIN\/1843532565\/codexflores-21\">Bei Amazon kaufen<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>05.03.2005 &#8212; Ein Jahrhundert Jazz auf 800 Seiten: Wer nennt die Namen, z\u00e4hlt die Stile in der Entwicklung des Jazz&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-576","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=576"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/576\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}