{"id":628,"date":"2014-01-11T20:46:58","date_gmt":"2014-01-11T20:46:58","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/kevin-bazzanas-gould-biografie\/"},"modified":"2014-01-11T20:46:58","modified_gmt":"2014-01-11T20:46:58","slug":"kevin-bazzanas-gould-biografie","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/kevin-bazzanas-gould-biografie\/","title":{"rendered":"Kevin Bazzanas Gould-Biografie"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2007\/070108gould.jpg\" border=\"0\" align=\"left\" \/>08.01.2007 &#8212; Glenn Gould ist so etwas wie der Archetypus des genialischen Sonderlings unter den Interpreten des 20. Jahrhunderts. Dass dies kein Zufall ist, zeigt Kevin Bazzanas akribische, detail- und anekdotenreiche Biografie \u00fcber den kanadischen Pianisten, die nun in der von Isabell Lorenz sorgf\u00e4ltig erstellten deutschen \u00dcbersetzung vorliegt. Sie best\u00e4tigt auf wundersame Weise j\u00fcngere Erkenntnisse zu den physiologischen Eigenheiten speziell kreativer Menschen, wie sie von der Psychologin Shelley Carson letztes Jahr pr\u00e4sentiert worden sind: In einem vielbeachteten Artikel im Journal of Personality and Social Psychology (<a href=\"http:\/\/212.60.37.143\/rezensionen_ind2.php?art=336#lit\">*<\/a>) vermutet Carson, dass eine reduzierte F\u00e4higkeit, wichtige und weniger wichtige Reize im Hirn zu filtern, bedeutende Faktoren individueller Kreativit\u00e4t bilden \u2013 samt der damit verbundenen st\u00e4ndigen geistigen (\u00dcber-)erregung. Und wie charakterisiert Bazzana Goulds Pers\u00f6nlichkeit? \u00abAls er acht war, gingen seine Eltern mit ihm ins Kino, in \u201aShea\u2019s Hippodrome\u2019 lief Walt Disneys \u201aFantasia\u2019, und er konnte diese \u201aentsetzliche Farborgie\u2019 nicht ausstehen, wie er sich noch Jahre sp\u00e4ter erinnerte. \u201aGanz deprimiert ging ich nach Hause, mir war leicht schwindlig, und zum ersten Mal im Leben hatte ich Kopfschmerzen, an die ich mich noch erinnern kann.\u2019\u00bb (33)<\/p>\n<p> Goulds Abneigung gegen alles, was die Reiz\u00fcberflutung bef\u00f6rdert, scheint da nur folgerichtig: \u00ab&#8230;alles S\u00fcdliche und Mediterrane war ihm ein Gr\u00e4uel: Sonnenschein, blauer Himmel, kr\u00e4ftig gew\u00fcrztes Essen, k\u00f6rperliche Anstrengung, leichtlebige Sinnlichkeit, emotionale Offenheit, italienische Oper. Er verabscheute leuchtende Farben und setzte Rot mit Gewalt gleich.\u00bb (33) Eine solche st\u00e4ndige Gefahr der Sinnesinflation f\u00fchrt dazu, dass sich Betroffene weit mehr mit sich selber besch\u00e4ftigen m\u00fcssen als der Durchschnittsmensch. Sie zeigen dadurch in ihrem Sozialverhalten h\u00e4ufig eine retardierte Entwicklung und schaffen es \u2013 wie im Falle Goulds \u2013 in liebevoller, aber im Grunde genommen verst\u00e4ndnisloser Umgebung dennoch nicht wirklich, ein ausgeglichenes und gesundes Selbstbild aufzubauen.<\/p>\n<p> Bazzana zeichnet auf differenzierte Weise genau dieses Bild von Gould als liebensw\u00fcrdigem, selbstbezogenem Nonkonformisten, dem die F\u00e4higkeit weitgehend abgeht, seine Mitmenschen und seine Wirkung auf diese ad\u00e4quat wahrzunehmen. Als medikamentens\u00fcchtiger Hypochonder scheint er sich \u00fcberdies st\u00e4ndig kurz vor einer Dissoziation des eigenen Ichs zu befinden. Akribisch erz\u00e4hlt das Buch etwa die Geschehnisse rund um eine \u00fcberraschende, spontan gemeinte freundschaftliche Ber\u00fchrung Goulds durch einen Steinway-Mitarbeiter, dem endlose Auseinandersetzungen um eine angebliche Schulterverletzung folgten (160). Es pr\u00e4sentiert auch amour\u00f6se Korrespondenzen (281), die vermuten lassen, dass Gould in seinem erotischen Verh\u00e4ltnis zu Frauen nie \u00fcber pubert\u00e4re Verwicklungen hinausgekommen ist oder auch sonst eine auffallende zwischenmenschliche Unreife zeigte. Wie ein Pubertierender verhielt sich Gold etwa auch, wenn er sich gegen\u00fcber Freunden im Publikum seiner Auftritte befangen f\u00fchlte. Er ging dabei so weit, darauf zu bestehen, dass die Sekret\u00e4rin seines Konzertagenten Walter Homburger \u00abtats\u00e4chlich (auf seine Kosten) <em>die Stadt verliess<\/em>, wenn f\u00fcr ihn mehrere Konzerte anstanden.\u00bb (150)<\/p>\n<p> In dieses Bild passt, dass auch Goulds Humor oft zum Selbstl\u00e4ufer geworden zu sein scheint und sein Auditorium zeitweise ratlos liess, selbst wenn er in lichten Momenten wirklich umwerfend witzig sein konnte \u2013 etwa wenn er in der parodistischen Rolle des deutschen Avantgarde-Komponisten Karlheinz Klopweisser die \u00abResonanz der Stille\u00bb beschw\u00f6rte, die als <em>deutsche<\/em> Stille \u00abnat\u00fcrlich organisch ist im Gegensatz zur franz\u00f6sischen Stille, die ornamental ist\u00bb (318) oder wenn er von Horowitz, den er \u00fcberhaupt nicht mochte, behauptete, dessen ber\u00fchmte Oktaventechnik sei \u00abbloss vorget\u00e4uscht\u00bb (87). <\/p>\n<p> \u00dcber alldies und vieles mehr berichtet die hervorragende und gerade wegen ihres n\u00fcchternen Blickes ungew\u00f6hnlich scharfsinnige Biografie, so auch \u00fcber das kleinb\u00fcrgerliche Toronto der dreissiger Jahre, von dem sich der Pianist zeitlebens nicht zu befreien vermochte, und \u00fcber zahlreiche Details seiner interpretatorischer Ideen. Es erz\u00e4hlt aber auch von Goulds teils spektakul\u00e4rer Virtuosit\u00e4t beim Schneiden von Tonaufnahmen oder dem Erfinden innovativer, in der Art kontrapunktischer Musik komponierter Radiosendungen, die in einer subversiven Parodie auf die R\u00fcckkehr von Horowitz aufs Konzertpodium gipfeln. In \u00abGlenn Goulds hysterische R\u00fcckkehr\u00bb tritt er \u00abmit dem Aklavik Philharmonic Orchestra auf einer Bohrinsel mitten im arktischen Ozean auf (&#8230;) W\u00e4hrend seiner Zugabe verursacht die Nachricht eines neuen \u00d6lfundes einen Massenexodus unter seinem Publikum (&#8230;) Als seine Zugabe zu Ende geht, steht Gould allein auf der Bohrinsel in dem heulenden Wind und verbeugt sich unter dem einsamen Gebell eines einsamen Seehundes\u00bb (333). Irgendwie bleibt einem ob dieses Sinnbildes von Goulds eigenem K\u00fcnstlertum das Lachen im Halse stecken.<\/p>\n<p> Dem Buch beigegeben ist eine CD mit einer Einspielung von Kompositionen Goulds (seine eigene Transkription von Wagners Siegfried-Idyll, f\u00fcnf kleine St\u00fccke aus dem Jahr 1950 und zwei St\u00fccke aus den Jahren 1951\/52 in dodekaphonischem Stil, eine Sonata f\u00fcr Klavier sowie ein absolut abenteuerlicher Vortrag \u00fcber Bach, den Gould auf Deutsch \u2013 das er selber nicht beherrscht oder versteht \u2013 radebrecht). Die Klavierst\u00fccke spielt der estnische Nachwuchspianist Vestard Shimkus.<\/p>\n<p> <span class=\"txt-s-black\">(<a name=\"lit\"><\/a>*) Shelley H. Carson; Jordan B. Peterson,; Daniel M. Higgins: \u00abDecreased Latent Inhibition Is Associated With Increased Creative Achievement in High-Functioning Individuals\u00bb, Journal of Personality and Social Psychology. 85(3), Sep 2003, <a href=\"http:\/\/content.apa.org\/journals\/psp\/85\/3\/499\">499-506<\/a><\/span> <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Kevin Bazzana: <em>Glenn Gould<\/em>, aus dem Englischen von Isabell Lorenz, 2006 Schott Music Mainz, 432 Seiten + 1 CD, ca. 25 \u20ac <a href=\"http:\/\/www.amazon.de\/gp\/product\/3795705703?ie=UTF8&amp;tag=codexflores-21&amp;linkCode=as2&amp;camp=1638&amp;creative=6742&amp;creativeASIN=3795705703\">bei Amazon kaufen<\/a><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.assoc-amazon.de\/e\/ir?t=codexflores-21&amp;l=as2&amp;o=3&amp;a=3795705703\" border=\"0\" alt=\"\" width=\"1\" height=\"1\" style=\"border: none !important; margin: 0px !important;\" \/> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>08.01.2007 &#8212; Glenn Gould ist so etwas wie der Archetypus des genialischen Sonderlings unter den Interpreten des 20. Jahrhunderts. Dass&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-628","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/628\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}