{"id":652,"date":"2014-01-11T21:00:22","date_gmt":"2014-01-11T21:00:22","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/haydns-londoner-symphonien\/"},"modified":"2014-01-11T21:00:22","modified_gmt":"2014-01-11T21:00:22","slug":"haydns-londoner-symphonien","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/haydns-londoner-symphonien\/","title":{"rendered":"Haydns Londoner Symphonien"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2007\/haydn191107.jpg\" border=\"0\" align=\"left\" \/>10.12.2007 &#8212; 59-j\u00e4hrig war Joseph Haydn, als er, eingeladen vom Geiger und Konzertmanager Johann Peter Salomon und verlockt durch die Aussicht auf erkleckliche Honorare, seine erste Reise nach London antrat. Dem England-Aufenthalt von 1791\/1792 folgte ein zweiter 1794\/1795. Unter den Hunderten von Werken, die Haydn dort komponierte (\u00fcber 3000 Notenseiten soll er geschrieben haben), finden sich die zw\u00f6lf sogenannten Londoner Sinfonien (Hob.I: 93 bis 104), die allesamt in der Metropole des Britischen Imperiums uraufgef\u00fchrt wurden. <\/p>\n<p> Im Auftrag des Bayerischen Rundfunks hat dessen Musikredakteurin Renate Ulm den Londoner Sinfonien, deren Entstehung, Deutung und Wirkung einen Band gewidmet. F\u00fcnfzehn Autorinnen und Autoren (Regina Back, Vera Baur, Alexandra Maria Dielitz, Christine Fischer, J\u00f6rg Handstein, R\u00fcdiger Heinze, Alexander Heinzel, Claudia Maria Knispel, Armin Raab, Nicole Restle, Susanne Schmerda, Doris Sennefelder, Wolfgang St\u00e4hr, Renate Ulm, Egon Voss) verfassten die Kapitel, was inhaltlich zu einigen Redundanzen f\u00fchrt, die allerdings nicht ins Gewicht fallen, da die Beitr\u00e4ge in beliebiger Reihenfolge gelesen werden k\u00f6nnen. <\/p>\n<p> Die klare inhaltliche Gliederung ergibt sich durch das Dutzend Werkbetrachtungen. An deren Anfang werden die betreffenden technischen Daten aufgef\u00fchrt: Entstehungszeit, Urauff\u00fchrung, Besetzung und Satzbezeichnungen. Individuell und durchwegs verst\u00e4ndlich sind die Beschreibungen und Analysen der Sinfonien. Auf Notenbeispiele wurde verzichtet (hilfreich zumindest w\u00e4ren die Incipits der S\u00e4tze); die Hinweise auf Taktnummern beziehen sich auf die Neue Gesamtausgabe, die vom Joseph-Haydn-Institut in K\u00f6ln herausgegeben wird (und \u00fcber die wohl die wenigsten verf\u00fcgen). Einige zeitgen\u00f6ssische Dokumente, die im Zusammenhang mit der besprochenen Sinfonie stehen, beschliessen die Werkbetrachtung. <\/p>\n<p> Jeder Einzelw\u00fcrdigung folgt ein Essay. Das auf Haydn bezogene Themenspektrum ist ebenso vielf\u00e4ltig wie anregend und unterhaltsam \u2013 beispielsweise Haydn und die Frauen, seine Londoner Notizb\u00fccher, der Impresario Salomon, das Konzertleben in London, das Reisen um 1800, Haydn und Mozart und Beethoven, ein Charakterbild Haydns, der Witz an seiner Musik, Haydn-Rezeption im Wandel der Zeit. Den Abschluss jedes Beitrags markiert eine von einer einf\u00fchlsamen Besprechung begleitete Portr\u00e4tabbildung Haydns, darunter dessen Totenmaske. <\/p>\n<p> Zwei einleitende Beitr\u00e4ge stellen gr\u00f6ssere Zusammenh\u00e4nge her: biografische Notizen zu Haydn und die Londoner Sinfonien im \u00dcberblick. Alles in allem f\u00fchrt der Band \u00fcber den grossartigen Werkkorpus hinaus zu einer klarsichtigen Ann\u00e4herung an Haydns Pers\u00f6nlichkeit und Leistung. <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Renate Ulm (Hrsg.): Haydns Londoner Symphonien. Entstehung \u2013 Deutung \u2013 Wirkung. Mit 13 Abbildungen. Gemeinschaftsausgabe B\u00e4renreiter-Verlag, Kassel \/ Deutscher Taschenbuch Verlag, M\u00fcnchen 2007. 244 Seiten. \u20ac 14,50. Fr. 25.20.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>10.12.2007 &#8212; 59-j\u00e4hrig war Joseph Haydn, als er, eingeladen vom Geiger und Konzertmanager Johann Peter Salomon und verlockt durch die&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-652","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=652"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/652\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}