{"id":661,"date":"2014-01-11T21:06:54","date_gmt":"2014-01-11T21:06:54","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/bachs-klavier-und-orgelwerke-das-handbuch\/"},"modified":"2014-01-11T21:06:54","modified_gmt":"2014-01-11T21:06:54","slug":"bachs-klavier-und-orgelwerke-das-handbuch","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/bachs-klavier-und-orgelwerke-das-handbuch\/","title":{"rendered":"Bachs Klavier- und Orgelwerke. Das Handbuch"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2008\/bach1_18508.jpg\" border=\"0\" align=\"left\" \/>21.05.2008 &#8212; Was einst selbstverst\u00e4ndlich war, ist es heute nicht mehr: die getrennte Erforschung der Klaviermusik und der Orgelwerke Johann Sebastian Bachs. Durchgesetzt hat sich die Erkenntnis, dass Bachs Kompositionen f\u00fcr Tasteninstrumente ein Ganzes bilden, dass er in allen zeitgen\u00f6ssischen Gattungen und Formen (ausgenommen die Suite) Werke schrieb, die sich \u2013 mit oder ohne Pedal \u2013 sowohl auf der Orgel wie auf Saitenklavieren spielen lassen. <\/p>\n<p> Der im Rahmen des siebenb\u00e4ndigen Bach-Handbuchs im Laaber-Verlag erschienene Band 4 ist nun die erste umfassende Publikation, die Bachs Schaffen f\u00fcr Tasteninstrumente \u2013 also f\u00fcr Orgel, Cembalo, Spinett, Clavichord, Pedalclavichord (ein Kapitel ist auch den Werken f\u00fcr Lauteninstrumente gewidmet) \u2013 vereint bespricht und nicht zuletzt aus dieser Perspektive neue Einsichten gewinnt. Dementsprechend aussagekr\u00e4ftig werden die Bezeichnungen pedaliter (mit Pedal) und manualiter (ohne Pedal). <\/p>\n<p> Zusammengefunden zur Realisierung dieses Grossunternehmens in Sachen Bach haben sich unter der Leitung von Siegbert Rampe (der auch f\u00fcr einen erklecklichen Teil als Verfasser zeichnet) weitere 14 Autoren. So imposant der Umfang des Opus \u2013 \u00fcber 1100 Seiten, gegliedert in die Teilb\u00e4nde I und II \u2013, so beeindruckend der Inhalt. <\/p>\n<p> Er bietet, Bachs Biografie folgend, einen Gesamt\u00fcberblick \u00fcber das Korpus seiner Tastenmusik in ihren Gattungen, Formen und Funktionen von den ersten erhaltenen Pr\u00e4ludien, Fantasien und Fugen des jungen Komponisten bis zu den letzten Sch\u00f6pfungen des Meisters, dem Musikalischen Opfer, den Sch\u00fcbler-Chor\u00e4len, der Kunst der Fuge. <\/p>\n<p> Einer der Akzente liegt in der Analyse vieler Kompositionen. Herausgeber Siegbert Rampe (Musikwissenschaftler und Professor f\u00fcr Cembalo, Orgel und Hammerklavier) unterstreicht im Vorwort, dass der Band \u00abf\u00fcr Bachs Tastenmusik ein St\u00fcck weit aufzuholen versucht, was nach dem Zweiten Weltkrieg [\u2026] meist auf wenige Einzelstudien beschr\u00e4nkt geblieben ist: ein Verst\u00e4ndnis von Bachs Intentionen als Komponist, der konstruktiven Bestandteile seiner Musik und deren historische Einordnung in die Geschichte der Gattungen. Es geht darum, Bach nicht prim\u00e4r als \u00fcberragendes Universalgenie zu begreifen, sondern seine Kunst aus seinem musikalischen Alltag und Umfeld heraus als mitteldeutscher Organist, Kapellmeister, Kantor und Lehrer zu erkl\u00e4ren.\u00bb <\/p>\n<p> Zur Werkanalyse und -einordnung, die sich auch auf bisher als zweifelhaft oder unecht eingestufte Kompositionen erstreckt und in manchen F\u00e4llen mit neuen Einsichten aufwartet, gesellt sich der sozialgeschichtliche Aspekt mit Erkenntnissen zu Musik und Instrumenten, werden die Funktion des einzelnen Werkkomplexes und die konkreten Umst\u00e4nde jener Epoche (wirtschaftliche und soziale Bedingungen, Musikhandwerk, Berufs- und Laienmusiker, Unterrichtsliteratur, Auftraggeber, Verlage) untersucht. <\/p>\n<p> <img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2008\/bach2_18508.jpg\" border=\"0\" align=\"left\" \/>Das Handbuch geht nicht nur auf Anspr\u00fcche von Musikwissenschaftlern und Musikliebhabern ein, ohne allerdings vertieftes Fachwissen vorauszusetzen, sondern bietet auch dem Musikpraktiker, sei er Cembalist, Organist oder Pianist, mancherlei fundierte Anregung. Grundlage bei Besprechung und Analyse ist die Neue Bach-Ausgabe NBA, weshalb auf Notenbeispiele weitgehend verzichtet worden ist. <\/p>\n<p> Sowohl im Einf\u00fchrungsteil wie in einzelnen Kapiteln finden sich Erkenntnisse zur Auff\u00fchrungspraxis der Bach-Zeit. Zudem befassen sich einige Beitr\u00e4ge mit grundlegenden Parametern des Vortrags (Takt und Tempo, Artikulationsprobleme, Ornamentik); thematische Schwerpunktthemen gehen ein auf Instrumentenkunde (Geschichte und Bauweise von Saitenklavieren und Orgel), auf die Orgelregistrierung und die Bachsche Temperatur. Selbstredend sind diese Einsichten und Anregungen auch ergiebig f\u00fcr Interpreten der Musik (nicht allein jener f\u00fcr Tasteninstrumente) von Zeitgenossen Bachs. <\/p>\n<p> Im Mittelpunkt stehen die Werke, doch die damit zusammenh\u00e4ngenden Themenkomplexe greifen weit aus. Einige Stichworte: Entstehungsgeschichte, autographe \u00dcberlieferung, Original und Bearbeitung, Revisionsg\u00e4nge, quellenkritische Untersuchungen, Fragen der Echtheitskritik, Probleme der Zuschreibung, Vertrauensw\u00fcrdigkeit von Sammelhandschriften, Musikalienherstellung und -publikation, Musikpraxis im Gottesdienst, Zweige der Bach-Forschung, Bach-Rezeption im 19. und 20. Jahrhundert. <\/p>\n<p> Die F\u00fclle des Materials zu Bach, seinem Lebens- und Arbeitsumfeld, seiner Tastenmusik und zu den zeitgen\u00f6ssischen Bedingungen ist klar gegliedert und sprachlich eloquent formuliert. Zum Thema Sorgfalt geh\u00f6rt inhaltlich, dass den erw\u00e4hnten Komponisten die Lebensdaten durchwegs beigegeben und dass Verweise nicht im \u00dcbermass eingesetzt wurden. Bez\u00fcglich Layout \u00fcberzeugen der angenehm grosse Schriftgrad, die praktische Platzierung der Anmerkungen in der inneren Marginalspalte und die informative Auswahl der Illustrationen. <\/p>\n<p> Erste Orientierung verschafft das detaillierte Inhaltsverzeichnis, in dem sich in der Marginalspalte die entsprechenden BWV-Nummern finden. Gezielten Zugriff erlauben das Register der erw\u00e4hnten Kompositionen Bachs nach dem BWV und das Personenregister. Das Werkverzeichnis im Anhang listet die im Band vorkommenden Werke auf; die Titel sind erg\u00e4nzt mit den Bezeichnungen manualiter bzw. pedaliter. Zudem aufgef\u00fchrt sind die Fundstellen der Werke in der NBA und in deren Kritischen Berichten. Bestandteil des Anhangs ist auch das umfangreiche Literaturverzeichnis (Quellen, Sekund\u00e4rliteratur, Notenausgaben). <\/p>\n<p> Der Band, der alle relevanten Aspekte des \u0152uvres in seinem Kontext ber\u00fccksichtigt, widerspiegelt den aktuellen Stand der Forschung samt offenen Fragen und vereint die Qualit\u00e4ten eines musik- und kulturgeschichtlichen Lesebuchs mit jenen eines anregenden Studienbuchs und \u2013 nicht zuletzt \u2013 eines ergiebigen Nachschlage- und grundlegenden Referenzwerks. <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Siegbert Rampe (Hrsg.): Bachs Klavier- und Orgelwerke. Das Handbuch. Mit Geleitworten von Ton Koopman und Gustav Leonhardt. 2 B\u00e4nde (Band 4, Teilb\u00e4nde 1 und 2, des Bach-Handbuchs in 7 B\u00e4nden), zusammen 1127 Seiten mit 42 Abbildungen und 41 Notenbeispielen sowie einem Werkverzeichnis. Laaber-Verlag, Laaber 2007. \u20ac 168,\u2013. Fr. 284.\u2013.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>21.05.2008 &#8212; Was einst selbstverst\u00e4ndlich war, ist es heute nicht mehr: die getrennte Erforschung der Klaviermusik und der Orgelwerke Johann&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-661","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=661"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/661\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}