{"id":671,"date":"2014-01-11T21:12:01","date_gmt":"2014-01-11T21:12:01","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/musik-konzepte-frederick-delius\/"},"modified":"2014-01-11T21:12:01","modified_gmt":"2014-01-11T21:12:01","slug":"musik-konzepte-frederick-delius","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/11\/musik-konzepte-frederick-delius\/","title":{"rendered":"Musik-Konzepte: Frederick Delius"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2008\/muskon171008.jpg\" border=\"0\" align=\"left\" \/>17.10.2008 &#8212; Was l\u00f6st sich aus der Erinnerung, wenn der Name Frederick Delius f\u00e4llt? Wer nennt seine Opern (darunter \u00abA Village Romeo and Juliet\u00bb nach Gottfried Kellers Novelle), wer seine Orchester- und Chorwerke, seine Konzerte, die Lieder, die Kammer- und Klaviermusik? <\/p>\n<p> 1899 erst wagte der 37-J\u00e4hrige den offiziellen Schritt in die \u00d6ffentlichkeit. Sein Handwerk hatte er in Florida erworben (wo er als Besitzer einer Orangenplantage kl\u00e4glich in Konkurs ging), dann vertieft am Leipziger Konservatorium. In Edward Grieg fand er einen F\u00f6rderer, in dessen Schaffen und in jenem von Wagner und Debussy Vorbilder. Delius liess sich in Paris nieder, wo er sich mit Paul Gauguin, August Strindberg und Edvard Munch befreundete. 1903 heiratete er die deutsche Malerin Helena \u00abJelka\u00bb Rosen, zog 1897 mit ihr nach Grez-sur-Loing, einem Ort s\u00fcdlich von Paris. Dort wohnte er mit Ausnahme der Jahre 1914 und 1915, die er in England, Norwegen und D\u00e4nemark verbrachte, bis zu seinem Tod. <\/p>\n<p> In den Zehner- und Zwanzigerjahren des letzten Jahrhunderts galt Delius (1862 als Fritz Theodor Albert Delius, Spross einer alten deutschen Kaufmannsfamilie aus Bielefeld, in Bradford, Yorkshire, geboren) in Deutschland als einer der Meister seines Fachs. Bald sank sein Renommee auf dem Kontinent, w\u00e4hrend sein Ruhm in England nicht zuletzt dank dem 1909 begonnenen nachhaltigen Einsatz des Dirigenten Thomas Beecham stieg und anhielt. <\/p>\n<p> 1895 hatte sich Frederick Delius mit Syphilis angesteckt, und nach und nach schwand seine Gesundheit \u2013 Mitte der Zwanzigerjahre war er gel\u00e4hmt und erblindet, brachte Kompositionen mit Hilfe seiner Gattin und seines Assistenten Eric Fenby aufs Papier. 1929 wurde er in London mit einem grossen Festival unter Beechams Leitung geehrt. 1934, im Alter von 72 Jahren, starb Frederick Delius; ein Jahr sp\u00e4ter wurde sein Sarg auf den Friedhof von Limpsfield, Surrey, \u00fcbergef\u00fchrt. <\/p>\n<p> W\u00e4hrend Delius in seiner Heimat als Nationalkomponist eine feste Gr\u00f6sse geblieben ist, setzt sich im deutschsprachigen Raum erst in j\u00fcngerer Zeit eine neue Generation von Musikwissenschaftlern und Interpreten mit dem Schaffen Delius\u2019 auseinander, verh\u00e4rtete Klischees aufbrechend. Nach Jahrzehnten liegt nun in deutscher Sprache wieder eine Publikation \u00fcber Delius vor mit Untersuchungen von acht Autoren und zwei Autorinnen. <\/p>\n<p> \u00abDem Band geht es nicht um die Rehabilitierung eines angeblich verkannten Genies, geschweige denn um den Versuch, den Heroen der Musikgeschichte mit Delius einen sogenannten ,Kleinmeister\u2019 an die Seite zu stellen\u00bb, h\u00e4lt Herausgeber Ulrich Tadday im Vorwort fest. \u00abVielmehr ist die Absicht, den Blick auf die Musikgeschichte, die auch im 19. und 20. Jahrhundert nicht allein in Deutschland geschrieben wurde, zu \u00f6ffnen und zwar aus einem gegenw\u00e4rtigen \u00e4sthetischen Interesse heraus, das sich der musikgeschichtlichen Pluralit\u00e4t der europ\u00e4ischen Moderne verpflichtet f\u00fchlt und kritische Fragen an das ambivalente \u0152uvre eines Komponisten stellt, der in Deutschland zwar nicht unbekannt, doch viel zu wenig bekannt ist.\u00bb <\/p>\n<p> Die zehn Beitr\u00e4ge richten den Blick zum einen auf gr\u00f6ssere Zusammenh\u00e4nge (James Deaville: Delius in der deutschsprachigen Rezeption. Rebekka Sandmeier: Delius und das Englische in der Musik. Julian Johnson: Natur bei Delius. Guido Heldt: Delius und die Idee einer Vokalmusik ohne Worte. Andreas Dorschel: Von Nietzsches zu Delius\u2019 Zarathustra. Eric Saylor: Delius und die Texte Walt Witmans), widmen sich zum andern einzelnen Kompositionen bzw. Gattungen (Arne Stollberg: Wahrnehmung, Bild und Klang in \u00abIn a Summer Garden\u00bb. Peter Revers: \u00abParis. The Song of a great City\u00bb. Barbara Eichner: \u00abA Village Romeo and Juliet\u00bb. Anthony Gritten: Delius\u2019 Konzerte). <\/p>\n<p> Die einzelnen Aspekte, illustriert durch Notenbeispiele, tabellarische Aufstellungen und einige Abbildungen, f\u00fcgen sich zu einem farben- und kontrastreichen Mosaik der Pers\u00f6nlichkeit, der k\u00fcnstlerischen Intentionen und des umfangreichen Schaffens von Frederick Delius und \u00f6ffnen Zug\u00e4nge zu Charakteristiken seines Werks. <\/p>\n<p> Der Anhang enth\u00e4lt, wie \u00fcblich in den Musik-Konzepte-B\u00e4nden, Abstracts, bibliografische Hinweise, Zeittafel und Kurzportr\u00e4ts der Autorinnen und Autoren. <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Frederick Delius. Reihe Musik-Konzepte, Band 141\/142. Neue Folge, herausgegeben von Ulrich Tadday. VII\/2008, edition text + kritik im Richard Boorberg Verlag, M\u00fcnchen. 207 Seiten mit Abbildungen und Notenbeispielen. \u20ac 26,00. Fr. 39.30.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>17.10.2008 &#8212; Was l\u00f6st sich aus der Erinnerung, wenn der Name Frederick Delius f\u00e4llt? Wer nennt seine Opern (darunter \u00abA&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-671","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=671"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/671\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}