{"id":711,"date":"2014-01-12T09:11:15","date_gmt":"2014-01-12T09:11:15","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/werkeinfuehrung-vivaldis-le-quattro-stagioni\/"},"modified":"2014-01-12T09:11:15","modified_gmt":"2014-01-12T09:11:15","slug":"werkeinfuehrung-vivaldis-le-quattro-stagioni","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/werkeinfuehrung-vivaldis-le-quattro-stagioni\/","title":{"rendered":"Werkeinf\u00fchrung: Vivaldis \u00abLe Quattro Stagioni\u00bb"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2010\/viv12510.jpg\" border=\"0\" align=\"left\" \/>14.05.2010 &#8212; \u00abQuattro Stagioni\u00bb: Nicht die gleichnamige Pizza soll hier interessieren, sondern das wohl popul\u00e4rste aller weltweit verbreiteten Werke aus dem Musikland Italien. Antonio Vivaldis \u00abVier Jahreszeiten\u00bb, die vier Concerti f\u00fcr Violine, Streicher und Basso continuo, 1725 in Amsterdam publiziert, sind die einzigen unter seinen etwa 30 mit Programmtiteln versehenen Instrumentalwerken, denen der Komponist konkrete aussermusikalische Inhalte in Form von Sonetten mitgegeben hat. Die Gedichte, im Druck dem einzelnen Konzert vorangestellt, sind zeilenweise an entsprechenden Stellen auch in die Partitur einger\u00fcckt, um den Bezug zwischen Text und Musik zu pr\u00e4zisieren. <\/p>\n<p> So eing\u00e4ngig, sinnlich, farben- und formenreich die Natur- und Seelenbilder der \u00abVier Jahreszeiten\u00bb auch sind, so komplex ist ihre Faktur, kunstvoll gestaltet in der Gesamtheit wie im Detail. Wer den Zyklus, wer Vivaldis Werkstatt mit Ausdauer und kritischem Geist erkunden will, dem ist Bernhard Moosbauer, Musikwissenschaftler, Dozent und Interpret auf Barock-Streichinstrumenten, ein kenntnisreicher Fachmann und anregender Vermittler. <\/p>\n<p> F\u00fcr sein im Rahmen der B\u00e4renreiter Werkeinf\u00fchrungen erschienenes Taschenbuch hat er einleitend die wichtigsten Daten und Fakten aufbereitet zur historischen Situation und zum Musikleben in Venedig zur Zeit Vivaldis, die Biografie des \u00abprete rosso\u00bb (1678 Venedig \u2013 1741 Wien) und sein k\u00fcnstlerisches Selbstverst\u00e4ndnis umrissen. <\/p>\n<p> Mit den Kapiteln \u00fcber die Jahreszeiten in Kunst und Musik und \u00fcber Vivaldis kompositorische Vorgaben und Planungen zu seinem Opus 8 (\u00abIl Cimento dell\u2019Armonia e dell\u2019Inventione\u00bb, der Sammlung von 12 Concerti) leitet Moosbauer \u00fcber zur detaillierten Erforschung der \u00abQuattro Stagioni\u00bb-Konzerte. <\/p>\n<p> Die Besprechung der Bauprinzipien und Strukturen, des Ausdrucksgehalts und Klangcharakters der Werke wird eingeleitet durch das jeweilige Sonett (im Original und in deutscher \u00dcbersetzung). An Gr\u00fcndlichkeit und Sorgfalt sind Moosbauers engmaschige, mit Notenbeispielen und Tonartdispositionen untermauerte Analysen (jedes Konzert beansprucht zwischen 16 und 19 Druckseiten) wohl kaum zu \u00fcbertreffen \u2013 wer in der Musiktheorie weniger heimisch ist, wird da ein Gef\u00fchl der \u00dcberforderung nicht unterdr\u00fccken k\u00f6nnen. Doch regelm\u00e4ssig weitet der Autor das Spektrum vom Einzelnen zum Umfassenden und zieht das Fazit seiner Erkenntnisse am Schluss jedes Teils. <\/p>\n<p> Den Ausklang dieses Studienbuchs bilden Informationen \u00fcber Selbstzitate aus den \u00abVier Jahreszeiten\u00bb-Konzerten, Zitate, die Vivaldi \u00fcberwiegend in B\u00fchnenwerken einsetzte, ferner die Rezeptionsgeschichte des Zyklus im 18. Jahrhundert und \u00dcberlegungen zum exemplarischen Charakter der \u00abQuattro Stagioni\u00bb. Im Anhang finden sich u. a. Hinweise zu Editionen und zur Literatur. <\/p>\n<p> <strong><em>Zitat aus dem Buch: <\/em><\/strong><br \/> \u00abF\u00fcr die Opernkomposition war eine reichhaltige musikalische Fantasie selbstverst\u00e4ndlich und zudem eine hohe Sensibilit\u00e4t, was die vielf\u00e4ltige Darstellung von Affekten und Naturereignissen betraf. Vivaldi \u00fcbertrug das Prinzip der Darstellung von Vorg\u00e4ngen der inneren und \u00e4u\u00dferen Natur der Oper konsequent auf die Instrumentalmusik, speziell auf seine Konzertkomposition. So erweckte er die Neugierde des Publikums, handelte es sich doch um eine Neuheit im Musikbetrieb Italiens. [\u2026] Die das Gewohnte \u00fcberschreitende Art der Affektdarstellung in der Instrumentalmusik d\u00fcrfte ihre Wirkung nicht verfehlt haben, denn &#8218;die Musik wirkte m\u00e4chtig auf die weichen sensitiven Seelen. Zeitgenossen berichten, h\u00e4ufig seien Frauen beim Anh\u00f6ren [\u2026] in Thr\u00e4nen und Schluchzen ausgebrochen und in Verz\u00fcckungen geraten&#8216;.\u00bb (Seite 54) <br \/> <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Bernhard Moosbauer: Antonio Vivaldi \u2013 Die Vier Jahreszeiten. B\u00e4renreiter Werkeinf\u00fchrungen. Mit Abbildungen und Notenbeispielen. B\u00e4renreiter-Verlag, Kassel 2010. 158 Seiten. \u20ac 14,95. Fr. 26.90. <\/p>\n<p> siehe auch: <br \/> <a href=\"http:\/\/www.codexflores.ch\/rezensionen_ind2.php?art=431\">Peter Ryoms Vivaldi Werkverzeichnis (RV)<\/a><br \/> <a href=\"http:\/\/www.codexflores.ch\/rezensionen_ind2.php?art=499\">Alle Blockfl\u00f6tenkonzerte Vivaldis<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>14.05.2010 &#8212; \u00abQuattro Stagioni\u00bb: Nicht die gleichnamige Pizza soll hier interessieren, sondern das wohl popul\u00e4rste aller weltweit verbreiteten Werke aus&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-711","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=711"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/711\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}