{"id":719,"date":"2014-01-12T09:15:33","date_gmt":"2014-01-12T09:15:33","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/wienerlieder\/"},"modified":"2014-01-12T09:15:33","modified_gmt":"2014-01-12T09:15:33","slug":"wienerlieder","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/wienerlieder\/","title":{"rendered":"Wienerlieder"},"content":{"rendered":"<p><span class=\"txt-m-black\"> <img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2010\/wienlied251010.jpg\" border=\"0\" align=\"left\" \/>01.11.2010 &#8212; \u00abAllweil lustig, fesch und munter, \/ Denn der Weaner geht net unter.\u00bb (Refrain eines Wienerlieds, anonym, 1880) Der Wiener in seinem \u00abanzigen, goldenen Wean\u00bb hat\u2019s anscheinend seit alters gern fr\u00f6hlich und weinselig, wobei Lustigkeit, Hamur (Humor) und Ironie die Spannung zwischen tr\u00fcbem Alltag und unausweichlichem Hinschied \u00fcberw\u00f6lbt. Von selbst versteht sich da, dass die Heimatstadt am blauen Donaustrom ein gm\u00fcatliches Schuckkasterl ist, gar ein St\u00fcckerl vom Paradies sein muss, \u00ab\u2026a Sternderl vom Himmel, \/ Das nur vom Herrgott kann sein\u00bb.<\/p>\n<p> Ein deutscher Professor, der in M\u00fcnster (Westfalen) lehrende Literaturwissenschaftler J\u00fcrgen Hein, hat seine innige Beziehung zum Wienerischen in Publikationen \u00fcber Raimund, Nestroy und das Wiener Volkstheater bewiesen. Nun liegt auch seine vor acht Jahren erstmals publizierte Sammlung von Wienerliedern in festem Einband wieder vor. <\/p>\n<p> Aus den auf \u00fcber zehntausend gesch\u00e4tzten Donaumetropole-Liedern hat Hein 64 \u00abKlassiker\u00bb ausgew\u00e4hlt, chronologisch geordnet von \u00abEi, du lieber Augustin\u00bb (1679) bis zu Peter Wehle, Gerhard Bronner, Georg Kreisler, Hans Weigel und Andr\u00e9 Heller. Den Texten beigef\u00fcgt sind, wo bekannt, Autor und Komponist samt ihren Lebensdaten. <\/p>\n<p> Da wogen Gef\u00fchle durcheinander, werden Erinnerungen beschworen an die goldene Zeit, an Grinzing, Sievering, den Kahlenberg, den Prater und den Steffel (den Stefansdom), an Walzer von Strau\u00df und Lanner, den Heurigen, das Flascherl Wein samt R\u00e4uscherl, die Schrammeln und die Fiaka, den bl\u00fchenden Flieder, die s\u00fcssen Madeln und die alten S\u00fcnder, an G\u2019m\u00fcatlichkeit und Weana Schm\u00e4h. <\/p>\n<p> Im Zusammenklang formt sich ein bewegtes buntes Potpourri wienerischer Befindlichkeiten, Psychogramme von Originalen mit Wurzeln in der goldenen Zeit der Monarchie, den Sinnen in der Gegenwart und der festen Hoffnung, dass in Zukunft alleweil alles bleibt, wie\u2019s war und ist. <\/p>\n<p> Mit kenntnisreichem Nachwort zu Herkunft und Wesen des Wienerlieds, mit aktualisierten Literaturhinweisen, einer Auswahldiskographie, dem Gedichtverzeichnis und \u2013 f\u00fcr patscherte Eindringlinge unverzichtbar zum Entschl\u00fcsseln des lokalen Idioms \u2013 mit einem Glossar \u00f6ffnet Hein das Verst\u00e4ndnis f\u00fcr den Beitrag der Volkss\u00e4nger und -s\u00e4ngerinnen zum Wien-Mythos. <\/p>\n<p> <strong><em>Zitat aus dem Buch: <\/em><\/strong><br \/> \u00abDas Wienerlied lebt in Kontrafaktur und Parodie oder auch in ungebrochener Wiederholung weiter, Satire und Verh\u00f6hnung als Kitsch haben ihm nichts anhaben k\u00f6nnen, eher die Liebe verst\u00e4rkt, wie zahlreiche Lieder-Alben und Tonaufzeichnungen beweisen. Einige der bekanntesten Lieder sind gewisserma\u00dfen Volkslieder geworden. Zuletzt hat das Wienerlied gar das Forschungsinteresse von Musik- und Literaturwissenschaft geweckt.\u00bb (Nachwort, Seite 109) <br \/> <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Wienerlieder. Von Raimund bis Georg Kreisler. Herausgegeben von J\u00fcrgen Hein. Verlag Philipp Reclam, Stuttgart 2010. 136 Seiten. \u20ac 6,90. Fr. 11.50. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>01.11.2010 &#8212; \u00abAllweil lustig, fesch und munter, \/ Denn der Weaner geht net unter.\u00bb (Refrain eines Wienerlieds, anonym, 1880) Der&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-719","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=719"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/719\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}