{"id":730,"date":"2014-01-12T09:20:58","date_gmt":"2014-01-12T09:20:58","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/einheit-in-der-vielfalt-vielfalt-in-der-einheit\/"},"modified":"2014-01-12T09:20:58","modified_gmt":"2014-01-12T09:20:58","slug":"einheit-in-der-vielfalt-vielfalt-in-der-einheit","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/einheit-in-der-vielfalt-vielfalt-in-der-einheit\/","title":{"rendered":"Einheit in der Vielfalt \u2013 Vielfalt in der Einheit"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/2011\/110609kontrapunkt.jpg\" border=\"0\" align=\"left\" \/>17.06.2011 &#8212; Wer kennt nicht aus der Schulzeit das Singen im Kanon: die Klasse wird in Gruppen aufgeteilt, und nach meist gemeinsamem \u00abDurchsingen\u00bb eines Liedes erhalten diese zeitlich gestaffelt ihren Einsatz, wobei es, Hand aufs Herz, zur Freude der Klasse und zum Leidwesen der Lehrperson gelegentlich weniger um den Wohlklang geht, als darum, welche Gruppe lauter singen kann\u2026 Dass es sich beim Kanon um die heute wohl gebr\u00e4uchlichste Art des seit Jahrhunderten praktizierten Kontrapunkts handelt, ist dabei vermutlich den wenigsten gel\u00e4ufig.<\/p>\n<p> Im Gegensatz zur sogenannten homophonen Musik, bei der im allgemeinen eine Stimme von Akkorden begleitet wird, ist polyphone Musik anders strukturiert: Hier haben alle Stimmen einen eigenst\u00e4ndigen melodischen Verlauf. Allerdings ist die Geschichte der Polyphonie gepr\u00e4gt von der Frage, wieviel Eigenst\u00e4ndigkeit denn nun die einzelnen Stimmen erhalten sollen und inwieweit R\u00fccksichtnahme bez\u00fcglich der anderen Stimmen erforderlich ist. Dieses Spannungsfeld galt in der Musikgeschichte geradezu als eine Metapher; Ssollte das Strukturprinzip der Vielfalt in der Einheit (discordia concors) oder doch eher die Einheit in der Vielfalt (concordia discors) gelten?<\/p>\n<p> Der Begriff des Kontrapunkts ist seit dem 14. Jahrhundert als \u00abPunctus contra punctum\u00bb (Note gegen Note) schriftlich verb\u00fcrgt und steht f\u00fcr nach Regeln komponierte polyphone Musik. Dass die Kompositionstechnik des Kontrapunkts allerdings noch lange nicht ausgedient hat, zeigt dessen Gebrauch etwa in der Musik des 20. Jahrhunderts, als nach dem Ende der Tonalit\u00e4t nach neuen Ordnungsstrukturen gesucht wurde.<\/p>\n<p> Die Verbreitung des Begriffs \u00abKontrapunkt\u00bb im Alltag zeigt aber auch, dass es sich dabei um weit mehr als um einen musikalischen Fachbegriff handelt; meist ist damit eine Gegenposition oder Antithese gemeint. Geistesgeschichtlich gesehen ist zudem die Bedeutung des Kontrapunkts als Strukturprinzip wichtig, das das Spannungsfeld zwischen Vielfalt in der Einheit respektive der Einheit in der Vielfalt beschreibt.<\/p>\n<p> Der vorliegende Sammelband tr\u00e4gt diesen verschiedenen Bedeutungen Rechnung, der Titel ist sozusagen Programm. Nicht satztechnische Probleme werden behandelt, sondern insgesamt 16 Beitr\u00e4ge von international namhaften Musik- respektive im erweiterten Sinn Kulturwissenschaftlern zeichnen die philosophischen und kulturellen Verkn\u00fcpfungen des Kontrapunkts nach. Wie aus dem Vorwort der Herausgebers Ulrich Tadday zu entnehmen ist, beruhen die Beitr\u00e4ge auf Vortr\u00e4gen im Rahmen des Internationalen Dortmunder Bach-Symposions im Jahr 2010.<\/p>\n<p> Den Anfang macht Martin Geck, der als emeritierter Professor der Musikwissenschaft an der TU Dortmund lehrt, die dortigen Internationalen Bach-Symposien gegr\u00fcndet hat und diese auch leitet. Geck hat \u00fcbrigens im Jahr 2000 ein Referenzwerk zu Leben und Schaffen von Johann Sebastian Bach ver\u00f6ffentlicht, das Massst\u00e4be setzt. Anhand des erst vor etwa 50 Jahren in einer Abschrift wiederentdeckten zweistimmigen Kanons BWV 1086 mit der \u00dcberschrift \u00abconcordia discors\u00bb beschreibt Geck die kulturgeschichtlichen Hintergr\u00fcnde dieses Begriffs, die bis in die Antike zur\u00fcckreichen.<\/p>\n<p> Der Begriff \u00abconcordia discors\u00bb war auch in musiktheoretischen Traktaten der fr\u00fchen Neuzeit pr\u00e4sent und muss f\u00fcr Bach eine grosse Bedeutung gehabt haben, so Geck. Der Autor verteidigt Bachs kontrapunktisches Sp\u00e4twerk, zu dem der besprochene Kanon geh\u00f6rt, gegen zahlentheoretische Interpretationen. Vielmehr war das Prinzip der \u00abconcordia discors\u00bb eine zentrale Figur im Schaffen von Bach, die auf das Ausbalancieren von widerstrebenden Ordnungsprinzipien und auf deren kulturgeschichtliche Tradition verweist, so Geck.<\/p>\n<p> Peter Schleuning, Musikwissenschaftler und Hochschullehrer an der Universit\u00e4t Oldenburg, fragt in seinem Beitrag nach Kontrapunkt in Sonatens\u00e4tzen, insbesondere in der Durchf\u00fchrung. Der Kontrapunkt stellt ja keine musikalische Form dar, obwohl er etwa stark mit der Fuge verkn\u00fcpft ist, sondern ist eine Satztechnik und als solche grunds\u00e4tzlich auf verschiedene musikalische Formen anwendbar. Im Sonatensatz werden zun\u00e4chst Themen in der Exposition vorgestellt, die in der anschliessenden Durchf\u00fchrung kompositorisch verarbeitet werden. F\u00fcr Komponisten \u00fcbrigens eine hervorragende Gelegenheit, ihr K\u00f6nnen unter Beweis zu stellen.<\/p>\n<p> Eigentlich, so Schleuning, w\u00e4re es naheliegend, dass in der Durchf\u00fchrung die Themen beispielsweise auch so verarbeitet w\u00fcrden, dass sie gleichzeitig erklingten, also simultan als thematischer Kontrapunkt einander gegen\u00fcber gestellt w\u00e4ren. Schleuning hat in den Kopfs\u00e4tzen von Sinfonien und Klaviersonaten von Carl Philipp Emanuel Bach, Haydn, Mozart und Beethoven und in den Sinfonien von Schubert gesucht, aber keinen einzigen Fall von thematischem Kontrapunkt gefunden. Offenbar, so Schleuning, ist dessen Anwendung nicht nur eine Frage der formalen Gelegenheit, sondern auch abh\u00e4ngig vom aktuellen Stil und den Vorlieben der jeweiligen Epoche, in der Werke komponiert werden.<\/p>\n<p> Sozusagen Einblick in die Werkstatt des Kontrapunkts gibt der von Martin Kaltenecker aus dem Franz\u00f6sischen \u00fcbersetzte Beitrag des franz\u00f6sischen Musikwissenschaftlers und Spezialisten f\u00fcr Harmonie und Kontrapunkt Anthony Bergerault, der am Conservatoire de Lyon unterrichtet. Bergerault hat den Unterricht in Kontrapunkt am Conservatoire de Paris in der zweiten H\u00e4lfte des 19. Jahrhunderts untersucht. Zweimal pro Jahr wurden die Arbeiten der Kompositionssch\u00fcler bewertet; zus\u00e4tzlich schrieben die Lehrer jeweils einen Bericht \u00fcber die Fortschritte der Sch\u00fcler.<\/p>\n<p> Gabriel Faur\u00e9 beispielsweise, seinerzeit Kompositionslehrer am Conservatoire, schrieb \u00fcber seinen Sch\u00fcler Maurice Ravel: \u00abSehr intelligent, sehr begabt, aber zu gesucht, zu raffiniert. Fleissiger Sch\u00fcler.\u00bb Als H\u00f6hepunkt galt der j\u00e4hrliche Wettbewerb in Kontrapunkt und Fuge, zu dem nur fortgeschrittene Sch\u00fcler zugelassen waren.<\/p>\n<p> Bergerault hat festgestellt, dass selbst in diesen durch und durch akademischen Wettbewerbsarbeiten das k\u00fcnstlerische Potential begabter Studenten erkennbar ist; im Gegensatz zu den weniger Talentierten wichen diese n\u00e4mlich h\u00e4ufiger von den vorgegebenen kontrapunktischen Regeln ab und zeigten selbst in diesem begrenzten Rahmen Ans\u00e4tze eines pers\u00f6nlichen Stils.<\/p>\n<p> Ulrich Tadday, Professor f\u00fcr Historische Musikwissenschaft an der Universit\u00e4t Bremen, stellt zu Beginn seines Beitrags ironisch fest, dass Johann Sebastian Bach in den letzten Jahren h\u00e4ufiger Opfer der Belletristik geworden sei. Er stellt einen Roman vor, der seiner Meinung nach eine Ausnahme darstellt: \u00abKontrapunkt\u00bb der niederl\u00e4ndischen Autorin Anna Enquist, der 2008 in der Originalsprache und in der deutschen \u00dcbersetzung erschienen ist. Der Roman erz\u00e4hlt die Geschichte einer Mutter, eine ausgebildete Pianistin, die ihre Tochter bei einem Unfall verliert und nach langer schwerer Krise \u00fcber das Spielen der Goldberg-Variationen zugleich N\u00e4he zu ihrer verstorbenen Tochter und zur\u00fcck ins eigene Leben findet.<\/p>\n<p> Tadday untersucht die Beziehung zwischen Musik und Literatur und verweist auf die komplexe Struktur des Romans, die sich streng am Aufbau der 30 Goldberg-Variationen orientiert. Form und Inhalt des Romans verschr\u00e4nken sich dabei wechselseitig kunstvoll. Tadday sieht im Roman von Enquist ein gelungenes Beispiel f\u00fcr den Transfer der Idee des musikalischen Kontrapunkts auf eine andere Kunstgattung.<\/p>\n<p> Der Sammelband wird erg\u00e4nzt durch englischsprachige Abstracts s\u00e4mtlicher Beitr\u00e4ge sowie durch kurze biographische Angaben zu den Autorinnen und Autoren. Die Texte halten, was der Herausgeber im Vorwort verspricht und bieten eine philosophische, kultur- und kunstgeschichtliche tour d\u2019horizon des Kontrapunkts f\u00fcr Interessierte. Nicht satztechnische Anleitungen sondern Einsichten in die eigentliche Idee des Kontrapunkts erwarten die Leserschaft, die auch ohne musiktheoretisches Vorwissen den Ausf\u00fchrungen gut folgen kann.<\/p>\n<p> <strong><em>Zitat aus dem Buch: <\/em><\/strong><br \/> \u00abWeder sind Bachs &#8218;Vollkommenheiten&#8216; mit Stilreinheit zu verwechseln, noch eignet sich seine Musik f\u00fcr das Unterfangen, von einem \u00abgrossen Ganzen\u00bb zu schw\u00e4rmen, in das sie sich umstandslos einordnen liessen. Nur wer zur Kenntnis nimmt, dass in seinem Werk allenthalben Widerspr\u00fcche ausgetragen und Widerst\u00e4nde bew\u00e4ltigt werden, darf deren letztendliche Aufl\u00f6sung in Harmonie feiern.\u00bb (S. 19).<br \/> <\/span> <span class=\"txt-m-black\">(<em>swe<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Philosophie des Kontrapunkts. Reihe Musik-Konzepte, Sonderband. Neue Folge, herausgegeben von Ulrich Tadday. November 2010, edition text + kritik im Richard Boorberg Verlag, M\u00fcnchen. 256 Seiten. \u20ac 28. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>17.06.2011 &#8212; Wer kennt nicht aus der Schulzeit das Singen im Kanon: die Klasse wird in Gruppen aufgeteilt, und nach&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-730","post","type-post","status-publish","format-standard","hentry","category-buchbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=730"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/730\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}