{"id":784,"date":"2014-01-12T11:45:30","date_gmt":"2014-01-12T11:45:30","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/aesthetik-des-einfalls\/"},"modified":"2014-01-12T11:45:30","modified_gmt":"2014-01-12T11:45:30","slug":"aesthetik-des-einfalls","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/aesthetik-des-einfalls\/","title":{"rendered":"\u00c4sthetik des Einfalls"},"content":{"rendered":"<p><span class=\"txt-m-black\">05.03.2005 &#8212; Als Hans Pfitzner Arnold Sch\u00f6nberg, den Erfinder der Zw\u00f6lftonmusik,einmal einlud, in Strassburg ein Konzert mit eigenen Werken zu dirigieren, stellte dieser drei Bedingungen: Ein hohes Honorar, zahlreiche Proben \u2013 und die Garantie, dass das Publikum nicht lacht. Die dritte glaubte Pfitzner nicht erf\u00fcllen zu k\u00f6nnen: \u00abWie soll man garantieren, dass in einem Konzert nicht gelacht wird? Ich kann doch nicht hinter jeden Besucher einen Schutzmann stellen\u00bb, war \u2013 laut dem Publizisten Ludwig Schrott \u2013 sein Kommentar.<\/p>\n<p> Die Anekdote k\u00f6nnte allerdings ein falsches Bild vom Verh\u00e4ltnis zwischen den beiden Komponisten vermitteln. Nicht Sch\u00f6nberg war es in erster Linie, gegen den Pfitzner als Satiriker in den Kampf zog, gerade Sch\u00f6nberg war einer derjenigen, die ihm nach dem Zweiten Weltkrieg \u00abf\u00fcr die Entnazifizierung gl\u00e4nzende und wirkungsvolle Zeugnisse schrieben\u00bb (Schrott). Und dennoch bestanden auch zwischen Pfitzner und der Wiener Schule grundlegende Unterschiede im \u00e4sthetischen Selbstverst\u00e4ndnis. Unter Sch\u00f6nberg und seinen Sch\u00fclern (von denen Berg \u00fcberigens zwischen der Wahl Sch\u00f6nbergs und Pfitzners als Lehrer geschwankt hatte) herrschte die Meinung vor, Musik sei rational fassbar, Pfitzner hingegen erlangte nicht zuletzt wegen seiner beredt und k\u00e4mpferisch vertretenen \u00ab\u00c4sthetik des Einfalls\u00bb Ber\u00fchmtheit. Das Wesen des Einfalls ist nach Pfitzeners Auffassung prinzipiell unanalysierbar; er ist eine aus dem direkten Kontakt mit dem Unbewussten gesch\u00f6pfte Idee, die durch das Medium des Genies empfangen wird. Ein Massstab f\u00fcr diese Genialit\u00e4t der Erfindung ist nach Pfitzner die Tatsache, dass sie selbst lange Strecken von Musik als aus einem Guss geformt erscheinen l\u00e4sst, f\u00fcr deren Verst\u00e4ndnis es auch \u00abeine gewisse Begabung des Aufnehmens, entsprechend der des Schaffens\u00bb braucht.<\/p>\n<p> Pfitzners Musikauffassung l\u00e4uft Gefahr, den Diskurs zu verunm\u00f6glichen: Wer entscheidet, wessen Empfindung genialisch ist? Wer beurteilt die \u00abBegabung des Aufnehmens\u00bb eines H\u00f6rers? Wer bestimmt, wer was erlebt? Offensichtlich fehlen dazu die Argumente.<\/p>\n<p> Mit der Einfalls\u00e4sthetik geht die \u00dcberzeugung Pfitzners \u00fcberein, dass einem musikalischen Werk eine ganz bestimmte Wahrheit innewohnt, von der man sich entfernen und der man sich n\u00e4hern kann. Sie liess ihren Verfechter eine dezidiert konservative Interpretationslehre vertreten, deren Ideale er vor allem in der Kammermusik verwirklicht sah: \u00abDer Anreiz aber, das Werk zu \u00fcberwuchern, wird nat\u00fcrlich nur dann in voller Kraft sich geltend machen, wenn der Wiedergebende allein als verantwortlich zeichnet, wie es der Fall ist bei dem kassenbeherrschenden B\u00fchnenstern, dem &#8217;sch\u00f6pferischen&#8216; \u00dcberdirigenten, dem B\u00fchnenbildner mit &#8218;modernem Gestaltungswillen&#8216;, dem Spielleiter &#8218;mit Ideen&#8216;. Bei der Kammermusik findet am sch\u00f6nsten eine Art Verteilung dieser Verantwortung, eine &#8218;beschr\u00e4nkte Haftung&#8216; statt, mit ihr f\u00e4llt die Sensationsverkrampfung des Einzelk\u00fcnstlers fort.\u00bb<\/p>\n<p> Ber\u00fchmt geworden ist die Kontroverse zwischen dem Sch\u00f6nberg-Sch\u00fcler Alban Berg und Pfitzner \u00fcber die Analysierbarkeit von Schumann \u00abTr\u00e4umerei\u00bb, auf die der schlechte Ruf zur\u00fcckgeht, die der spr\u00f6de Sp\u00e4tromantiker in gewissen Avantgardekreisen geniesst. Der junge Komponist Wolfgang Rihm erinnert sich in einem Vortrag (\u00abZur Aktualit\u00e4t Pfitzners\u00bb): \u00abSo schalt Heinz-Klaus Metzger Luigi Nono einen seriellen &#8218;Pfitzner&#8216;, als Nono nicht so froh im Avantgardeclub mitturnen mochte, wie er h\u00e4tte sollen.\u00bb Im selben Vortrag weist Rihm jedoch auch darauf hin, dass trotz aller Neigung zur Analyse gerade Sch\u00f6nberg Pfitzners Einfallsmusik am konsequentesten entwickelt habe. Und er verweist auf die heutige Aktualit\u00e4t Pfitzners: \u00abDer Einfall, das Einlassen auf den momentanen Impuls, das Vertrauen auf die Gef\u00fchlssicherheit ist gegen\u00fcber der systematischen Musikherbeif\u00fchrung wesentlich aufgewertet. Durch Betonung der Einfallskunst wird heute ein progressiver Ort markiert, wird eine Haltung gegen die akademische Wiedergabe systematischer Raster eingenommen.\u00bb (wb)<br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>05.03.2005 &#8212; Als Hans Pfitzner Arnold Sch\u00f6nberg, den Erfinder der Zw\u00f6lftonmusik,einmal einlud, in Strassburg ein Konzert mit eigenen Werken zu&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-784","post","type-post","status-publish","format-standard","hentry","category-musikgeschichte","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=784"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/784\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}