{"id":789,"date":"2014-01-12T11:49:10","date_gmt":"2014-01-12T11:49:10","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/ein-leben-voller-ungemach\/"},"modified":"2014-01-12T11:49:10","modified_gmt":"2014-01-12T11:49:10","slug":"ein-leben-voller-ungemach","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/ein-leben-voller-ungemach\/","title":{"rendered":"Ein Leben voller Ungemach"},"content":{"rendered":"<p><span class=\"txt-m-black\">26.08.2005 &#8212; Heinrich Sch\u00fctz ist kein Musiker, dem gesellschaftlich und famili\u00e4r ein unbeschwertes Dasein verg\u00f6nnt gewesen w\u00e4re. \u00dcberblickt man sein Leben, so ist man erstaunt, mit welcher Vitalit\u00e4t und Lebensbejahung trotz aller widriger Umst\u00e4nde er sich immer wieder f\u00fcr die Seinen und die Musik einzusetzen weiss.<\/p>\n<p> 1585 als Sohn eines Wirtes in Weissenfels geboren, wird er vom Landgrafen Moritz von Hessen-Kassel auf einer seiner Reisen entdeckt und tatkr\u00e4ftig gef\u00f6rdert. \u00dcber die einzelnen Stationen seines Wirkens brauchen nicht viel Worte verloren zu werden, auff\u00e4llig ist die Best\u00e4ndigkeit und Treue, mit der er gedient hat, zuerst in Kassel, sp\u00e4ter \u2013 mehr als dreissig Jahre \u2013 in Dresden am Hofe des s\u00e4chsischen Kurf\u00fcrsten, dem er, im Interesse der von ihm abh\u00e4ngigen Untergebenen, selbst dann noch mit aller Kraft beisteht, als dieser sich schon lange der Trunksucht ergeben hat und den hartn\u00e4ckigen Bitten seines Kapellmeisters nach Linderung der Not ebenso hartn\u00e4ckiges Schweigen entgegensetzt.<\/p>\n<p> In dieser schwierigen Zeit gibt Sch\u00fctz zur Unterst\u00fctzung seiner notleidenden Musiker beinahe alles hin, was er besitzt. Die Anerkennung jedoch bleibt ihm versagt, und viel Ungemach, das er erleidet, muss darauf zur\u00fcckgef\u00fchrt werden, dass er nicht in erster Linie die eigene Karriere im Auge hat, sondern in erster Linie die Qualit\u00e4t der Musik.<\/p>\n<p> Unter keinem guten Stern steht auch sein Familienleben. Seine Frau, die er von ganzem Herzen liebt, stirbt sechs Jahre nach der Hochzeit. Sch\u00fctz hat sie nie vergessen k\u00f6nnen: Kurz vor seinem Tode l\u00e4sst er ihr Grab neu herrichten, an ihrer Seite will er selbst beerdigt sein.<\/p>\n<p> Auch mit seinen T\u00f6chtern hat er kein Gl\u00fcck. Euphrosyne, die einzige, die das heiratsf\u00e4hige Alter erreicht, ist schw\u00e4chlich und stirbt vier Jahre nach ihrer Hochzeit, auch von ihren Kindern \u00fcberlebt nur eines. Selbst die meisten seiner Geschwister sieht Sch\u00fctz vor sich ins Grab sinken.<\/p>\n<p> Auch wenn Sch\u00fctz einen Grossteil seines Lebens am Hofe des s\u00e4chsischen Kurf\u00fcrsten in Dresden verbringt, so bringen ihn Studienreisen doch auch nach Italien zu Giovanni Gabrieli, wo er neben der neuen, leichten Art des Musizierens umfassenden humanistischen Geist kennenlernt. Dem Kurf\u00fcrsten Johann Georg gelingt es lange Zeit, im Dreissigj\u00e4hrigen Krieg sein Land aus den religi\u00f6sen und politischen Auseinandersetzungen zwischen den kaiserlich Katholischen unter der F\u00fchrung Wallensteins und den reformierten Streitkr\u00e4ften Gustav Adolfs herauszuhalten.<\/p>\n<p> Die apokalyptische Zerst\u00f6rung Magdeburgs \u2013 bis zum Ende des Zweiten Weltkriegs l\u00e4sst sich in Europa kein vergleichbares Ereignis mehr finden \u2013 bildet jedoch den Auftakt zu einer Eskalation der Auseinandersetzungen, von denen abzusehen ist, dass sie sich auf s\u00e4chsischen Boden ausweiten werden. Als die Kaiserlichen die Burg von Weissenfels pl\u00fcndern und Tilly unter Verw\u00fcstung des umliegenden Landes in Sachsen einbricht, schl\u00e4gt sich der Kurf\u00fcrst auf die Seite Gustav Adolfs.<\/p>\n<p> Die Bilanz jahrzehntelanger Unkultur ist erschreckend: St\u00e4dte, die abwechselnd von den kaiserlichen und den schwedischen Truppen gepl\u00fcndert worden sind, z\u00e4hlen nach dem Krieg noch ein Drittel ihrer urspr\u00fcnglichen Bev\u00f6lkerung; raubende, brandschatzende und mordende Soldatenverb\u00e4nde, deren Versorgung das umliegende Land zu besorgen hat, ruinieren ganze Ernten, foltern und vergewaltigen, ohne zur Rechenschaft gezogen zu werden; Seuchen, Hungersn\u00f6te und religi\u00f6ser Wahnsinn, wie er sich nicht zuletzt in den sinnlosen, tausendfachen Hexenverbrennungen manifestiert, sind die Begleiterscheinungen des Krieges.<\/p>\n<p> Im Gegensatz zur Johannespassion, in welcher der Nachvollzug der Leiden Christi im Zentrum steht, ist das Evangelium nach Matth\u00e4us auf die Zukunft, auf die Erschaffung der neuen Gemeinde gerichtet. F\u00fcr dessen Vertonung, die als Aufforderung an die Nachkriegsgeneration, ein neues Europa zu schaffen, angesehen werden kann, w\u00e4hlt Sch\u00fctz den dorischen Modus. \u00abUm solche grundlegende Allgemeinverbindlichkeit zu symbolisieren, nimmt Sch\u00fctz die universelle Tonartengruppe, die in der Gabrieli-Schule die Mitte der m\u00f6glichen Affektlagen zeichenhaft symbolisiert\u00bb (Otto Brodde).<\/p>\n<p> Es ist dies wohl auch die angemessene Art, die d\u00fcsteren Jahre des Dreissigj\u00e4hrigen Kriegs und den christlichen Auftrag in Erinnerung zu rufen. Sch\u00fctz bedient sich des unbegleiteten Rezitativs. Die Matth\u00e4uspassion setzt zudem mit asketisch leeren Quinten ein, in die sich, \u00aberschrocken \u00fcber den g\u00e4hnenden Abgrund, sofort Intervalle der Nebentonart mit dem weiterf\u00fchrenden Wort schieben\u00bb (Martin Gregor-Dellin) (wb)<br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>26.08.2005 &#8212; Heinrich Sch\u00fctz ist kein Musiker, dem gesellschaftlich und famili\u00e4r ein unbeschwertes Dasein verg\u00f6nnt gewesen w\u00e4re. \u00dcberblickt man sein&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-789","post","type-post","status-publish","format-standard","hentry","category-musikgeschichte","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=789"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/789\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}