{"id":837,"date":"2014-01-12T13:29:36","date_gmt":"2014-01-12T13:29:36","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/orchestra-della-svizzera-italiana-in-zuerich\/"},"modified":"2014-01-12T13:29:36","modified_gmt":"2014-01-12T13:29:36","slug":"orchestra-della-svizzera-italiana-in-zuerich","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/orchestra-della-svizzera-italiana-in-zuerich\/","title":{"rendered":"Orchestra della Svizzera Italiana in Z\u00fcrich"},"content":{"rendered":"<p><span class=\"txt-m-black\">23.01.2011 &#8212; Man kennt sich: Die junge Hornistin Zora Slokar, die das Konzert der dritten Tournee der Migros Kulturprozent Classics mit dem Orchestra della Svizzera Italiana (OSI) in der Z\u00fcrcher Tonhalle er\u00f6ffnete, ist selber Mitglied des Ensembles. Entsprechend harmonisch f\u00fcgen sich Kollektiv und Solistin zu einem Ganzen \u2013 fast schon zu harmonisch, ist man versucht zu sagen, denn das Tessiner Orchester pflegte in der Wiedergabe des zweiten Hornkonzertes des Salzburger Meisters einen gegl\u00e4tteten, eher konventionellen Mozart-Stil.<\/p>\n<p> Da blieben denn die \u2013 vor allem im dritten Satz \u2013 schalkhaften bis frechen Momente wie die Stop-and-Go-Generalpausen mit Fortepiani oder die vorwitzigen Vorschlag-Ketten in den Violinen eher unterverkauft. Die Solistin spielte auch die Kadenz in dem Satz nicht wirklich aus. Alles in allem h\u00f6rte man da eine gef\u00e4llige, klangsch\u00f6ne, in den Streichern seidige und kompakte Wiedergabe, die aber eher vom einem Bed\u00fcrfnis gepr\u00e4gt war: vor allem keine Risiken einzugehen.<\/p>\n<p> Dabei darf nicht vergessen gehen, dass das traditionsreiche Orchester, das seine Existenz zur Zeit unverst\u00e4ndlicherweise finanziell rechtfertigen muss, mit einem Acht-Millionen-Budget wirklich Erstaunliches leistet. Klanglich wirkt es ausgewogen, in den einzelnen Registern exzellent besetzt und wendig-kultiviert.<\/p>\n<p> In der Wiedergabe von Beethovens siebter Sinfonie erwies es sich unter der Leitung des Kolumbianers Andr\u00e9s Orozco-Estrada als spielfreudiger, kompakter Klangk\u00f6rper, der nicht die Sch\u00e4rfen des historisch-informierten Musizierens anstrebt (mittlerweile hat man eher die knalligen Pauken und Naturh\u00f6rner neuerer Aufnahmen im Ohr als die geschmeidigen Texturen, die das OSI aus dem 20. Jahrhundert tradiert). Man l\u00e4sst sich aber auch von dieser Lesart des Bonner Klassikers gerne packen und mitreissen. <\/p>\n<p> Den reichen und herzlichen Applaus verdankte das Ensemble mit der Ouvert\u00fcre zu Mozarts Oper \u00abLe nozze di Figaro\u00bb &#8211; in gewisser Hinsicht ein gelungener R\u00fcckverweis auf das Hornkonzert, in dem im ersten Satz Motive einer sp\u00e4teren \u00abFigaro\u00bb-Arie angelegt sind.<\/p>\n<p> Dazwischen gesellte sich der Geiger Vadim Repin zum OSI, als Solist des \u00fcberaus popul\u00e4ren Violinkonzertes von Tschaikowsky. Auch er wagte sich kaum auf neue Pfade. Er scheute weder gelegentliche Portamenti noch manchmal etwas grossz\u00fcgig-pauschales Durcheilen des Laufwerkes, fand aber hier und da auch zu intensiven, expressiven Momenten des Gleichklanges mit dem sensibel mitgehenden Orchester. <\/p>\n<p> Als Zugabe servierte Repin Paganinis virtuos durch Pizzicato- und Sechzehntelm\u00fchlen gedrehten \u00abKarneval von Venedig\u00bb, ein Kabinettst\u00fccklein, in dem die spieltechnische Disziplin dann allerdings vollst\u00e4ndig auf der Strecke blieb. Dem lebhaften Zuspruch des Publikums tat das allerdings keinen Abbruch \u2013 und dessen Urteil z\u00e4hlt ja letztlich. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">Orchestra della Svizzera Italiana, Andr\u00e9s Orozco-Estrada (Leitung), Vadim Repin (Violine), Zora Slokar (Horn), Mozart: 2. Hornkonzert KV 417, Tschaikowsky: Violinkonzert D-Dur, op. 35, Beethoven: 7. Sinfonie op. 92. Tonhalle Z\u00fcrich, Grosser Saal, Freitag, 21. Januar 2011.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>23.01.2011 &#8212; Man kennt sich: Die junge Hornistin Zora Slokar, die das Konzert der dritten Tournee der Migros Kulturprozent Classics&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-837","post","type-post","status-publish","format-standard","hentry","category-ereignisbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=837"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/837\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}