{"id":838,"date":"2014-01-12T13:30:03","date_gmt":"2014-01-12T13:30:03","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/aargauer-symphonie-orchester-koenig-david\/"},"modified":"2014-01-12T13:30:03","modified_gmt":"2014-01-12T13:30:03","slug":"aargauer-symphonie-orchester-koenig-david","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/aargauer-symphonie-orchester-koenig-david\/","title":{"rendered":"Aargauer Symphonie Orchester: \u00abK\u00f6nig David\u00bb"},"content":{"rendered":"<p><span class=\"txt-m-black\">07.03.2011 &#8212; Jede Epoche hat ihre Geschichten. Heute pilgert das Volk in Musicals wie \u00abEwigi Liebi\u00bb oder \u00abDie Schwarzen Br\u00fcder\u00bb. Anfangs des 20. Jahrhunderts waren es noch die biblischen Mythen, die dem Schweizer Publikum Divertissement, Dramatik und Erbauung boten. Zunutze machte sich das auch der Welschschweizer Ren\u00e9 Morax, der dem Schweizer Komponisten Arthur Honegger mit \u00abLe Roi David\u00bb die Vorlage f\u00fcr eine farbenreiche, effektvolle und zug\u00e4ngliche Theatermusik lieferte.<\/p>\n<p> Die urspr\u00fcnglich f\u00fcr Bl\u00e4ser und Harmonium als Streicherersatz konzipierte Partitur kam am 11. Juni 1921 im Th\u00e9\u00e2tre du Jorat im waadtl\u00e4ndischen Ort M\u00e9zi\u00e8res, einem imposanten Holzbau mitten im Lausanner Hinterland, zur szenischen Urauff\u00fchrung (siehe dazu auch das Codex-flores-<a href=\"http:\/\/212.60.37.143\/dossiers_ind9.php?art=65\">Dossier<\/a>). Zwei Jahre sp\u00e4ter fand eine umgearbeitete Konzertfassung mit Streichern den Weg aufs Podium.<\/p>\n<p> \u00abLe Roi David\u00bb ist damit ein hochkar\u00e4tiges St\u00fcck Schweizer Volkskultur. So stimmte denn auch alles zusammen, als es das Aargauer Symphonie Orchester mit lauter lokalen Akteuren etwas ausserhalb der Stadt Aarau in der B\u00e4renmatte Suhr zum besten gab \u2013 an einem Ort, der zwar nicht den l\u00e4ndlichen Charme des Th\u00e9\u00e2tre du Jorat hat, aber mit seinen Backsteinw\u00e4nden und seinem n\u00fcchtern-sauberen Ambiente einer typisch mittell\u00e4ndischen Mehrzweckhalle den unpr\u00e4tenti\u00f6sen, auf die Inhalte und nicht auf repr\u00e4sentativen Glamour fokussierenden Anspruch des Werkes unterstrich. <\/p>\n<p> Die vergleichsweise trockene Akustik des Raumes kam der Durchh\u00f6rbarkeit der mit Streichern angereicherten Bl\u00e4sermusik dabei durchaus zugute: Kaum ein Detail der theatralisch-gestisch geschriebenen Musik entging da dem Ohr.<\/p>\n<p> Dass das Orchester sich auch in der erbarmungslos alle Feinheiten sezierenden akustischen Linse der B\u00e4renmatte mit hoher Pr\u00e4zision und herausragenden einzelnen Leistungen vor allem der Bl\u00e4ser zu profilieren vermochte, sprach f\u00fcr das hohe musikalische Niveau des Ensembles und die Erfahrung des britischen Dirigenten Douglas Bostock, der weniger f\u00fcr die Galerie dirigierte, als dass er mit praktischem Sinn und pragmatischer Lenkkraft die Musik aufbl\u00fchen liess. <\/p>\n<p> Exzellent vorbereitet zeigte sich auch die rund hundertk\u00f6pfige Schola Cantorum Wettingensis, die unter der Leitung von Roland Fitzlaff steht, und f\u00fcr die honeggersche Herausforderung \u00fcberdies vom am Opernhaus Z\u00fcrich t\u00e4tigen J\u00fcrg H\u00e4mmerli gecoacht wurde. Ideal besetzt zeigten sich schliesslich die Solopartien \u2013 mit der ukrainischen Mezzosopranistin Christina Daletska (die laut Programmheft auch Denk- und Logikpuzzleb\u00fccher verfasst), der Sopranistin Franziska Welti, dem Tenor Valentin Gloor sowie last but not least dem Schauspieler Walter K\u00fcng als Erz\u00e4hler.<\/p>\n<p> Das Aargauer Symphonie Orchester darf f\u00fcr sich in Anspruch nehmen, mit dieser Produktion eine in jeder Hinsicht stimmige und authentische Deutschschweizer Adaption des Oratoriums realisiert zu haben und damit an eine Tradition der volksverbundenen Schweizer Musikkultur angekn\u00fcpft zu haben, die in ihrer unaufgeregten, geschmackvollen und weltoffenen Art nichts von ihrer Kraft verloren hat. <\/p>\n<p> Dem Oratorium vorangestellt hatte Bostock eine Wiedergabe der 39. Sinfonie Es-Dur KV 543 Mozarts. Sie war vor allem durch den Verleger und Pionier des Schweizer Chorwesens Hans Georg N\u00e4geli, respektive dessen vielzitiertes (und sprachlich missgl\u00fccktes) Verdikt, das Werk \u00abschnappe\u00bb im Finale unvermutet \u00abab\u00bb mit der hiesigen Musikkultur verbunden. <\/p>\n<p> Da musste sich das Orchester in ungleich st\u00e4rkerem Masse als im Oratorium an einer differenzierten und opulenten Interpretationsgeschichte messen lassen. Es erwies sich in diesem Fall als zwar eher konventionell, aber pr\u00e4zise und spielfreudig agierendes Ensemble. Es zeigte sich da, dass seinen Violinregistern ab und zu m\u00f6glicherweise etwas der letzte Schliff fehlt. In den erbarmungslos analytischen H\u00f6rverh\u00e4ltnissen des Saales setzte es sauberen Zusammenklang manchmal auch vor Spielwitz, Vorw\u00e4rtsdrang und dynamische Subtilit\u00e4ten. <\/span> <span class=\"txt-m-black\">(<em>wb<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">\u00abEs lebe der K\u00f6nig!\u00bb, Konzert des Aargauer Symphonie Orchesters. Mozart: Symphonie Es-Dur KV 543, Honegger: \u00abK\u00f6nig David\u00bb. Mitwirkende: Walter K\u00fcng (Erz\u00e4hler), Franziska Welti (Sopran), Christina Daletska (Mezzosopran), Valentin Gloor (Tenor), Schola Cantorum Wettingensis ((Leitung: Roland Fitzlaff, Gesamteinstudierung: J\u00fcrg H\u00e4mmerli), Douglas Bostock (Dirigent),<br \/> Sonntag, 6. M\u00e4rz 2011, B\u00e4renmatte Suhr.<\/p>\n<p> Weitere Auff\u00fchrungsdaten: Dienstag, 8. M\u00e4rz 2011, 20 Uhr, B\u00e4renmatte Suhr, Samstag, 12. M\u00e4rz 2011, 20 Uhr, Trafo-Halle Baden. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>07.03.2011 &#8212; Jede Epoche hat ihre Geschichten. Heute pilgert das Volk in Musicals wie \u00abEwigi Liebi\u00bb oder \u00abDie Schwarzen Br\u00fcder\u00bb.&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-838","post","type-post","status-publish","format-standard","hentry","category-ereignisbesprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=838"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/838\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}