{"id":880,"date":"2014-01-12T16:12:35","date_gmt":"2014-01-12T16:12:35","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/ferde-grofe-koenig-der-lautmalerei\/"},"modified":"2014-01-12T16:12:35","modified_gmt":"2014-01-12T16:12:35","slug":"ferde-grofe-koenig-der-lautmalerei","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/ferde-grofe-koenig-der-lautmalerei\/","title":{"rendered":"Ferde Grof\u00e9, K\u00f6nig der Lautmalerei"},"content":{"rendered":"<table cellpadding=\"10\">\n<tbody>\n<tr>\n<td width=\"430\"><span class=\"txt-m-black\">13.10.2003 &#8212; Als Ferde Grof\u00e9s \u00abTabloid Suite\u00bb in der New Yorker Carnegie Hall erstmals gegeben wurde, erg\u00e4nzten das Orchester vier Schreibmaschinen, ein Revolver, ein Maschinengewehr, eine Ambulanz-Sirene, eine Polizeipfeife und eine klappernde Telegraphen-Taste. So wie der Revolver auf dem Hintergrund von schmetternden Blechbl\u00e4sern und rollenden Trommeln abgefeuert wurde, schrieb die \u00abNew York Times\u00bb, habe er das vornehme Publikum buchst\u00e4blich aus Sitzen und Anz\u00fcgen geblasen.<\/p>\n<p> Soviel zur Lust am Effekt des amerikanischen Popul\u00e4rmusik-Komponisten Ferde Grof\u00e9, der heute beinahe vergessen ist, als Arrangeur zwischen 1919 und 1933 dem legend\u00e4ren Orchester Paul Whitemans jedoch einen unverwechselbaren Stempel aufgedr\u00fcckt und damit amerikanische Musikgeschichte geschrieben hat. Als Komponist tat Grof\u00e9 alles, um sich selber f\u00fcr die Hochkultur ein f\u00fcr alle Mal radikal zu deklassieren: Neben den Arbeiten f\u00fcr ein \u00abJazz\u00bb-Orchester ist dies vor allem der hemmungslose Griff in die Trickkiste der Lautmalerei, die ab und an selbst die Kniffe eines Scott Bradley und dessen Vertonungen der \u00abTom and Jerry\u00bb-Trickfilme in den Schatten stellt. Die \u00abTabloid Suite\u00bb beschreibt die Atmosph\u00e4re bei der Produktion einer Grossstadt-Zeitung, was auch die Effektabteilung des Orchesters erkl\u00e4rt. Und tats\u00e4chlich sieht man buchst\u00e4blich vor sich, wie die Redaktoren ihre \u00abLatest News\u00bb zum sozialen und gesellschaftlichen Leben der Stadt in die Tasten h\u00e4mmern und die Druckmaschinen angeworfen werden. Alles perfekt, souver\u00e4n und \u00fcberaus lustvoll aufs Notenpapier gebracht.<\/p>\n<p> Dem Vergessen entrissen hat die Partitur nicht ein Amerikaner, sondern der Niederl\u00e4nder Gert-Jan Blom. Der Leiter des Metropole Orchestras, einer einzigartigen Kombination von Jazzmusikern und klassisch geschulten Instrumentalisten, behandelte Grof\u00e9s Manuskripte mit dem gleichen Respekt, die den Werken eines Schubert, Strauss oder Debussy zukommen. Aufgrund einer genauen Analyse der Autographen erstellte er eine \u00abUrtext\u00bb-Fassung der Musik und spielte diese zusammen mit der bekannteren \u00abGrand Canyon Suite\u00bb Grof\u00e9s mit \u00abHet Metropole Orkest\u00bb ein. Obwohl geografisch weit vom Entstehungsort der Musik entfernt angesiedelt, kann sich das holl\u00e4ndische Ensemble als legitime H\u00fcterin der Musik f\u00fchlen, wurde es doch 1945 von Dolf van der Linden mit dem Vorbild des Paul-Whiteman-Orchesters gegr\u00fcndet.<\/p>\n<p> Die Doppel-CD birgt eine weitere Perle, die in erster Linie f\u00fcr Gershwin-Fans ein Muss darstellt. Wer h\u00e4tte gewusst, dass das \u00abConcerto in F\u00bb urspr\u00fcnglich klassische Musik f\u00fcr ein Jazzorchester und nicht Jazz f\u00fcr ein klassisches Orchester h\u00e4tte werden sollen? So zumindest sah es Whiteman, der Gershwin mit dem Auftrag zur \u00abRhapsody in Blue\u00bb auf die uramerikanische Tonsprache gestossen hatte. Zum Verdruss Whitemans orchestrierte Gershwin das Konzert jedoch selber \u2013 in der mittlerweile bekannten grossorchestralen Fassung. 1928 beauftragte Whiteman seinen Arrangeur Grof\u00e9 damit, Gershwins Musik f\u00fcr sein Orchester einzurichten. Dank Gert-Jan Bloms Bem\u00fchungen ist auch diese Version nun einem breiten Publikum zug\u00e4nglich. Es ist unglaublich spannend, Gershwins und Grof\u00e8s Versionen zu vergleichen und in letzterer ein F\u00fclle an Details zu entdecken, die dem Werk einen frechen, sperrig-derben und urmusikantischen Dreh verleihen.<\/span> <span class=\"txt-m-black\">(<em>pb<\/em>)<\/span><\/p>\n<p><center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center><\/td>\n<\/tr>\n<tr>\n<td><span class=\"txt-s-black\">Ferde Grof\u00e9: Tabloid Suite, Grand Canyon Suite; George Gershwin: Concerto in F (arr. Ferde Grof\u00e9), Het Metropole Orkest, Jan Stulen (Leitung), Jan Willem Nelleke (Klavier), Basta 30-9119-2 <\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>13.10.2003 &#8212; Als Ferde Grof\u00e9s \u00abTabloid Suite\u00bb in der New Yorker Carnegie Hall erstmals gegeben wurde, erg\u00e4nzten das Orchester vier&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-880","post","type-post","status-publish","format-standard","hentry","category-tontraeger-besprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=880"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/880\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}