{"id":895,"date":"2014-01-12T16:20:02","date_gmt":"2014-01-12T16:20:02","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/dido-and-aeneas-purcells-einzige-oper\/"},"modified":"2014-01-12T16:20:02","modified_gmt":"2014-01-12T16:20:02","slug":"dido-and-aeneas-purcells-einzige-oper","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/dido-and-aeneas-purcells-einzige-oper\/","title":{"rendered":"\u00abDido and Aeneas\u00bb: Purcells einzige Oper"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/purcell270104.jpg\" border=\"0\" align=\"left\" \/>31.01.2004 &#8212; Fragen \u00fcber Fragen wirft Englands erste Nationaloper \u00abDido and Aeneas\u00bb, Henry Purcells popul\u00e4rstes Werk, auf. Unklar sind Anlass und Entstehungsdatum, und wohl nicht mehr zu eruieren ist die originale Fassung der Oper in drei Akten mit Prolog und Epilog. Gesichert ist immerhin der Ort der Urauff\u00fchrung: das M\u00e4dchenpensionat in Chelsea des Josias Priest, Tanzlehrer und Choreograph. <\/p>\n<p> Die Oper, vermutlich eine Auftragsarbeit von 1683\/84 f\u00fcr eine Wiedergabe am Hof, ist wohl 1689 erstmals aufgef\u00fchrt worden. Wenn auf die Mitteilung Verlass ist, dass sie der Komponist vom Cembalo aus geleitet hat, wird er selbst das Werk dem K\u00f6nnen der Sch\u00fclerinnen angepasst haben, die solistische und chorische Aufgaben zu \u00fcbernehmen hatten. Andere Quellen sprechen davon, dass Josias Priest selbst eine Fassung hergestellt hat. Wie dem auch sei: Gewiss ist hier nur das Ungewisse, weil man zudem die M\u00f6glichkeit in Betracht ziehen muss, dass nicht alles Komponierte erhalten blieb. Zudem haben nach Purcells Tod (er starb 1695 im Alter von 36 Jahren) immer wieder Bearbeiter im Sinn ihres Verst\u00e4ndnisses und der Erwartungen ihrer Gegenwart eingegriffen. Als Quellen verf\u00fcgbar sind Abschriften bzw. Fassungen von 1750 und 1784\/85.<\/p>\n<p> Emmanuelle Ha\u00efm, Cembalistin (sie arbeitete mit William Christie, Christophe Rousset und Marc Minkowski), Gr\u00fcnderin (2000) und Leiterin des Ensembles Le Concert d\u2019Astr\u00e9e, hat f\u00fcr die vorliegende Einspielung eine Version aus Versionen hergestellt, immer mit der Absicht, den Nerv des Werks, wie es sich bei der Urauff\u00fchrung im Pensionat des Tanzlehrers pr\u00e4sentiert haben mag, zu treffen. Deshalb gab sie der szenischen, gestischen Atmosph\u00e4re mit Einschluss der effektvollen Ballette den Vorzug. <\/p>\n<p> Purcell bannt in dieser durchkomponierten Kurzoper die Gefahr der Kurzatmigkeit, indem er einzelne Elemente zusammenfasst zu gr\u00f6sseren Einheiten. So f\u00fchrt er Solonummern thematisch im anschliessenden Chorsatz weiter oder l\u00e4sst Ch\u00f6re in Tanzs\u00e4tze m\u00fcnden. Im engen Rahmen bringt er eine Vielfalt von Formen, Modellen und Affekten unter, treibt die Handlung energisch voran.<\/p>\n<p>Gewonnen hat Nahum Tate sein Libretto aus dem 4. Gesang von Vergils Epos \u00abAeneis\u00bb. Dido, als Tochter des K\u00f6nigs von Tyros fr\u00fcher Melissa geheissen, Gr\u00fcnderin Karthagos, verliebt sich in Aeneas, Aphrodites Sohn, der nach dem Untergang Trojas auf der Flucht ist. Bei Vergil ruft Didos eifers\u00fcchtiger Nachbark\u00f6nig Iarbas keinen Geringeren als Jupiter zu Hilfe, der Aeneas die Weiterreise befiehlt; Dido st\u00fcrzt sich ins Schwert. Im Libretto allerdings wird der G\u00f6tterk\u00f6nig nur vorgeschoben: Eine t\u00fcckische Zauberin und ihre Hexen (beliebte Figuren jener Epoche) beauftragen einen angeblich von Jupiter gesandten Boten, Aeneas unverz\u00fcglich nach Italien zu schicken (wo er dann, wie die Legende weiss, Gr\u00fcnder des r\u00f6mischen Volkes wird und dergestalt Italien zum legitimen Erben Griechenlands macht). Dido, die br\u00fcsk Verlassene, stirbt aus Verzweiflung, ein Opfer des tragischen Konflikts zwischen Liebe und Pflicht. <\/p>\n<p> Der genialen Musik und dem Zauber dieser (technisch makellos aufgenommenen) Interpretation kann man sich nicht entziehen. Emmanuelle Ha\u00efm, temperamentvolle Leiterin und Cembalistin, die ideal harmonierenden Vokalistinnen und Vokalisten der ersten Garde \u2013 Susan Graham (Dido), Ian Bostridge (Aeneas), Camilla Tilling (Belinda), C\u00e9cile de Boever (Zweite Dame), Felicity Palmer (Hexe), David Daniels (Bote) und Paul Agnew (Seemann) \u2013, die European Voices und Le Concert d\u2019Astr\u00e9e gestalten mit weitem Atem, bis ins Detail mit Vitalit\u00e4t und rhythmischer Pointierung, mit reich n\u00fcancierter Klangfarbenpracht und nobler, die Charaktere und die Handlung plastisch entwickelnde Expressivit\u00e4t. Von der Ouvert\u00fcre bis zu Didos ber\u00fchmtem Lamento \u00abWhen I am laid in earth\u00bb mit dem Schlusschor ein faszinierendes Erlebnis! <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\"><a href=\"http:\/\/www.amazon.de\/exec\/obidos\/ASIN\/B000093U3J\/codexflores-21\">Henry Purcell: \u00abDido and Aeneas\u00bb,<\/a> Opera in Three Acts. Solisten, European Voices, Le Concert d\u2019Astr\u00e9e. Leitung: Emmanuelle Ha\u00efm. (Virgin Classics 7243 5 45604 2 2; 53\u2019. Booklet mit Libretto, englisch\/franz\u00f6sisch\/deutsch)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>31.01.2004 &#8212; Fragen \u00fcber Fragen wirft Englands erste Nationaloper \u00abDido and Aeneas\u00bb, Henry Purcells popul\u00e4rstes Werk, auf. Unklar sind Anlass&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-895","post","type-post","status-publish","format-standard","hentry","category-tontraeger-besprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=895"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/895\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}