{"id":906,"date":"2014-01-12T16:25:34","date_gmt":"2014-01-12T16:25:34","guid":{"rendered":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/spass-mit-john-corigliano\/"},"modified":"2014-01-12T16:25:34","modified_gmt":"2014-01-12T16:25:34","slug":"spass-mit-john-corigliano","status":"publish","type":"post","link":"https:\/\/codexflores.ch\/index.php\/2014\/01\/12\/spass-mit-john-corigliano\/","title":{"rendered":"Spass mit John Corigliano"},"content":{"rendered":"<p><span class=\"txt-m-black\"><img decoding=\"async\" src=\"http:\/\/212.60.37.143\/bilder\/corig250404.jpg\" border=\"0\" align=\"left\" \/>17.04.2004 &#8212; Wie eine Rakete gestartet wird? Ein Streichholz angerissen, Feuer gelegt an die Zw\u00f6lfton-Z\u00fcndschnur; die Maschine kommt schwerf\u00e4llig in Gang, faucht und stampft und hebt schliesslich fulminant ab mit dem Beginn einer Sinfonie des Mannheimers Johann Wenzel Anton Stamitz. Soweit der Auftakt zu einer Raketen-Reise, die in ferne Sph\u00e4ren, aber auch durch zwei Jahrhunderte Musik f\u00fchrt. Der Flug endet turbulent mit dem ungebremsten Fall der gigantischen Papprakete und ihrem Aufschlag auf der Erde. Selbst Wagner kann da nichts mehr retten. <\/p>\n<p> Im Auftrag des Orchesters des Mannheimer Nationaltheaters und zur Bereicherung der Gattung der musikalischen Sp\u00e4sse hat John Corigliano das Elf-Minuten-St\u00fcck \u00abThe Mannheim Rocket\u00bb (2000) komponiert. Inspirationskern ist die sogenannte Mannheimer Rakete, eine rasch aufsteigende melodische Figur der Mannheimer Schule (2. H\u00e4lfte 18. Jahrhundert); den Motor f\u00fcr seine M\u00fcnchhausiaden-Rakete gewann Corigliano aus den Bassbegleitfiguren des Italieners Domenico Alberti, die meist in Zeitlupe einherstampfen. <\/p>\n<p> F\u00fcr Witz und Heiterkeit sorgt zudem eine Reihe von Zitaten; sie erklingen meist in K\u00fcrzelform und erweisen deutschen Meistern aus zweihundert Jahren Reverenz. Ebenso humorig sind thematische oder instrumentale Allusionen, und die brillante Instrumentation geizt nicht mit Effekten und Eins\u00e4tzen von Sonderinstrumenten. <\/p>\n<p> Das Hauptwerk dieses Albums allerdings ist John Coriglianos Symphony No. 2 f\u00fcr Streichorchester, uraufgef\u00fchrt im Jahre 2000 in Boston und ein Jahr sp\u00e4ter ausgezeichnet mit dem Pulitzer-Preis f\u00fcr Musik. Das Werk basiert auf Coriglianos Streichquartett von 1996; drei der f\u00fcnf S\u00e4tze sind allerdings stark \u00fcberarbeitet worden. <\/p>\n<p> Der 1938 in New York geborene John Corigliano, hoch gesch\u00e4tzt in seiner Heimat, erweist sich in seiner 2. Sinfonie als gewiefter Klangorganisator, der \u00fcber eine breite Palette gebietet von gl\u00e4sern fragilen Flageolett-Geweben bis zu kompakten Unisono-Bl\u00f6cken. Durchaus effektvoll, ohrg\u00e4ngig, s\u00fcffig gar, auch mal sch\u00f6n bombastisch wirkt das alles, expressiv aufgeladen mit stimmungsmalerischem sp\u00e4tromantischem Gestus: Bilder, Szenen, Erinnerungen, wirkungssicher umgesetzt in Klang. <\/p>\n<p> Traditionell ist der hohe Wiedererkennungswert der Themen, erprobt die Dramaturgie. Hier und dort lassen Kollegen gr\u00fcssen (Mendelssohn, Tschaikowski, Bart\u00f3k). Viel versprechende Konstruktionsideen und strukturelle Muster werden alsbald aufgeweicht, originelle Einf\u00e4lle verm\u00f6gen den vorherrschenden Eindruck der Konventionalit\u00e4t des Ganzen nicht zu verd\u00e4ngen. <\/p>\n<p> Ungeschm\u00e4lertes Lob verdienen die Ausf\u00fchrenden, die sich der Partituren \u2013 beide Werke sind Ersteinspielungen \u2013 mit K\u00f6nnen und vehementem Einsatz annehmen: das Philharmonische Orchester Helsinki unter der Leitung von John Storg\u00e5rds. <\/span> <span class=\"txt-m-black\">(<em>ws<\/em>)<\/span><\/p>\n<p><\/p>\n<p> <center> <\/p>\n<table style=\"width: 430px;\" summary=\"linie\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" bgcolor=\"#666666\" height=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/212.60.37.143\/grafiken\/dbrown1x1.gif\" border=\"0\" width=\"1\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/center> <\/p>\n<p><span class=\"txt-s-black\">John Corigliano: <a href=\"http:\/\/www.amazon.de\/exec\/obidos\/ASIN\/B0001W8E1O\/codexflores-21\">Sinfonie Nr.2. &#8211; The Mannheim Rocket<\/a>. Helsinki Philharmonic Orchestra. Leitung: John Storg\u00e5rds. (Ondine ODE 1039-2; 56\u2019)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>17.04.2004 &#8212; Wie eine Rakete gestartet wird? Ein Streichholz angerissen, Feuer gelegt an die Zw\u00f6lfton-Z\u00fcndschnur; die Maschine kommt schwerf\u00e4llig in&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-906","post","type-post","status-publish","format-standard","hentry","category-tontraeger-besprechungen","entry"],"_links":{"self":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/comments?post=906"}],"version-history":[{"count":0,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/posts\/906\/revisions"}],"wp:attachment":[{"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/media?parent=906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/categories?post=906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codexflores.ch\/index.php\/wp-json\/wp\/v2\/tags?post=906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}